{"id":19992,"date":"2019-10-23T11:18:11","date_gmt":"2019-10-23T09:18:11","guid":{"rendered":"https:\/\/le-clairon-nouveau.fr\/wordpress\/?page_id=19992"},"modified":"2019-10-23T15:44:47","modified_gmt":"2019-10-23T13:44:47","slug":"unes-edition-58","status":"publish","type":"page","link":"https:\/\/le-clairon-nouveau.fr\/wordpress\/unes\/unes-edition-58\/","title":{"rendered":"\u00c9dition n\u00b0 58 &#8211; Octobre \/ Novembre 2019"},"content":{"rendered":"<div id=\"pl-19992\"  class=\"panel-layout\" ><div id=\"pg-19992-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-19992-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19992-0-0-0\" class=\"so-panel widget widget_sow-slider panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-slider so-widget-sow-slider-default-6d39609536fd-19992\"\n\t\t\t\n\t\t>\t\t\t\t<div class=\"sow-slider-base\" style=\"display: none\" tabindex=\"0\">\n\t\t\t\t\t<ul\n\t\t\t\t\tclass=\"sow-slider-images\"\n\t\t\t\t\tdata-settings=\"{&quot;pagination&quot;:true,&quot;speed&quot;:3000,&quot;timeout&quot;:6000,&quot;paused&quot;:false,&quot;pause_on_hover&quot;:false,&quot;swipe&quot;:true,&quot;nav_always_show_desktop&quot;:&quot;&quot;,&quot;nav_always_show_mobile&quot;:&quot;&quot;,&quot;breakpoint&quot;:&quot;780px&quot;,&quot;unmute&quot;:false,&quot;anchor&quot;:null}\"\n\t\t\t\t\t\t\t\t\t\tdata-anchor-id=\"\"\n\t\t\t\t>\t\t<li class=\"sow-slider-image\" style=\"visibility: visible;\" >\n\t\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t\t<div class=\"sow-slider-image-wrapper\" style=\"max-width: 1200px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sow-slider-image-foreground-wrapper\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"150\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-01.png?fit=1200%2C150&amp;ssl=1\" class=\"sow-slider-foreground-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-01.png?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-01.png?resize=300%2C38&amp;ssl=1 300w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-01.png?resize=768%2C96&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-01.png?resize=1024%2C128&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t\t<div class=\"sow-slider-image-wrapper\" style=\"max-width: 1200px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sow-slider-image-foreground-wrapper\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"150\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-02.png?fit=1200%2C150&amp;ssl=1\" class=\"sow-slider-foreground-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-02.png?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-02.png?resize=300%2C38&amp;ssl=1 300w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-02.png?resize=768%2C96&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-02.png?resize=1024%2C128&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t\t<div class=\"sow-slider-image-wrapper\" style=\"max-width: 1200px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sow-slider-image-foreground-wrapper\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"150\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-03B.png?fit=1200%2C150&amp;ssl=1\" class=\"sow-slider-foreground-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-03B.png?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-03B.png?resize=300%2C38&amp;ssl=1 300w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-03B.png?resize=768%2C96&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Pub-Edition-58-Panneau-03B.png?resize=1024%2C128&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t<\/ul>\t\t\t\t<ol class=\"sow-slider-pagination\">\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"0\" aria-label=\"Display slide 1\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"1\" aria-label=\"Display slide 2\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"2\" aria-label=\"Display slide 3\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-next\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"next\" aria-label=\"Next slide\" data-action=\"next\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-right\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-prev\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"previous\" aria-label=\"Previous slide\" data-action=\"prev\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-left\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><div id=\"pg-19992-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-19992-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-19992-1-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child\" data-index=\"1\" ><div class=\"panel-widget-style panel-widget-style-for-19992-1-0-0\" ><div class=\"textwidget\"><h3 style=\"text-align: center;\"><span style=\"color: #8f4511;\">\u00c9ditorial<\/span><\/h3>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-post-border pt-cv-justify pt-cv-reused\" id=\"pt-cv-view-a2290f1fn4\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19978\"><div class='pt-cv-ifield'><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/combien-de-francaises-et-de-francais-letat-a-t-il-le-droit-de-consommer-au-service-de-leconomie-capitaliste\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd\" target=\"_self\" ><img decoding=\"async\" width=\"300\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/04\/Image-supprimee.png?resize=266%2C266&amp;ssl=1\" class=\"pt-cv-thumbnail img-rounded cvp-substitute no-lazyload \" alt=\"Combien de Fran\u00e7aises et de Fran\u00e7ais l\u2019Etat a-t-il le droit de consommer au service de l\u2019\u00e9conomie capitaliste ?\" title=\"\" data-no-lazy=\"1\" \/><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/combien-de-francaises-et-de-francais-letat-a-t-il-le-droit-de-consommer-au-service-de-leconomie-capitaliste\/\" class=\"_self cvplbd\" target=\"_self\" >Combien de Fran\u00e7aises et de Fran\u00e7ais l\u2019Etat a-t-il le droit de consommer au service de l\u2019\u00e9conomie capitaliste ?<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/hubert\/\" rel=\"author\">Hubert Reys<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2019-10-23T12:30:37+02:00\">23 octobre 2019<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">Le choix de l\u2019Etat Macron est clair : lorsqu\u2019il s\u2019agit d\u2019arbitrer entre les int\u00e9r\u00eats de tel ou tel acteur \u00e9conomique et le bien \u00eatre et la sant\u00e9 de la population, tout sera fait pour compromettre le moins possible les int\u00e9r\u00eats du premier ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/combien-de-francaises-et-de-francais-letat-a-t-il-le-droit-de-consommer-au-service-de-leconomie-capitaliste\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-b351e3fjpy\">#pt-cv-view-a2290f1fn4.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-a2290f1fn4.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-a2290f1fn4 .pt-cv-title a, #pt-cv-view-a2290f1fn4  .panel-title { font-size: 18px !important; line-height: 1.3 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-content , #pt-cv-view-a2290f1fn4  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-a2290f1fn4  .pt-cv-hover-wrapper::before   { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-a2290f1fn4:not(.pt-cv-nohover) .pt-cv-mask *   { color: #fff; }\n#pt-cv-view-a2290f1fn4 .pt-cv-carousel-caption  { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-specialp { background-color: #CC3333 !important }\n#pt-cv-view-a2290f1fn4 .pt-cv-specialp * { color: #fff !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-pficon  { color: #bbb !important; }\n#pt-cv-view-a2290f1fn4  .add_to_cart_button, #pt-cv-view-a2290f1fn4  .add_to_cart_button *   { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-a2290f1fn4  .woocommerce-onsale   { color: #ffffff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-a2290f1fn4  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-a2290f1fn4  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-a2290f1fn4'] .active.pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .active .pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .selected.pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .dropdown-toggle   { color: #fff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-a2290f1fn4'] .pt-cv-filter-title   { color: #fff !important; background-color: #00aeef !important; }\n#pt-cv-gls-a2290f1fn4 li a   { font-weight: 600 !important; }\n#pt-cv-gls-a2290f1fn4 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-gls-header  { background-color: #00aeef !important; }\n#pt-cv-view-a2290f1fn4 .img-rounded, #pt-cv-view-a2290f1fn4 .pt-cv-hover-wrapper { -webkit-border-radius: 3px !important; -moz-border-radius: 3px !important; border-radius: 3px !important; }\n#pt-cv-view-a2290f1fn4 { text-align: justify; }<\/style>\r\n\t\t\t <br><\/p>\n<\/div><\/div><\/div><div id=\"panel-19992-1-0-1\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-last-child\" data-index=\"2\" ><div class=\"panel-widget-style panel-widget-style-for-19992-1-0-1\" ><div class=\"textwidget\"><h3 style=\"text-align: center;\"><span style=\"color: #993300;\">Ils ont contribu\u00e9 \u00e0 cette \u00e9dition<\/span><\/h3>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-reused\" id=\"pt-cv-view-edf64eb5yg\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19990\"><div class='pt-cv-ifield'><div class=\"pt-cv-content\"><p><span style=\"font-size: 14pt;color: #0000ff\"><strong>Articles<\/strong><\/span><br \/>\nCatherine Burger (Aude)<br \/>\nPhilippe Casal (Aude)<br \/>\nBertrand Claverie (Aude)<br \/>\nJean Cordier (H\u00e9rault)<br \/>\nAlbert Cormary (Aude)<br \/>\nJean Fran\u00e7ois Lambert (Aude)<br \/>\nSophie Masini (Strasbourg)<br \/>\nPatricia Renaud (Savoie)<br \/>\nHubert Reys (Aude)<br \/>\nSuzy R (Pi\u00e9mont vosgien)<br \/>\nLouise B. Velpeau (Aude)<br \/>\nJean Pierre Vialle (Aude)<\/p>\n<p><strong><span style=\"color: #0000ff;font-size: 14pt\">R\u00e9daction, Edition, Publication\u00a0:<\/span><br \/>\n<\/strong>Jean Cordier<br \/>\nHubert Reys<\/p>\n<p><span style=\"font-size: 14pt;color: #0000ff\"><strong>Coach\u00a0:<\/strong><\/span><\/p>\n<p>Dundee\u00a0 <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-19010\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?resize=28%2C42&#038;ssl=1\" alt=\"\" width=\"28\" height=\"42\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?resize=201%2C300&amp;ssl=1 201w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?w=685&amp;ssl=1 685w\" sizes=\"auto, (max-width: 28px) 100vw, 28px\" \/><\/p>\n<script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>ontribution \\<strong\\>A\\<\\\/strong\\>dditionnelle de \\<strong\\>S\\<\\\/strong\\>olidarit\u00e9 pour l'\\<strong\\>A\\<\\\/strong\\>utonomie\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips109',tt_store_content,'5687'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<\/a><a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/span><\/a><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<\/a><a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/span><\/a><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/p><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br \/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<br \/><br \/>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<br \/><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br \/>\\<\/a><a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/a><\/span><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/span><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/a><\/sup><\/a><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/a><\/sup><\/a><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/span><\/p><\/script><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-44303c4vyf\">#pt-cv-view-edf64eb5yg.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-edf64eb5yg.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-edf64eb5yg .pt-cv-title a, #pt-cv-view-edf64eb5yg  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-content , #pt-cv-view-edf64eb5yg  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-readmore  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-edf64eb5yg  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-edf64eb5yg  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-edf64eb5yg li a   { font-weight: 600 !important; }\n#pt-cv-gls-edf64eb5yg li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t <br><\/p>\n<\/div><\/div><\/div><\/div><div id=\"pgc-19992-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-19992-1-1-0\" class=\"so-panel widget widget_ink-tabs panel-first-child panel-last-child\" data-index=\"3\" ><div class=\"panel-widget-style panel-widget-style-for-19992-1-1-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-ink-tabs so-widget-ink-tabs-tabs-3f7267cc0eba-19992\"\n\t\t\t\n\t\t>\n<div class=\"iw-so-tabs iw-so-tabs-horizontal iw-so-tabs-default\">\n\n\t<ul class=\"iw-so-tabs-nav\">\n\n\t\t\t\t\t<li class=\"iw-so-tab-title iw-so-tab-active\" id=\"ink-tabs-828010003-1\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-1-content\">\n\t\t\t\t\t<span class=\"sow-icon-elegantline\" data-sow-icon=\"&#xe009;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Actualit\u00e9s G\u00e9n\u00e9rales<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-2\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-2-content\">\n\t\t\t\t\t<span class=\"sow-icon-elegantline\" data-sow-icon=\"&#xe047;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Actualit\u00e9s Locales<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-3\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-3-content\">\n\t\t\t\t\t<span class=\"sow-icon-elegantline\" data-sow-icon=\"&#xe02d;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Br\u00e8ves<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-4\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-4-content\">\n\t\t\t\t\t<span class=\"sow-icon-elegantline\" data-sow-icon=\"&#xe005;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Oncle Jef<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-5\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-5-content\">\n\t\t\t\t\t<span class=\"sow-icon-elegantline\" data-sow-icon=\"&#xe028;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Expression Libre<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\n\t<\/ul>\n\n\t<div class=\"iw-so-tabs-content\">\n\n\t\t\t\t\t<div class=\"iw-so-tabs-panel iw-so-tab-active\" id=\"ink-tabs-828010003-1-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-8a92ffelkv\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19914\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/privatisation-des-aeroports-de-paris-echec-annonce-du-rip-ou-occasion-dune-mobilisation-inedite\/\" class=\"_self cvplbd\" target=\"_self\" >Privatisation des A\u00e9roports de Paris &#8211; \u00c9chec annonc\u00e9 du RIP ou occasion d&rsquo;une mobilisation in\u00e9dite ?<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/privatisation-des-aeroports-de-paris-echec-annonce-du-rip-ou-occasion-dune-mobilisation-inedite\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Privatisation des A\u00e9roports de Paris - \u00c9chec annonc\u00e9 du RIP ou occasion d&#039;une mobilisation in\u00e9dite ?\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/09\/ADP-Il-serait-temps.jpg?resize=533%2C279&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Apr\u00e8s des d\u00e9buts prometteurs qui, malheureusement, n'ont pas dur\u00e9 plus d'une vingtaine de jours, le nombre de soutiens au Referendum d'Initiative Partag\u00e9e, visant \u00e0 \u00e9viter la privatisation du groupe A\u00e9roports de Paris, est aujourd'hui tr\u00e8s nettement inf\u00e9rieur \u00e0 ce qu'il devrait \u00eatre. La moyenne quotidienne des soutiens obtenus d\u00e9cro\u00eet de fa\u00e7on d\u00e9sesp\u00e9rante depuis maintenant trois mois, laissant augurer d'un \u00e9chec. Quelles sont les causes de cette situation, quels sont les moyens pour inverser la tendance et qu'est-ce qui est en jeu ? \r\n ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/privatisation-des-aeroports-de-paris-echec-annonce-du-rip-ou-occasion-dune-mobilisation-inedite\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/jean\/\" rel=\"author\">Jean Cordier<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:29+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19883\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/epr-la-filiere-nucleaire-francaise-a-encore-de-beaux-jours-devant-elle\/\" class=\"_self cvplbd\" target=\"_self\" ><span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span> : la fili\u00e8re nucl\u00e9aire fran\u00e7aise a encore de beaux jours devant elle<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/epr-la-filiere-nucleaire-francaise-a-encore-de-beaux-jours-devant-elle\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"EPR : la fili\u00e8re nucl\u00e9aire fran\u00e7aise a encore de beaux jours devant elle\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/04\/Image-supprimee.png?resize=250%2C250&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Pourquoi se lancer maintenant  dans ce programme de construction de 6 nouveaux EPR alors que la fili\u00e8re nucl\u00e9aire va si mal ? ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/epr-la-filiere-nucleaire-francaise-a-encore-de-beaux-jours-devant-elle\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/curly\/\" rel=\"author\">Curly Mc Toole<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:10+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19973\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/urgences-citoyennes\/\" class=\"_self cvplbd\" target=\"_self\" >Urgences  citoyennes<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/urgences-citoyennes\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Urgences  citoyennes\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/04\/Image-supprimee.png?resize=210%2C210&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Cons\u00e9quences d\u00e9sastreuses d'une tenace confusion entre \u00e9conomie et finance, entre int\u00e9r\u00eat g\u00e9n\u00e9ral et int\u00e9r\u00eats particuliers - Tissu social en lente d\u00e9sagr\u00e9gation - Environnement et biodiversit\u00e9 menac\u00e9s, autant par des (non-) choix politiques \u00e0 grande \u00e9chelle, que par nos pratiques quotidiennes - Fragilisation des libert\u00e9s publiques et durcissement des r\u00e9pressions - Tous <span class='tooltipsall tooltip_post_id_29829 classtoolTips180'>ces<\/span> sympt\u00f4mes d'une civilisation en voie de r\u00e9gression se manifestent quotidiennement, provoquant chez le citoyen un d\u00e9sir d'agir pour enrayer ce qui ressemble, chaque jour un peu plus, \u00e0 une inexorable progression vers le pire. Mais peut-on choisir un domaine et un moyen d'action, dans un contexte ou tout semble rev\u00eatir la m\u00eame importance, le m\u00eame degr\u00e9 d'urgence ?  ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/urgences-citoyennes\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/jean\/\" rel=\"author\">Jean Cordier<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:02+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19894\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/alice-et-le-maire\/\" class=\"_self cvplbd\" target=\"_self\" >Alice et le maire<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/alice-et-le-maire\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Alice et le maire\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/04\/Image-supprimee.png?resize=300%2C300&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">France \u2013 1h43 \u2013 2018 Un film de Nicolas Pariser avec Fabrice Luchini, Ana\u00efs Demoustier, Nora Hamzawi. L&rsquo;insoutenable solitude de l&rsquo;homme politique ! Le maire\u00a0 socialiste de Lyon, Paul Th\u00e9raneau, en panne d&rsquo;id\u00e9es apr\u00e8s un long exercice du pouvoir demande \u00e0 une jeune normalienne, Alice, de l&rsquo;aider \u00e0 penser ! Il constate de fa\u00e7on d\u00e9sabus\u00e9e qu&rsquo;il n&rsquo;a plus d&rsquo;id\u00e9es, peut-il trouver aupr\u00e8s de la jeunesse un second souffle ?. Cela ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/alice-et-le-maire\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/patren\/\" rel=\"author\">Patricia Renaud<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:46+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"20004\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/les-bons-conseils-de-tante-suzy\/\" class=\"_self cvplbd\" target=\"_self\" >Les bons conseils de Tante Suzy<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/les-bons-conseils-de-tante-suzy\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Les bons conseils de Tante Suzy\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_20191023_114930.jpg?resize=459%2C338&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Le Clairon de l\u2019Atax inaugure par la pr\u00e9sente une s\u00e9rie sporadique de conseils pratiques. Il s\u2019agit de \u00ab\u00a0savoir-faire\u00a0\u00bb particuliers qui tombent sous le coup du bon sens\u2026En voici le premier. Comment sortir du restaurant avec une bouteille de bon vin \u00e0 moiti\u00e9 pleine et rentrer en auto sans la renverser Bien s\u00fbr si on a un passager on peut toujours lui demander de tenir la bouteille verticalement avec le goulot ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/les-bons-conseils-de-tante-suzy\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:41+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19876\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/lavenement-dhitler-jacques-prevert\/\" class=\"_self cvplbd\" target=\"_self\" >\u00ab\u00a0L&rsquo;av\u00e8nement d&rsquo;Hitler\u00a0\u00bb &#8211; Jacques Pr\u00e9vert<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/lavenement-dhitler-jacques-prevert\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"&quot;L&#039;av\u00e8nement d&#039;Hitler&quot; - Jacques Pr\u00e9vert\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Avenement-Hitler-Pr%C3%A9vert.jpg?resize=345%2C572&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Toi, moi, vous, nous connaissons tous Pr\u00e9vert ! Nos instituteurs nous demandaient d&rsquo;apprendre un po\u00e8me en primaire, voire en 6\u00e8me ou en 5\u00e8me&#8230; Quelques textes plus ou moins gentils dans l&rsquo;ensemble, puis apr\u00e8s on ne nous parlait plus de Pr\u00e9vert&#8230;\u00a0 Oubli\u00e9 des programmes. En tout cas en ce qui me concerne.\u00a0 D&rsquo;ailleurs est-ce qu&rsquo;il nous ont r\u00e9ellement parl\u00e9 de l&rsquo;auteur, de sa capacit\u00e9 \u00e0 nous balancer de coups de poing ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/lavenement-dhitler-jacques-prevert\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/jpvialle\/\" rel=\"author\">Jean-Pierre Vialle<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:33+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19848\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/ceux-qui-travaillent\/\" class=\"_self cvplbd\" target=\"_self\" >Ceux qui travaillent<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/ceux-qui-travaillent\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Ceux qui travaillent\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/04\/Image-supprimee.png?resize=250%2C250&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Suisse\/Belgique \u2013 1h42 \u2013 2018 Un film d&rsquo;Antoine Russbach avec Olivier Gourmet, Ad\u00e8le Bochatay, Louka Minella. Ce film fait partie d&rsquo;une trilogie sur le mode m\u00e9di\u00e9val : le tiers \u00e9tat ( \u00ab\u00a0Ceux qui travaillent\u00a0\u00bb), la noblesse ( \u00ab\u00a0Ceux qui combattent\u00a0\u00bb) et le clerg\u00e9 (\u00ab\u00a0Ceux qui prient\u00a0\u00bb). Cela met en \u00e9vidence la difficult\u00e9 de trouver sa place aujourd&rsquo;hui. Les personnages r\u00e9pondent \u00e0 des questions fondamentales : qui nous nourrit ?, qui ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/ceux-qui-travaillent\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/patren\/\" rel=\"author\">Patricia Renaud<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:19+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19889\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/martin-eden-un-film-inspire-du-roman-eponyme-de-jack-london\/\" class=\"_self cvplbd\" target=\"_self\" >Martin Eden, un film inspir\u00e9 du roman <span class='tooltipsall tooltip_post_id_6639 classtoolTips46'>\u00e9ponyme<\/span> de Jack London<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/martin-eden-un-film-inspire-du-roman-eponyme-de-jack-london\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Martin Eden, un film inspir\u00e9 du roman \u00e9ponyme de Jack London\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Image-substitution-Clairon.jpg?resize=300%2C225&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Italie\/France \u2013 2h08\u00a0 &#8211; 2019 \u2013 Coupe Volpi du Meilleur Acteur\u00a0 \u00e0 la Mostra de Venise 2019. Un film de Pietro Marcello avec Luca Marinelli, Jessica Cressy, Carlo Cecchi. \u00ab\u00a0La princesse et le matelot\u00a0\u00bb Naples, d\u00e9but du 20\u00e8me si\u00e8cle, Martin Eden est marin, Martin Eden est prol\u00e9taire mais comme il va s&rsquo;interposer pour soutirer un jeune homme des mains d&rsquo;un tortionnaire, il recevra les remerciements et les f\u00e9licitations de la ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/martin-eden-un-film-inspire-du-roman-eponyme-de-jack-london\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/patren\/\" rel=\"author\">Patricia Renaud<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:09+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-c4e4a44zo6\">#pt-cv-view-8a92ffelkv  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-8a92ffelkv.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-8a92ffelkv.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-8a92ffelkv.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-8a92ffelkv .pt-cv-title a, #pt-cv-view-8a92ffelkv  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-8a92ffelkv  .pt-cv-title a:hover, #pt-cv-view-8a92ffelkv  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-8a92ffelkv .pt-cv-content , #pt-cv-view-8a92ffelkv  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-8a92ffelkv  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-8a92ffelkv .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-8a92ffelkv .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-8a92ffelkv .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-8a92ffelkv  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-8a92ffelkv  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-8a92ffelkv li a   { font-weight: 600 !important; }\n#pt-cv-gls-8a92ffelkv li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-2-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-d1137f7ibt\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19813\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/extension-de-port-la-nouvelle-des-derapages-financiers-avant-le-debut-des-travaux\/\" class=\"_self cvplbd\" target=\"_self\" >Extension de Port la Nouvelle :  des d\u00e9rapages financiers avant le d\u00e9but des travaux !<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/extension-de-port-la-nouvelle-des-derapages-financiers-avant-le-debut-des-travaux\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Extension de Port la Nouvelle :  des d\u00e9rapages financiers avant le d\u00e9but des travaux !\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/04\/Image-supprimee.png?resize=250%2C250&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Plus fort que Flamanville avant m\u00eame que d\u00e9marrent les travaux les co\u00fbts d\u00e9rapent ! Ayant examin\u00e9 divers dossiers de grands projets, la Cour des comptes avait estim\u00e9 la d\u00e9rive budg\u00e9taire moyenne \u00e0 30 % de l\u2019estimation initiale. Pour Port la Nouvelle l\u2019estimation livr\u00e9e \u00e0 l\u2019enqu\u00eate publique \u00e9tait : Rappelons que l\u2019\u00e9tape 1 concerne le quai \u00e9olien (ainsi que le dragage du chenal d\u2019acc\u00e8s \u00e0 11 m) et la construction des ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/extension-de-port-la-nouvelle-des-derapages-financiers-avant-le-debut-des-travaux\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/albert\/\" rel=\"author\">Albert Cormary<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:06+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19921\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/effondrements-ecologiques-agir-et-prendre-conscience\/\" class=\"_self cvplbd\" target=\"_self\" >Effondrements \u00e9cologiques :  agir et prendre conscience.<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/effondrements-ecologiques-agir-et-prendre-conscience\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Effondrements \u00e9cologiques :  agir et prendre conscience.\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/04\/Image-supprimee.png?resize=250%2C250&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">L'urgence climatique nous laisse de moins en moins de temps pour agir et sortir de la spirale mortif\u00e8re o\u00f9 nous sommes engag\u00e9s, abus\u00e9s par une certaine id\u00e9e du progr\u00e8s. Le Clairon de l'Atax a choisi de pr\u00e9senter ici et dans ses prochaines \u00e9ditions un s\u00e9rie d'articles qui t\u00e9moignent d'un chemin possible ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/effondrements-ecologiques-agir-et-prendre-conscience\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/bertrand\/\" rel=\"author\">Bertrand Claverie<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:29+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19907\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/ceta-pesticides-un-communique-de-la-confederation-paysanne-de-laude\/\" class=\"_self cvplbd\" target=\"_self\" >CETA, Pesticides : un communiqu\u00e9 de la Conf\u00e9d\u00e9ration paysanne de l&rsquo;Aude<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/ceta-pesticides-un-communique-de-la-confederation-paysanne-de-laude\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"CETA, Pesticides : un communiqu\u00e9 de la Conf\u00e9d\u00e9ration paysanne de l&#039;Aude\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/10\/Conf-Pays-Aude.png?resize=389%2C140&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Limoux, le 8 octobre Communiqu\u00e9 de presse La mobilisation agricole est loin de faire l&rsquo;unanimit\u00e9 La Conf\u00e9d\u00e9ration Paysanne de l&rsquo;Aude n&rsquo;a pas particip\u00e9 \u00e0 la journ\u00e9e de mobilisation organis\u00e9e aujourd&rsquo;hui par la CR (Ndlr : Cordination Rurale) et la Fnsea, autour de th\u00e8mes divers. Parmi ceux-ci, le CETA et les pesticides sont deux sujets dont le traitement par le gouvernement illustre son d\u00e9sint\u00e9r\u00eat pour l&rsquo;agriculture, et son m\u00e9pris pour les ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/ceta-pesticides-un-communique-de-la-confederation-paysanne-de-laude\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/hubert\/\" rel=\"author\">Hubert Reys<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:13+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19865\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/port-la-nouvelle-le-projet-dextension-du-port-rencontre-une-opposition-croissante-aux-arguments-bien-etayes\/\" class=\"_self cvplbd\" target=\"_self\" >Port La Nouvelle : le projet d\u2019extension du port rencontre une opposition croissante aux arguments bien \u00e9tay\u00e9s<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/port-la-nouvelle-le-projet-dextension-du-port-rencontre-une-opposition-croissante-aux-arguments-bien-etayes\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Port La Nouvelle : le projet d\u2019extension du port rencontre une opposition croissante aux arguments bien \u00e9tay\u00e9s\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/04\/Image-supprimee.png?resize=250%2C250&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Le projet d\u2019extension de Port La Nouvelle se trouve actuellement fortement remis en cause. Des critiques s'\u00e9l\u00e8vent de toutes part pour contester ce projet, d'autant plus que beaucoup d'habitants et d'associations qui ont particip\u00e9 \u00e0 la consultation publique r\u00e8glementaire lors de son \u00e9laboration constatent que leurs remarques et propositions n'ont pas \u00e9t\u00e9 prises en compte ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/port-la-nouvelle-le-projet-dextension-du-port-rencontre-une-opposition-croissante-aux-arguments-bien-etayes\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/hubert\/\" rel=\"author\">Hubert Reys<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2019-10-23T12:30:33+02:00\">23 octobre 2019<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-b214bc5ec5\">#pt-cv-view-d1137f7ibt  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-d1137f7ibt.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-d1137f7ibt.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-d1137f7ibt.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-d1137f7ibt .pt-cv-title a, #pt-cv-view-d1137f7ibt  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-d1137f7ibt  .pt-cv-title a:hover, #pt-cv-view-d1137f7ibt  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-d1137f7ibt .pt-cv-content , #pt-cv-view-d1137f7ibt  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-d1137f7ibt  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-d1137f7ibt .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-d1137f7ibt .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-d1137f7ibt .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-d1137f7ibt  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-d1137f7ibt  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-d1137f7ibt li a   { font-weight: 600 !important; }\n#pt-cv-gls-d1137f7ibt li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-3-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-nolf pt-cv-reused\" id=\"pt-cv-view-27f17e1db0\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19910\"><div class='pt-cv-ifield'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/deterioration-du-cadre-de-vie-des-francais-les-accidents-industriels-ont-augmente-de-34-en-2-ans\/\" class=\"_self cvplbd\" target=\"_self\" >D\u00e9t\u00e9rioration du cadre de vie des Fran\u00e7ais : les accidents industriels ont augment\u00e9 de 34% en 2 ans<\/a><\/h2>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/lbvp\/\" rel=\"author\">Louise B Velpeau<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2019-10-23T12:30:58+02:00\">23 octobre 2019<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">Tandis que les accidents industriels on augment\u00e9 de 34% en 2 ans la politique d'aust\u00e9rit\u00e9 suivie par le gouvernement fran\u00e7ais r\u00e9duit lles moyens de contr\u00f4le des installations class\u00e9es. Il ne faut pas s'\u00e9tonner si des sinistres comme celui de Lubrizol se produisent ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/deterioration-du-cadre-de-vie-des-francais-les-accidents-industriels-ont-augmente-de-34-en-2-ans\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"19932\"><div class='pt-cv-ifield'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/incinerateur-tdn-dorano-malvesi-rubresus-et-c-ol-e-r-e-souhaitent-faire-appel\/\" class=\"_self cvplbd\" target=\"_self\" >Incin\u00e9rateur <span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>TDN<\/span> d&rsquo;<span class='tooltipsall tooltip_post_id_5129 classtoolTips77'>Orano<\/span>\/Malv\u00e9si : <span class='tooltipsall tooltip_post_id_7255 classtoolTips44'>Rubresus<\/span> et C.OL.E.R.E. souhaitent faire appel<\/a><\/h2>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2019-10-23T12:30:21+02:00\">23 octobre 2019<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">Le Tribunal Administratif de Montpellier a rejet\u00e9 le 15 octobre 2019 le recours conjoint en annulation de l&rsquo;autorisation d&rsquo;exploitation de l&rsquo;installation des d\u00e9chets radioactifs nitrat\u00e9s TDN d&rsquo;Orano Malv\u00e9si form\u00e9 par les associations <span class='tooltipsall tooltip_post_id_7255 classtoolTips44'>Rubr\u00e9sus<\/span> et <span class='tooltipsall tooltip_post_id_19946 classtoolTips72'>COLERE<\/span>. Selon ces associations la d\u00e9cision du TA se fonde sur un dossier incomplet pr\u00e9sent\u00e9 par le rapporteur public \u00ab\u00a0au prix d&rsquo;inexactitudes flagrantes\u00a0\u00bb. Elles expliquent leurs positions et intentions dans un communiqu\u00e9 de presse conjoint : ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/incinerateur-tdn-dorano-malvesi-rubresus-et-c-ol-e-r-e-souhaitent-faire-appel\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-2e8a14d8cl\">#pt-cv-view-27f17e1db0 .pt-cv-content-item { padding-left: 5px !important; padding-right: 5px !important; }\n#pt-cv-view-27f17e1db0  { margin-left: -5px !important; margin-right: -5px !important; }\n#pt-cv-view-27f17e1db0 .pt-cv-ifield { padding-top: 0px !important; padding-left: 0px !important; padding-bottom: 5px !important; padding-right: 0px !important; }\n#pt-cv-view-27f17e1db0  .pt-cv-ifield   { background-color: rgba(234,212,86,0.2) !important; }\n#pt-cv-view-27f17e1db0.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-27f17e1db0.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-27f17e1db0 .pt-cv-title a, #pt-cv-view-27f17e1db0  .panel-title { font-family: 'Nunito', Arial, serif !important; font-size: 18px !important; color: #cc2e2e !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-27f17e1db0  .pt-cv-title a:hover, #pt-cv-view-27f17e1db0  .panel-title:hover   { color: rgba(204,46,46,0.41) !important; }\n#pt-cv-view-27f17e1db0 .pt-cv-content , #pt-cv-view-27f17e1db0  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-27f17e1db0  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(214,214,214,0.77) !important; }\n#pt-cv-view-27f17e1db0 .pt-cv-meta-fields * { font-size: 12px !important; line-height: 1.3 !important; }\n#pt-cv-view-27f17e1db0 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-27f17e1db0 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-27f17e1db0  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-27f17e1db0  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-27f17e1db0 li a   { font-weight: 600 !important; }\n#pt-cv-gls-27f17e1db0 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Nunito' rel='stylesheet' type='text\/css'> <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-4-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-reused\" id=\"pt-cv-view-3628ccfwmi\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"19838\"><div class='pt-cv-ifield'><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/la-fin-dun-cycle-et-apres\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-left cvplbd\" target=\"_self\" ><img decoding=\"async\" width=\"300\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/06\/La-Chronique-d%E2%80%99oncle-JEF.jpg?resize=264%2C59&amp;ssl=1\" class=\"pt-cv-thumbnail img-none pull-left cvp-substitute no-lazyload \" alt=\"La fin d\u2019un cycle\u2026 Et apr\u00e8s !\" title=\"\" data-no-lazy=\"1\" \/><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/la-fin-dun-cycle-et-apres\/\" class=\"_self cvplbd\" target=\"_self\" >La fin d\u2019un cycle\u2026 Et apr\u00e8s !<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/onclejef\/\" rel=\"author\">Oncle Jef<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2019-10-23T12:30:31+02:00\">23 octobre 2019<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">Le 29 juillet 2019, le \u00ab <span class='tooltipsall tooltip_post_id_7802 classtoolTips5'>jour du d\u00e9passement<\/span> \u00bb, nous avons consomm\u00e9, au niveau mondial, plus que la plan\u00e8te ne peut nous donner. En France, ce jour est le 5 mai\u2026 En 1999, il y a 20 ans, le jour de d\u00e9passement avait \u00e9t\u00e9 fix\u00e9 au 29 septembre ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2019\/10\/23\/la-fin-dun-cycle-et-apres\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-0ea7f4fv02\">#pt-cv-view-3628ccfwmi  .pt-cv-ifield   { background-color: rgba(234,212,86,0.2) !important; }\n#pt-cv-view-3628ccfwmi.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-3628ccfwmi.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-3628ccfwmi .pt-cv-title a, #pt-cv-view-3628ccfwmi  .panel-title { color: #cc2e2e !important; font-weight: 600 !important; }\n#pt-cv-view-3628ccfwmi  .pt-cv-title a:hover, #pt-cv-view-3628ccfwmi  .panel-title:hover   { color: rgba(204,46,46,0.41) !important; }\n#pt-cv-view-3628ccfwmi .pt-cv-content , #pt-cv-view-3628ccfwmi  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-3628ccfwmi .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-3628ccfwmi .pt-cv-readmore:hover  { color: #ff413a !important; font-weight: 600 !important; }\n#pt-cv-view-3628ccfwmi  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-3628ccfwmi  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-3628ccfwmi li a   { font-weight: 600 !important; }\n#pt-cv-gls-3628ccfwmi li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-5-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-post-border pt-cv-reused\" id=\"pt-cv-view-8090fb6z9g\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page cv-npf\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"0\"><div class='pt-cv-ifield'><div class=\"pt-cv-no-post\">Aucune publication trouv\u00e9e.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-3004579bz2\">#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-color: #ede0ce; border-left-color: #ede0ce }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; border-right-color: #ede0ce; border-bottom-color: #ede0ce; }\n#pt-cv-view-8090fb6z9g .pt-cv-title a, #pt-cv-view-8090fb6z9g  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-8090fb6z9g  .pt-cv-hover-wrapper::before   { background-color: rgba(0,0,0,.3) !important; }\n#pt-cv-view-8090fb6z9g  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-8090fb6z9g:not(.pt-cv-nohover) .pt-cv-mask *   { color: #fff; }\n#pt-cv-view-8090fb6z9g .pt-cv-carousel-caption  { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-meta-fields * { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-specialp { background-color: #CC3333 !important }\n#pt-cv-view-8090fb6z9g .pt-cv-specialp * { color: #fff !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-pficon  { color: #bbb !important; }\n#pt-cv-view-8090fb6z9g  .add_to_cart_button, #pt-cv-view-8090fb6z9g  .add_to_cart_button *   { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-8090fb6z9g  .woocommerce-onsale   { color: #ffffff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-8090fb6z9g  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-8090fb6z9g  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-8090fb6z9g'] .active.pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .active .pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .selected.pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .dropdown-toggle   { color: #fff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-8090fb6z9g'] .pt-cv-filter-title   { color: #fff !important; background-color: #00aeef !important; }\n#pt-cv-gls-8090fb6z9g li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-gls-header  { color: #fff !important; background-color: #00aeef !important; }<\/style>\r\n\t\t\t <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><script type=\"text\/javascript\"> var tt_store_content = \"Le \\<strong\\><span class='tooltipsall tooltip_post_id_3742 classtoolTips27'>glyphosate<\/span>\\<\\\/strong\\> est un \\<strong\\>herbicide non s\u00e9lectif\\<\\\/strong\\> absorb\u00e9 par les feuilles et ayant une action g\u00e9n\u00e9ralis\u00e9e\\. Produit \u00e0 partir de 1974 sous \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Brevet'\\>brevet\\<\\\/a\\> par la firme MONSANTO sous la marque ROUNDUP, ce brevet est tomb\u00e9 dans le domaine public en 2000\\. Il est produit depuis cette date par d\u2019autres firmes de l\u2019agrochimie\\.\"; toolTips('.classtoolTips27',tt_store_content,'3742'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>T\\<\\\/strong\\>raitement\\<strong\\> D\\<\\\/strong\\>es\\<strong\\> N\\<\\\/strong\\>itrates\\<strong\\> \\(TDN\\)<br\/>TH\\<\\\/strong\\>ermal\\<strong\\> O\\<\\\/strong\\>rganic\\<strong\\> R\\<\\\/strong\\>eduction\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>THOR<\/span>\\)\\<\\\/strong\\>\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Proc\u00e9d\u00e9 envisag\u00e9 par la soci\u00e9t\u00e9 AREVA pour retraiter les d\u00e9chets nitrat\u00e9s et radio\\-actifs issus de son activit\u00e9 d'enrichissement de l'uranium, phase I de la pr\u00e9paration du combustible des centrales nucl\u00e9aires\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Cette activit\u00e9 est mise en \u0153uvre dans l'usine de Malv\u00e9si \u00e0 quelques kilom\u00e8tres de Narbonne\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Ce proc\u00e9d\u00e9, potentiellement tr\u00e8s toxique pour la sant\u00e9 et l'environnement, est au centre d'une vive opposition de la part des riverains et \u00e0 laquelle le Clairon s'associe \\(\\<a href\\='https\\:\\\/\\\/le\\-clairon\\-nouveau\\.fr\\\/wordpress\\\/dossiers\\\/dossier\\-malvesi\\-areva\\\/' target\\='_blank' rel\\='noopener'\\>voir notre dossier\\<\\\/a\\> sur le sujet\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips37',tt_store_content,'3610'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>ontribution \\<strong\\>A\\<\\\/strong\\>dditionnelle de \\<strong\\>S\\<\\\/strong\\>olidarit\u00e9 pour l'\\<strong\\>A\\<\\\/strong\\>utonomie\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips109',tt_store_content,'5687'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Le <span class='tooltipsall tooltip_post_id_3743 classtoolTips128'>CIRC<\/span> est le&nbsp; \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Centre_international_de_recherche_sur_le_cancer' target\\='_blank' rel\\='noopener'\\>Centre international de Recherche sur le Cancer\\<\\\/a\\>, cr\u00e9\u00e9 en 1965 par l\u2019\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Organisation_mondiale_de_la_sant%C3%A9' target\\='_blank' rel\\='noopener'\\>Organisation Mondiale de la Sant\u00e9\\<\\\/a\\> \\(OMS\\) des \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Organisation_des_Nations_unies' target\\='_blank' rel\\='noopener'\\>Nations Unies\\<\\\/a\\>\\.\"; toolTips('.classtoolTips128',tt_store_content,'3743'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br\/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><br\/><br\/>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>evenu de \\<strong\\>S\\<\\\/strong\\>olidarit\u00e9 \\<strong\\>A\\<\\\/strong\\>ctive\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Le revenu de solidarit\u00e9 active est une prestation sociale fran\u00e7aise, g\u00e9r\u00e9e par les conseils d\u00e9partementaux, vers\u00e9e par les <span class='tooltipsall tooltip_post_id_5652 classtoolTips155'>CAF<\/span> et les MSA et destin\u00e9e \u00e0 garantir \u00e0 ses b\u00e9n\u00e9ficiaires, qu'ils aient ou non la capacit\u00e9 de travailler, un revenu minimum, avec en contrepartie une obligation de chercher un emploi ou de d\u00e9finir et suivre un projet professionnel visant \u00e0 am\u00e9liorer sa situation financi\u00e8re\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Cette prestation sociale a \u00e9t\u00e9 mise en place en 2009, en remplacement du RMI \\(revenu minimum d'insertion\\), mis en place en 1988\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>En 2016, 2,5 millions de personnes \u00e9taient b\u00e9n\u00e9ficiaires du <span class='tooltipsall tooltip_post_id_5651 classtoolTips154'>RSA<\/span>\\.\\<\\\/p\\><br\/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Revenu_de_solidarit%C3%A9_active' target\\='_blank' rel\\='noopener'\\>Acc\u00e9der ici \u00e0 la fiche Wikipedia traitant du RSA\\<\\\/a\\><br\/>\\<a href\\='https\\:\\\/\\\/www\\.insee\\.fr\\\/fr\\\/metadonnees\\\/definition\\\/c1718' target\\='_blank' rel\\='noopener'\\>Acc\u00e9der ici \u00e0 la d\u00e9finition du RSA fournie par l'<span class='tooltipsall tooltip_post_id_6978 classtoolTips82'>INSEE<\/span>\\<\\\/a\\>\\<\\\/em\\>\"; toolTips('.classtoolTips154',tt_store_content,'5651'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9pertoire \\<strong\\>N\\<\\\/strong\\>ational des \\<strong\\>A\\<\\\/strong\\>ssociations\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips159',tt_store_content,'24374'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(COR\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<em\\>\\<strong\\>Banque Centrale Europ\u00e9enne\\<\\\/strong\\>\\<\\\/em\\>\\<\\\/p\\><br\/>Aller sur \\<a href\\='http\\:\\\/\\\/www\\.ecb\\.europa\\.eu\\\/home\\\/languagepolicy\\\/html\\\/index\\.fr\\.html' target\\='_blank' rel\\='noopener'\\>le site de la <span class='tooltipsall tooltip_post_id_4170 classtoolTips166'>BCE<\/span>\\<\\\/a\\><br\/>Voir la \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Banque_centrale_europ%C3%A9enne' target\\='_blank' rel\\='noopener'\\>fiche Wikipedia de la BCE\\<\\\/a\\>\"; toolTips('.classtoolTips166',tt_store_content,'4170'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br\/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;<br\/><br\/>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\u00c9cole des<br\/>\\<strong\\>H\\<\\\/strong\\>autes \\<strong\\>\u00c9\\<\\\/strong\\>tudes \\<strong\\>C\\<\\\/strong\\>ommerciales\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips171',tt_store_content,'5214'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>\\<span class\\='ILfuVd'\\>La politique agricole commune \\(\\<b\\><span class='tooltipsall tooltip_post_id_11364 classtoolTips174'>PAC<\/span>\\<\\\/b\\>\\) est une politique mise en place \u00e0 l'\u00e9chelle de l'Union europ\u00e9enne\\. \u00c0 l'origine, elle est fond\u00e9e principalement sur des mesures de contr\u00f4le des prix et de subventionnement, visant \u00e0 moderniser et d\u00e9velopper l'agriculture\\.\\<\\\/span\\> \\(source Wikipedia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips174',tt_store_content,'11364'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br\/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<br\/><br\/>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<br\/><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br\/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia EPR\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_21204 classtoolTips199'>COV<\/span> \\= Compos\u00e9 Organique Volatile\\<\\\/p\\>\"; toolTips('.classtoolTips199',tt_store_content,'21204'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>d\u00e9chets \u00e0 Vie Courte \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips212',tt_store_content,'19201'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br\/>ou<br\/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"<div class='tooltips_youtube_class' ><iframe width='100%' height='100%' src='http:\/\/www.youtube.com\/embed\/terawatt?rel=0&autoplay=1' frameborder='0' allowfullscreen><\/iframe><\/div>\\<p\\>\\<strong\\>TERAWATT \\(<span class='tooltipsall tooltip_post_id_30105 classtoolTips219'>TW<\/span>\\) \\= 1000 000 000 000 <span class='tooltipsall tooltip_post_id_30101 classtoolTips216'>KW<\/span>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips219',tt_store_content,'30105'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\><span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nm<\/span> \\= n\\<\\\/strong\\>ano\\<strong\\>m\\<\\\/strong\\>\u00e8tre \\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<em\\>le <span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nanom\u00e8tre<\/span>, de symbole nm, est une unit\u00e9 de longueur du Syst\u00e8me international\\. C'est un sous\\-multiple du m\u00e8tre, il vaut un milliardi\u00e8me de m\u00e8tre, soit un millioni\u00e8me de millim\u00e8tre\\.\\<\\\/em\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<em\\> 1 nm \\= 10\u207b\u00b3 \u00b5m \\= 10\\<sup\\>\u20136\\<\\\/sup\\> mm \\= 10\\<sup\\>\u20139\\<\\\/sup\\> m\\.\\<\\\/em\\>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips222',tt_store_content,'21736'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script>","protected":false},"excerpt":{"rendered":"<p>\u00c9ditorial Ils ont contribu\u00e9 \u00e0 cette \u00e9dition<script type=\"text\/javascript\"> var tt_store_content = \"Le \\<strong\\><span class='tooltipsall tooltip_post_id_3742 classtoolTips27'>glyphosate<\/span>\\<\\\/strong\\> est un \\<strong\\>herbicide non s\u00e9lectif\\<\\\/strong\\> absorb\u00e9 par les feuilles et ayant une action g\u00e9n\u00e9ralis\u00e9e\\. Produit \u00e0 partir de 1974 sous \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Brevet'\\>brevet\\<\\\/a\\> par la firme MONSANTO sous la marque ROUNDUP, ce brevet est tomb\u00e9 dans le domaine public en 2000\\. Il est produit depuis cette date par d\u2019autres firmes de l\u2019agrochimie\\.\"; toolTips('.classtoolTips27',tt_store_content,'3742'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>T\\<\\\/strong\\>raitement\\<strong\\> D\\<\\\/strong\\>es\\<strong\\> N\\<\\\/strong\\>itrates\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>TDN<\/span>\\)<br \/>TH\\<\\\/strong\\>ermal\\<strong\\> O\\<\\\/strong\\>rganic\\<strong\\> R\\<\\\/strong\\>eduction\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>THOR<\/span>\\)\\<\\\/strong\\>\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Proc\u00e9d\u00e9 envisag\u00e9 par la soci\u00e9t\u00e9 AREVA pour retraiter les d\u00e9chets nitrat\u00e9s et radio\\-actifs issus de son activit\u00e9 d'enrichissement de l'uranium, phase I de la pr\u00e9paration du combustible des centrales nucl\u00e9aires\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Cette activit\u00e9 est mise en \u0153uvre dans l'usine de Malv\u00e9si \u00e0 quelques kilom\u00e8tres de Narbonne\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Ce proc\u00e9d\u00e9, potentiellement tr\u00e8s toxique pour la sant\u00e9 et l'environnement, est au centre d'une vive opposition de la part des riverains et \u00e0 laquelle le Clairon s'associe \\(\\<a href\\='https\\:\\\/\\\/le\\-clairon\\-nouveau\\.fr\\\/wordpress\\\/dossiers\\\/dossier\\-malvesi\\-areva\\\/' target\\='_blank' rel\\='noopener'\\>voir notre dossier\\<\\\/a\\> sur le sujet\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips37',tt_store_content,'3610'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>ontribution \\<strong\\>A\\<\\\/strong\\>dditionnelle de \\<strong\\>S\\<\\\/strong\\>olidarit\u00e9 pour l'\\<strong\\>A\\<\\\/strong\\>utonomie\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips109',tt_store_content,'5687'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Le <span class='tooltipsall tooltip_post_id_3743 classtoolTips128'>CIRC<\/span> est le&nbsp; \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Centre_international_de_recherche_sur_le_cancer' target\\='_blank' rel\\='noopener'\\>Centre international de Recherche sur le Cancer\\<\\\/a\\>, cr\u00e9\u00e9 en 1965 par l\u2019\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Organisation_mondiale_de_la_sant%C3%A9' target\\='_blank' rel\\='noopener'\\>Organisation Mondiale de la Sant\u00e9\\<\\\/a\\> \\(OMS\\) des \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Organisation_des_Nations_unies' target\\='_blank' rel\\='noopener'\\>Nations Unies\\<\\\/a\\>\\.\"; toolTips('.classtoolTips128',tt_store_content,'3743'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br \/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><\/p>\n<p>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>evenu de \\<strong\\>S\\<\\\/strong\\>olidarit\u00e9 \\<strong\\>A\\<\\\/strong\\>ctive\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le revenu de solidarit\u00e9 active est une prestation sociale fran\u00e7aise, g\u00e9r\u00e9e par les conseils d\u00e9partementaux, vers\u00e9e par les <span class='tooltipsall tooltip_post_id_5652 classtoolTips155'>CAF<\/span> et les MSA et destin\u00e9e \u00e0 garantir \u00e0 ses b\u00e9n\u00e9ficiaires, qu'ils aient ou non la capacit\u00e9 de travailler, un revenu minimum, avec en contrepartie une obligation de chercher un emploi ou de d\u00e9finir et suivre un projet professionnel visant \u00e0 am\u00e9liorer sa situation financi\u00e8re\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Cette prestation sociale a \u00e9t\u00e9 mise en place en 2009, en remplacement du RMI \\(revenu minimum d'insertion\\), mis en place en 1988\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>En 2016, 2,5 millions de personnes \u00e9taient b\u00e9n\u00e9ficiaires du <span class='tooltipsall tooltip_post_id_5651 classtoolTips154'>RSA<\/span>\\.\\<\\\/p\\><br \/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Revenu_de_solidarit%C3%A9_active' target\\='_blank' rel\\='noopener'\\>Acc\u00e9der ici \u00e0 la fiche Wikipedia traitant du RSA\\<\\\/a\\><br \/>\\<a href\\='https\\:\\\/\\\/www\\.insee\\.fr\\\/fr\\\/metadonnees\\\/definition\\\/c1718' target\\='_blank' rel\\='noopener'\\>Acc\u00e9der ici \u00e0 la d\u00e9finition du RSA fournie par l'<span class='tooltipsall tooltip_post_id_6978 classtoolTips82'>INSEE<\/span>\\<\\\/a\\>\\<\\\/em\\>\"; toolTips('.classtoolTips154',tt_store_content,'5651'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9pertoire \\<strong\\>N\\<\\\/strong\\>ational des \\<strong\\>A\\<\\\/strong\\>ssociations\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips159',tt_store_content,'24374'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<em\\>\\<strong\\>Banque Centrale Europ\u00e9enne\\<\\\/strong\\>\\<\\\/em\\>\\<\\\/p\\><br \/>Aller sur \\<a href\\='http\\:\\\/\\\/www\\.ecb\\.europa\\.eu\\\/home\\\/languagepolicy\\\/html\\\/index\\.fr\\.html' target\\='_blank' rel\\='noopener'\\>le site de la <span class='tooltipsall tooltip_post_id_4170 classtoolTips166'>BCE<\/span>\\<\\\/a\\><br \/>Voir la \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Banque_centrale_europ%C3%A9enne' target\\='_blank' rel\\='noopener'\\>fiche Wikipedia de la BCE\\<\\\/a\\>\"; toolTips('.classtoolTips166',tt_store_content,'4170'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br \/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\u00c9cole des<br \/>\\<strong\\>H\\<\\\/strong\\>autes \\<strong\\>\u00c9\\<\\\/strong\\>tudes \\<strong\\>C\\<\\\/strong\\>ommerciales\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips171',tt_store_content,'5214'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>\\<span class\\='ILfuVd'\\>La politique agricole commune \\(\\<b\\><span class='tooltipsall tooltip_post_id_11364 classtoolTips174'>PAC<\/span>\\<\\\/b\\>\\) est une politique mise en place \u00e0 l'\u00e9chelle de l'Union europ\u00e9enne\\. \u00c0 l'origine, elle est fond\u00e9e principalement sur des mesures de contr\u00f4le des prix et de subventionnement, visant \u00e0 moderniser et d\u00e9velopper l'agriculture\\.\\<\\\/span\\> \\(source Wikipedia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips174',tt_store_content,'11364'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br \/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<\/p>\n<p>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br \/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_21204 classtoolTips199'>COV<\/span> \\= Compos\u00e9 Organique Volatile\\<\\\/p\\>\"; toolTips('.classtoolTips199',tt_store_content,'21204'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>d\u00e9chets \u00e0 Vie Courte \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips212',tt_store_content,'19201'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br \/>ou<br \/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"<\/p>\n<div class='tooltips_youtube_class' ><iframe width='100%' height='100%' src='http:\/\/www.youtube.com\/embed\/terawatt?rel=0&autoplay=1' frameborder='0' allowfullscreen><\/iframe><\/div>\n<p>\\<p\\>\\<strong\\>TERAWATT \\(<span class='tooltipsall tooltip_post_id_30105 classtoolTips219'>TW<\/span>\\) \\= 1000 000 000 000 <span class='tooltipsall tooltip_post_id_30101 classtoolTips216'>KW<\/span>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips219',tt_store_content,'30105'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\><span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nm<\/span> \\= n\\<\\\/strong\\>ano\\<strong\\>m\\<\\\/strong\\>\u00e8tre \\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<em\\>le <span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nanom\u00e8tre<\/span>, de symbole nm, est une unit\u00e9 de longueur du Syst\u00e8me international\\. C'est un sous\\-multiple du m\u00e8tre, il vaut un milliardi\u00e8me de m\u00e8tre, soit un millioni\u00e8me de millim\u00e8tre\\.\\<\\\/em\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<em\\> 1 nm \\= 10\u207b\u00b3 \u00b5m \\= 10\\<sup\\>\u20136\\<\\\/sup\\> mm \\= 10\\<sup\\>\u20139\\<\\\/sup\\> m\\.\\<\\\/em\\>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips222',tt_store_content,'21736'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1235,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"coauthors":[8],"class_list":["post-19992","page","type-page","status-publish","hentry","no-thumb"],"acf":[],"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/P9B5TM-5cs","_links":{"self":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/19992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=19992"}],"version-history":[{"count":0,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/19992\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/1235"}],"wp:attachment":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=19992"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/coauthors?post=19992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}