{"id":25184,"date":"2021-09-20T19:02:51","date_gmt":"2021-09-20T17:02:51","guid":{"rendered":"https:\/\/le-clairon-nouveau.fr\/wordpress\/?page_id=25184"},"modified":"2021-11-22T14:03:19","modified_gmt":"2021-11-22T13:03:19","slug":"unes-edition-79","status":"publish","type":"page","link":"https:\/\/le-clairon-nouveau.fr\/wordpress\/unes\/unes-edition-79\/","title":{"rendered":"\u00c9dition n\u00b0 79 &#8211; Septembre \/ Octobre 2021"},"content":{"rendered":"<div id=\"pl-25184\"  class=\"panel-layout\" ><div id=\"pg-25184-0\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-25184-0\" ><div id=\"pgc-25184-0-0\"  class=\"panel-grid-cell\" ><div class=\"panel-cell-style panel-cell-style-for-25184-0-0\" ><div id=\"panel-25184-0-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"panel-widget-style panel-widget-style-for-25184-0-0-0\" ><div id=\"pl-w614c6b5d53384\"  class=\"panel-layout\" ><div id=\"pg-w614c6b5d53384-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w614c6b5d53384-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w614c6b5d53384-0-0-0\" class=\"so-panel widget widget_sow-hero panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-hero so-widget-sow-hero-default-635e1db5ac93 so-widget-fittext-wrapper\"\n\t\t\t data-fit-text-compressor=\"2.5\"\n\t\t>\t\t\t\t<div class=\"sow-slider-base\" style=\"display: none\" tabindex=\"0\">\n\t\t\t\t\t<ul\n\t\t\t\t\tclass=\"sow-slider-images\"\n\t\t\t\t\tdata-settings=\"{&quot;pagination&quot;:true,&quot;speed&quot;:1200,&quot;timeout&quot;:10000,&quot;paused&quot;:false,&quot;pause_on_hover&quot;:true,&quot;swipe&quot;:true,&quot;nav_always_show_desktop&quot;:&quot;&quot;,&quot;nav_always_show_mobile&quot;:&quot;&quot;,&quot;breakpoint&quot;:&quot;780px&quot;,&quot;unmute&quot;:false,&quot;anchor&quot;:null}\"\n\t\t\t\t\tstyle=\"min-height: 150px\"\t\t\t\t\tdata-anchor-id=\"\"\n\t\t\t\t>\t\t<li class=\"sow-slider-image\" style=\"visibility: visible;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">\u00c9lections pr\u00e9sidentielles<\/h2>\n<h2 style=\"text-align: center\">Concentrons-nous sur les programmes avant de nous int\u00e9resser aux candidats<\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">Si l'aust\u00e9rit\u00e9 permet de doper la production,<br \/>\nla d\u00e9croissance permet de pr\u00e9server la vie<\/h2>\n<h2 style=\"text-align: center\">Que voulons-nous ?<\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">La d\u00e9mocratie passe par le d\u00e9bat,<br \/>\nles \u00e9bats et l'invective an\u00e9antissent toute expression d\u00e9mocratique<\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">Huit mois pour choisir un.e pr\u00e9sident.e<\/h2>\n<h2 style=\"text-align: center\">Huit mois de vigilance redoubl\u00e9e vis-\u00e0-vis des m\u00e9dia<\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">Le don de sang reste une priorit\u00e9 quotidienne pour nos services de sant\u00e9<\/h2>\n<h5 style=\"text-align: center\"><em>Pour conna\u00eetre les collectes les plus proches, rendez-vous \u00e0 la page<br \/>\n<a href=\"https:\/\/dondesang.efs.sante.fr\/trouver-une-collecte\" target=\"_blank\" rel=\"noopener\">https:\/\/dondesang.<span class='tooltipsall tooltip_post_id_21261 classtoolTips150'>efs<\/span>.sante.fr\/trouver-une-collecte<\/a><\/em><\/h5>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t<\/ul>\t\t\t\t<ol class=\"sow-slider-pagination\">\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"0\" aria-label=\"Display slide 1\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"1\" aria-label=\"Display slide 2\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"2\" aria-label=\"Display slide 3\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"3\" aria-label=\"Display slide 4\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"4\" aria-label=\"Display slide 5\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-next\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"next\" aria-label=\"Next slide\" data-action=\"next\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-right\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-prev\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"previous\" aria-label=\"Previous slide\" data-action=\"prev\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-left\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w614c6b5d53384-1\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-w614c6b5d53384-1\" ><div id=\"pgc-w614c6b5d53384-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w614c6b5d53384-1-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"panel-widget-style panel-widget-style-for-w614c6b5d53384-1-0-0\" ><div class=\"textwidget\"><p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><em>Publicit\u00e9 Citoyenne<\/em><\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-25184-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-25184-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-25184-1-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"textwidget\"><p style=\"text-align: center;\"><span id=\"textillate-dhysni\"><span style=\"visibility: hidden;\"><span class=\"tlt-texts\" style=\"display:none;\"><br \/>\n<span data-in-delay=\"50\" data-out-delay=\"50\" data-in-effect=\"flipInY\" data-in-sync=\"true\" data-out-effect=\"flipOutY\" data-out-sync=\"true\"><span style=\"color: #000000;\">A titre temporaire, seuls les articles \u00e0 compter de d\u00e9cembre 2019 (\u00e9dition n\u00b0 60) sont disponibles<\/span><\/span> <br \/>\n<span data-in-delay=\"50\" data-out-delay=\"50\" data-in-effect=\"flipInY\" data-in-sync=\"true\" data-out-effect=\"flipOutY\" data-out-sync=\"true\"><span style=\"color: #520000;\">Nous vous tiendrons r\u00e9guli\u00e8rement inform\u00e9.e.s de la republication des articles des \u00e9ditions pr\u00e9c\u00e9dentes<\/span> <\/span> <br \/>\n<\/span>&nbsp;<\/span><\/span><\/p>\n<\/div><\/div><\/div><\/div><div id=\"pg-25184-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-25184-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-25184-2-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child\" data-index=\"2\" ><div class=\"panel-widget-style panel-widget-style-for-25184-2-0-0\" ><div class=\"textwidget\"><h3 style=\"text-align: center;\"><span style=\"color: #8f4511;\">\u00c9ditorial<\/span><\/h3>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-post-border pt-cv-justify pt-cv-reused\" id=\"pt-cv-view-a2290f1fn4\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25249\"><div class='pt-cv-ifield'><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/encore-8-mois\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd\" target=\"_self\" ><img decoding=\"async\" width=\"300\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/Debat-Image-par-WikiImages-de-Pixabay.jpg?resize=597%2C368&amp;ssl=1\" class=\"pt-cv-thumbnail img-rounded cvp-substitute no-lazyload \" alt=\"Encore 8 mois !\" title=\"\" data-no-lazy=\"1\" \/><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/encore-8-mois\/\" class=\"_self cvplbd\" target=\"_self\" >Encore 8 mois !<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/hubert\/\" rel=\"author\">Hubert Reys<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2021-09-23T12:30:56+02:00\">23 septembre 2021<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">Comment se sortir de ce processus si peu d\u00e9mocratique que sont devenues les \u00e9lections pr\u00e9sidentielles ? ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/encore-8-mois\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-ce4c086p63\">#pt-cv-view-a2290f1fn4.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-a2290f1fn4.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-a2290f1fn4 .pt-cv-title a, #pt-cv-view-a2290f1fn4  .panel-title { font-size: 18px !important; line-height: 1.3 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-content , #pt-cv-view-a2290f1fn4  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-a2290f1fn4  .pt-cv-hover-wrapper::before   { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-a2290f1fn4:not(.pt-cv-nohover) .pt-cv-mask *   { color: #fff; }\n#pt-cv-view-a2290f1fn4 .pt-cv-carousel-caption  { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-specialp { background-color: #CC3333 !important }\n#pt-cv-view-a2290f1fn4 .pt-cv-specialp * { color: #fff !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-pficon  { color: #bbb !important; }\n#pt-cv-view-a2290f1fn4  .add_to_cart_button, #pt-cv-view-a2290f1fn4  .add_to_cart_button *   { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-a2290f1fn4  .woocommerce-onsale   { color: #ffffff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-a2290f1fn4  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-a2290f1fn4  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-a2290f1fn4'] .active.pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .active .pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .selected.pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .dropdown-toggle   { color: #fff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-a2290f1fn4'] .pt-cv-filter-title   { color: #fff !important; background-color: #00aeef !important; }\n#pt-cv-gls-a2290f1fn4 li a   { font-weight: 600 !important; }\n#pt-cv-gls-a2290f1fn4 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-gls-header  { background-color: #00aeef !important; }\n#pt-cv-view-a2290f1fn4 .img-rounded, #pt-cv-view-a2290f1fn4 .pt-cv-hover-wrapper { -webkit-border-radius: 3px !important; -moz-border-radius: 3px !important; border-radius: 3px !important; }\n#pt-cv-view-a2290f1fn4 { text-align: justify; }<\/style>\r\n\t\t\t <br><\/p>\n<\/div><\/div><\/div><div id=\"panel-25184-2-0-1\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-last-child\" data-index=\"3\" ><div class=\"panel-widget-style panel-widget-style-for-25184-2-0-1\" ><div class=\"textwidget\"><h3 style=\"text-align: center;\"><span style=\"color: #993300;\">Ils ont contribu\u00e9 \u00e0 cette \u00e9dition<\/span><\/h3>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-reused\" id=\"pt-cv-view-edf64eb5yg\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25240\"><div class='pt-cv-ifield'><div class=\"pt-cv-content\"><p><span style=\"font-size: 14pt;color: #3366ff\"><strong>\u00c9dition 79, septembre \/ octobre 2021<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #3366ff;font-size: 14pt\">Articles<\/span><br \/>\n<\/strong><br \/>\nConf\u00e9d\u00e9ration Paysanne 11 (Aude)<br \/>\nJean Cordier (H\u00e9rault)<br \/>\nPatrick Chevalier (Alsace \/ Aude)<br \/>\nLaurent Fabas (Aude)<br \/>\nSafoura Kelishadi (Alsace)<br \/>\nSophie Masini (Alsace)<br \/>\nPatricia Renaud (Savoie)<br \/>\nHubert Reys (Aude)<br \/>\nCurly Mac Toole (Paris)<br \/>\nLouise B. Velpeau (Aude)<br \/>\nColin Reys (Alsace)<br \/>\nDaniel Vexenat (Aude)<br \/>\nLena Waag (Alsace)<\/p>\n<p><span style=\"color: #3366ff;font-size: 14pt\"><strong>R\u00e9daction,\u00c9dition, Publication :<\/strong><\/span><\/p>\n<p>Jean Cordier<br \/>\nHubert Reys<\/p>\n<p><span style=\"font-size: 14pt;color: #3366ff\"><strong>Coach\u00a0:<\/strong><\/span><\/p>\n<p>Dundee\u00a0 <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-19010\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?resize=40%2C60&#038;ssl=1\" alt=\"\" width=\"40\" height=\"60\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?resize=201%2C300&amp;ssl=1 201w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?w=685&amp;ssl=1 685w\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" \/>\u00a0 L\u2019avenir appartient \u00e0 celui dont le chien se l\u00e8ve t\u00f4t<\/p>\n<script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/p><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/span><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/a><\/sup><\/a><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/a><\/sup><\/a><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-d428fc5utc\">#pt-cv-view-edf64eb5yg.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-edf64eb5yg.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-edf64eb5yg .pt-cv-title a, #pt-cv-view-edf64eb5yg  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-content , #pt-cv-view-edf64eb5yg  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-readmore  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-edf64eb5yg  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-edf64eb5yg  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-edf64eb5yg li a   { font-weight: 600 !important; }\n#pt-cv-gls-edf64eb5yg li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t <br><\/p>\n<\/div><\/div><\/div><\/div><div id=\"pgc-25184-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-25184-2-1-0\" class=\"so-panel widget widget_ink-tabs panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"panel-widget-style panel-widget-style-for-25184-2-1-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-ink-tabs so-widget-ink-tabs-tabs-668eb67c20e6-25184\"\n\t\t\t\n\t\t>\n<div class=\"iw-so-tabs iw-so-tabs-horizontal iw-so-tabs-fullwidth\">\n\n\t<ul class=\"iw-so-tabs-nav\">\n\n\t\t\t\t\t<li class=\"iw-so-tab-title iw-so-tab-active\" id=\"ink-tabs-828010003-1\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-1-content\">\n\t\t\t\t\t<span class=\"sow-icon-elegantline\" data-sow-icon=\"&#xe009;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Actualit\u00e9s<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-2\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-2-content\">\n\t\t\t\t\t<span class=\"sow-icon-elegantline\" data-sow-icon=\"&#xe031;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Culture et Art de Vivre<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-3\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-3-content\">\n\t\t\t\t\t<span class=\"sow-icon-elegantline\" data-sow-icon=\"&#xe028;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Expression Libre<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\n\t<\/ul>\n\n\t<div class=\"iw-so-tabs-content\">\n\n\t\t\t\t\t<div class=\"iw-so-tabs-panel iw-so-tab-active\" id=\"ink-tabs-828010003-1-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-7de6ca3ldm\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25158\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/22-octobre-1921-centieme-anniversaire-de-la-naissance-de-georges-brassens\/\" class=\"_self cvplbd\" target=\"_self\" >22 octobre 1921 : centi\u00e8me anniversaire de la naissance de Georges Brassens<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/22-octobre-1921-centieme-anniversaire-de-la-naissance-de-georges-brassens\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"22 octobre 1921 : centi\u00e8me anniversaire de la naissance de Georges Brassens\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/Un-poete-une-nuit-un-phare.-Image-par-Willgard-Krause-de-Pixabay-Image-par-Willgard-Krause-de-Pixabay-.jpg?resize=613%2C345&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Une autre route qu\u2019eux \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00ab Plus c\u2019est po\u00e9tique, plus c\u2019est r\u00e9el \u00bb \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 G.P. F. Novalis \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00ab Trenet sans qui nous serions tous des comptables \u00bb \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Jacques Brel Un po\u00e8te, une nuit, un phare. Image par Willgard Krause de Pixabay Image par Willgard Krause de Pixabay Lorsque j\u2019ai acquiesc\u00e9 \u00e0 la proposition d\u2019\u00e9crire quelque chose pour l\u2019anniversaire de la naissance de Georges Brassens, j\u2019avais en t\u00eate la ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/22-octobre-1921-centieme-anniversaire-de-la-naissance-de-georges-brassens\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/sophie\/\" rel=\"author\">Sophie Masini<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:34+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25163\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/le-rec-de-veyret-a-narbonne-un-enjeu-durbanisme-et-damenagement\/\" class=\"_self cvplbd\" target=\"_self\" >Le Rec de Veyret \u00e0 Narbonne : un enjeu d\u2019urbanisme et d\u2019am\u00e9nagement<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/le-rec-de-veyret-a-narbonne-un-enjeu-durbanisme-et-damenagement\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Le Rec de Veyret \u00e0 Narbonne : un enjeu d\u2019urbanisme et d\u2019am\u00e9nagement\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/Barrage-Cap-de-Pla-1.jpg?resize=600%2C338&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Entour\u00e9e de collines couvertes d\u2019une v\u00e9g\u00e9tation m\u00e9diterran\u00e9enne, la ville de Narbonne est non seulement expos\u00e9e aux risques d\u2019incendie, mais aussi aux inondations brutales, d\u00e9clench\u00e9es par des \u00e9pisodes pluvieux aussi soudains que massifs qui peuvent cr\u00e9er de graves probl\u00e8mes d\u2019\u00e9coulement. Les \u00ab\u00a0rec\u00a0\u00bb d\u00e9signent\u00a0 en langue locale de petits ruisseaux, qui strient les bassins versants. Souvent \u00e0 sec en \u00e9t\u00e9,\u00a0 ils se transforment parfois, suite \u00e0 des \u00e9pisodes de forts orages, en ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/le-rec-de-veyret-a-narbonne-un-enjeu-durbanisme-et-damenagement\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/laurent\/\" rel=\"author\">Laurent Fabas<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:33+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25229\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/a-propos-du-communique-de-la-conference-paysanne-de-laude-sur-le-rapport-du-giec\/\" class=\"_self cvplbd\" target=\"_self\" >A propos du communiqu\u00e9 de la Conf\u00e9rence paysanne de l\u2018Aude sur le rapport du <span class='tooltipsall tooltip_post_id_20538 classtoolTips113'>GIEC<\/span><\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/a-propos-du-communique-de-la-conference-paysanne-de-laude-sur-le-rapport-du-giec\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"A propos du communiqu\u00e9 de la Conf\u00e9rence paysanne de l\u2018Aude sur le rapport du GIEC\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/cyclone-Image-par-WikiImages-de-Pixabay.jpg?resize=605%2C399&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Cyclone Katrina age par WikiImages de Pixabay.jpg Le 9 ao\u00fbt dernier le GIEC (Groupe d\u2019experts intergouvernemental sur l\u2019\u00e9volution du climat) publiait son 6\u00e8me rapport sur le climat. Ce rapport qui s\u2019appuie sur une base de plus de 14.000 \u00e9tudes, a \u00e9t\u00e9 r\u00e9dig\u00e9 par 234 scientifiques de 66 pays. Il confirme ce qui, jusque l\u00e0, \u00e9tait pr\u00e9sent\u00e9 comme une hypoth\u00e8se probable\u00a0: il \u00a0y a une relation \u00e9troite entre le r\u00e9chauffement constat\u00e9 ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/a-propos-du-communique-de-la-conference-paysanne-de-laude-sur-le-rapport-du-giec\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:22+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25210\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/cigeo-enfouissons-ces-dechets-nucleaires-que-nous-ne-saurions-voir\/\" class=\"_self cvplbd\" target=\"_self\" ><span class='tooltipsall tooltip_post_id_4298 classtoolTips91'>Cigeo<\/span> : enfouissons <span class='tooltipsall tooltip_post_id_29829 classtoolTips180'>ces<\/span> d\u00e9chets nucl\u00e9aires que  nous ne saurions voir ! (*)<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/cigeo-enfouissons-ces-dechets-nucleaires-que-nous-ne-saurions-voir\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Cigeo : enfouissons ces d\u00e9chets nucl\u00e9aires que  nous ne saurions voir ! (*)\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/nuclear-waste-Image-par-Dirk-Rabe-de-Pixabay.jpg?resize=595%2C308&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">La France d\u00e9tient apr\u00e8s le Japon le record de densit\u00e9 de r\u00e9acteurs nucl\u00e9aires au Km\u00b2. Depuis 1963 ces r\u00e9acteurs produisent des d\u00e9chets de moyenne activit\u00e9 \u00e0 vie longue (<span class='tooltipsall tooltip_post_id_19197 classtoolTips99'>MA-VL<\/span>) et de haute activit\u00e9 \u00e0 vie longue (<span class='tooltipsall tooltip_post_id_19196 classtoolTips223'>HA<\/span>-VL). Ces d\u00e9chets ont \u00e9t\u00e9 entrepos\u00e9s dans des sites provisoires ; \u00e0 ce jour aucune solution de stockage d\u00e9finitif s\u00fbre et efficace n\u2019a \u00e9t\u00e9 trouv\u00e9e.  ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/cigeo-enfouissons-ces-dechets-nucleaires-que-nous-ne-saurions-voir\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/curly\/\" rel=\"author\">Curly Mc Toole<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:00+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-81c6c82hvc\">#pt-cv-view-7de6ca3ldm  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-7de6ca3ldm.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-7de6ca3ldm.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-7de6ca3ldm.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-7de6ca3ldm .pt-cv-title a, #pt-cv-view-7de6ca3ldm  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-7de6ca3ldm  .pt-cv-title a:hover, #pt-cv-view-7de6ca3ldm  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-7de6ca3ldm .pt-cv-content , #pt-cv-view-7de6ca3ldm  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-7de6ca3ldm  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-7de6ca3ldm .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-7de6ca3ldm .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-7de6ca3ldm .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-7de6ca3ldm  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-7de6ca3ldm  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-7de6ca3ldm li a   { font-weight: 600 !important; }\n#pt-cv-gls-7de6ca3ldm li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><br \/>\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#be8552;border-radius:10px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:#f1b885;color:#88360d;border-top-left-radius:8px;border-top-right-radius:8px\">Les Br\u00e8ves du mois<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:8px;border-bottom-right-radius:8px\"><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-scrollable pt-cv-colsys pt-cv-nolf pt-cv-reused\" id=\"pt-cv-view-176b9dand1\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"3\"><div id=\"fc97dcdqp1\" class=\"pt-cv-carousel pt-cv-slide\" data-ride=\"cvcarousel\" data-interval=5000>\n<div class=\"carousel-inner\"><div class=\"item active\"><div class=\"row\"><div class=\"col-md-4 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25224\"><div class=\"pt-cv-carousel-caption pt-cv-cap-wo-img\"><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/le-festival-du-theatre-de-segure-a-bien-eu-lieu\/\" class=\"_self cvplbd\" target=\"_self\" >Le festival du Th\u00e9\u00e2tre de S\u00e9gure \u00e0 bien eu lieu<\/a><\/h2>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/hubert\/\" rel=\"author\">Hubert Reys<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2021-09-23T12:30:56+02:00\">23 septembre 2021<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">Photo HR Non seulement\u00a0 le 5\u00e8me festival de S\u00e9gure a bien eu lieu du 18 au 22 ao\u00fbt, mais il ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/le-festival-du-theatre-de-segure-a-bien-eu-lieu\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"col-md-4 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25146\"><div class=\"pt-cv-carousel-caption pt-cv-cap-wo-img\"><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/une-croissance-qui-fait-plaisir-celle-du-velo-en-france\/\" class=\"_self cvplbd\" target=\"_self\" >Une croissance qui fait plaisir : celle du v\u00e9lo en France<\/a><\/h2>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/lbvp\/\" rel=\"author\">Louise B Velpeau<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2021-09-23T12:30:34+02:00\">23 septembre 2021<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">Voici une croissance qui r\u00e9jouit et qui apporte plus de bienfaits que de torts : en France le v\u00e9lo connait ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/une-croissance-qui-fait-plaisir-celle-du-velo-en-france\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-3e08720802\">#pt-cv-view-176b9dand1 .pt-cv-content-item { padding-left: 5px !important; padding-right: 5px !important; }\n#pt-cv-view-176b9dand1  { margin-left: -5px !important; margin-right: -5px !important; }\n#pt-cv-view-176b9dand1 .pt-cv-carousel-caption { padding-top: 0px !important; padding-left: 0px !important; padding-bottom: 5px !important; padding-right: 0px !important; }\n#pt-cv-view-176b9dand1 .pt-cv-carousel-caption { left : 5px !important }\n#pt-cv-view-176b9dand1 .carousel-control.left { right : 40px }\n#pt-cv-view-176b9dand1 .pt-cv-carousel-caption { right : 5px !important }\n#pt-cv-view-176b9dand1 .carousel-control.right { right : 5px }\n#pt-cv-view-176b9dand1 .row {margin: 0 0 !important}\n#pt-cv-view-176b9dand1  .pt-cv-carousel-caption   { background-color: rgba(234,212,86,0.2) !important; }\n#pt-cv-view-176b9dand1.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-176b9dand1.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-176b9dand1.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-176b9dand1 .pt-cv-title a, #pt-cv-view-176b9dand1  .panel-title { font-family: 'Nunito', Arial, serif !important; font-size: 14px !important; color: #cc2e2e !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-176b9dand1  .pt-cv-title a:hover, #pt-cv-view-176b9dand1  .panel-title:hover   { color: rgba(204,46,46,0.41) !important; }\n#pt-cv-view-176b9dand1 .pt-cv-content , #pt-cv-view-176b9dand1  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 12px !important; line-height: 1.3 !important; }\n#pt-cv-view-176b9dand1  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(214,214,214,0.77) !important; }\n#pt-cv-view-176b9dand1 .pt-cv-meta-fields * { font-size: 12px !important; line-height: 1.3 !important; }\n#pt-cv-view-176b9dand1 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-176b9dand1 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-176b9dand1  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-176b9dand1  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-176b9dand1 li a   { font-weight: 600 !important; }\n#pt-cv-gls-176b9dand1 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Nunito' rel='stylesheet' type='text\/css'> <br><\/div><\/div><br \/>\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#be8552;border-radius:10px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:#f1b885;color:#88360d;border-top-left-radius:8px;border-top-right-radius:8px\">La chronique des Successeurs<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:8px;border-bottom-right-radius:8px\"><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-reused\" id=\"pt-cv-view-8d96c5df5a\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"25242\"><div class='pt-cv-ifield'><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/cette-fois-ci-un-film-les-sorcieres-darkelare\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-left cvplbd\" target=\"_self\" ><img decoding=\"async\" width=\"300\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/La-chronique-des-successeurs.jpg?resize=300%2C81&amp;ssl=1\" class=\"pt-cv-thumbnail img-none pull-left cvp-substitute no-lazyload \" alt=\"Cette fois-ci un film : Les sorci\u00e8res d\u2019Ark\u00e9lare\" title=\"\" data-no-lazy=\"1\" \/><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/cette-fois-ci-un-film-les-sorcieres-darkelare\/\" class=\"_self cvplbd\" target=\"_self\" >Cette fois-ci un film : Les sorci\u00e8res d\u2019Ark\u00e9lare<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/lenaw\/\" rel=\"author\">Lena Waag<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2021-09-23T12:30:39+02:00\">23 septembre 2021<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">Les sorci\u00e8res d\u2019Ark\u00e9lare \u00a0 Les Sorci\u00e8res d&rsquo;Akelarre\u00a0: 2021, film r\u00e9alis\u00e9 par Pablo Ag\u00fcero avec Alex Brendem\u00fchl, Amaia Aberasturi \u00c9nigmes de la nature et fantasmes masculins, les femmes insolentes dont il est question dans ce film, furent coupables de f\u00e9minit\u00e9 et de libert\u00e9. Voici une histoire vraie, durant l\u2019inquisition, puissante et envoutante, o\u00f9 l\u2019autorit\u00e9 patriarcale est bouscul\u00e9e ; dans un monde o\u00f9 les hommes craignent les femmes qui n\u2019ont pas peur. Terrifiant d\u2019actualit\u00e9. Sorci\u00e8re Image par silphatristis de Pixabay \u00ab\u00a0Les sorci\u00e8res d\u2019Akelarre\u00a0\u00bb (Un mot qui signifie sabbat en basque), est un film \u00e0 petit budget, qui a re\u00e7u de nombreuses nominations et r\u00e9compenses en Espagne. Un hymne f\u00e9ministe ensorcelant d\u2019\u00e9l\u00e9gance et de courage. \u00a0 L\u2019histoire se passe au pays basque, en l\u2019an 1609. Tandis que les hommes sont partis en mer, six jeunes femmes participent \u00e0 une f\u00eate dans les bois, la nuit, avec d\u2019autres filles du village. A l\u2019aube, elles sont imm\u00e9diatement arr\u00eat\u00e9es et accus\u00e9es d\u2019avoir particip\u00e9 \u00e0 une c\u00e9r\u00e9monie satanique\u00a0: le Sabbat. Quoi qu\u2019elles disent ou fassent pour leur d\u00e9fense, elles sont diabolis\u00e9es par ces hommes qui les m\u00e9prisent et les torturent\u00a0: le pr\u00eatre du village, les soldats, et le juge Pierre de Rosteguy de Lancre (missionn\u00e9 par Henri ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/cette-fois-ci-un-film-les-sorcieres-darkelare\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-02e1a58rxd\">#pt-cv-view-8d96c5df5a  .pt-cv-ifield   { background-color: rgba(234,212,86,0.2) !important; }\n#pt-cv-view-8d96c5df5a.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-8d96c5df5a.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-8d96c5df5a.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-8d96c5df5a .pt-cv-title a, #pt-cv-view-8d96c5df5a  .panel-title { color: #cc2e2e !important; font-weight: 600 !important; }\n#pt-cv-view-8d96c5df5a  .pt-cv-title a:hover, #pt-cv-view-8d96c5df5a  .panel-title:hover   { color: rgba(204,46,46,0.41) !important; }\n#pt-cv-view-8d96c5df5a .pt-cv-content , #pt-cv-view-8d96c5df5a  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-8d96c5df5a .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-8d96c5df5a .pt-cv-readmore:hover  { color: #ff413a !important; font-weight: 600 !important; }\n#pt-cv-view-8d96c5df5a  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-8d96c5df5a  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-8d96c5df5a li a   { font-weight: 600 !important; }\n#pt-cv-gls-8d96c5df5a li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t <br><\/div><\/div><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-2-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-0a21f34gl7\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25158\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/22-octobre-1921-centieme-anniversaire-de-la-naissance-de-georges-brassens\/\" class=\"_self cvplbd\" target=\"_self\" >22 octobre 1921 : centi\u00e8me anniversaire de la naissance de Georges Brassens<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/22-octobre-1921-centieme-anniversaire-de-la-naissance-de-georges-brassens\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"22 octobre 1921 : centi\u00e8me anniversaire de la naissance de Georges Brassens\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/Un-poete-une-nuit-un-phare.-Image-par-Willgard-Krause-de-Pixabay-Image-par-Willgard-Krause-de-Pixabay-.jpg?resize=613%2C345&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Une autre route qu\u2019eux \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00ab Plus c\u2019est po\u00e9tique, plus c\u2019est r\u00e9el \u00bb \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 G.P. F. Novalis \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00ab Trenet sans qui nous serions tous des comptables \u00bb \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Jacques Brel Un po\u00e8te, une nuit, un phare. Image par Willgard Krause de Pixabay Image par Willgard Krause de Pixabay Lorsque j\u2019ai acquiesc\u00e9 \u00e0 la proposition d\u2019\u00e9crire quelque chose pour l\u2019anniversaire de la naissance de Georges Brassens, j\u2019avais en t\u00eate la ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/22-octobre-1921-centieme-anniversaire-de-la-naissance-de-georges-brassens\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/sophie\/\" rel=\"author\">Sophie Masini<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:34+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25168\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/la-loi-de-teheran\/\" class=\"_self cvplbd\" target=\"_self\" >La loi de T\u00e9h\u00e9ran<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/la-loi-de-teheran\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"La loi de T\u00e9h\u00e9ran\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/addict-Image-par-%D0%9B%D0%B5%D1%87%D0%B5%D0%BD%D0%B8%D0%B5-%D0%9D%D0%B0%D1%80%D0%BA%D0%BE%D0%BC%D0%B0%D0%BD%D0%B8%D0%B8-de-Pixabay.jpg?resize=348%2C232&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Iran \u2013 2h14 &#8211; 2021- Un film de Saeed Roustayi avec Payman Maadi, Navid Mohammadzadeh, Houman Kiai. \u00a0\u00bb Dura lex sed lex \u00ab\u00a0 addict-Image par \u041b\u0435\u0447\u0435\u043d\u0438\u0435 \u041d\u0430\u0440\u043a\u043e\u043c\u0430\u043d\u0438\u0438 de Pixabay Quel que soit le poids de la drogue avec laquelle on est arr\u00eat\u00e9, la loi est la m\u00eame : la peine de mort. Cela se passe en Iran de nos jours et 6,5 millions de personnes vivent dans l&rsquo;enfer de la ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/la-loi-de-teheran\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/patren\/\" rel=\"author\">Patricia Renaud<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:28+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25178\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/drive-my-car\/\" class=\"_self cvplbd\" target=\"_self\" >Drive my car<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/drive-my-car\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Drive my car\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/shirakawa02-Image-par-pen_ash-de-Pixabay.jpg?resize=384%2C256&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Japon \u2013 2h59 \u2013 2021 \u2013 Prix du sc\u00e9nario au festival de Cannes 2021 Un film de Ryusuke Hamaguchi avec Hidetoshi Nishijima, Toko Miura, Masaki Okada. Adaptation d&rsquo;un extrait du recueil \u00ab\u00a0Des hommes sans femmes\u00a0\u00bb de Haruki Murakami. Un chef d&rsquo;\u0153uvre de d\u00e9licatesse shirakawa02-Image par pen_ash de Pixabay Yusuke Kafuku\u00a0 est acteur et metteur en sc\u00e8ne. Oto, sa femme, lui raconte une histoire qui sert de pr\u00e9lude sexuel. Mais Oto ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/drive-my-car\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/patren\/\" rel=\"author\">Patricia Renaud<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:55+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25174\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/un-triomphe\/\" class=\"_self cvplbd\" target=\"_self\" >Un triomphe<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/un-triomphe\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Un triomphe\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/enactment-Image-par-Mauricio-Keller-Keller-de-Pixabay.jpg?resize=300%2C199&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">France &#8211; 1h48 \u2013 2019 Un film de Emmanuel Courcol avec Kad Merad, David Ayala, Lamine Cissokho, Pierre Lottin, Sofian Khammes, Marina Hands, Wabinl\u00e9 Nabi\u00e9, Aleksandr Medvedev, Sa\u00efd Benchnafa, Laurent Stocker. Un grand moment et du vrai th\u00e9\u00e2tre au cin\u00e9ma ! r\u00e9p\u00e9tition-Image par Mauricio Keller Keller de Pixabay Un acteur sur le d\u00e9clin accepte d&rsquo;animer des ateliers th\u00e9\u00e2tre en prison. Certains d\u00e9tenus vont l&rsquo;\u00e9tonner par leur capacit\u00e9 \u00e0 se mettre ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/un-triomphe\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/patren\/\" rel=\"author\">Patricia Renaud<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:03+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25219\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/un-plat-de-legumes-a-la-mode-iranienne\/\" class=\"_self cvplbd\" target=\"_self\" >Un plat de l\u00e9gumes \u00e0 la mode iranienne<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/un-plat-de-legumes-a-la-mode-iranienne\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Un plat de l\u00e9gumes \u00e0 la mode iranienne\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/92B2905.jpg?resize=602%2C319&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Encore un peu de soleil avec l\u2019automne qui vient\u00a0! Voici un plat pour les v\u00e9g\u00e9tariens\u2026et les autres. Il n\u2019est compos\u00e9 que de l\u00e9gumes et d\u2019\u0153ufs. Il nous vient du nord de l\u2019Iran gr\u00e2ce \u00e0 Safoura qui a bien voulu nous pr\u00e9parer ce d\u00e9lice au go\u00fbt fum\u00e9 que l\u2019on sert en Iran sur du pain ou avec du riz.. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Mirza \u2013 ghasemi (Photo Colin Reys) \u00a0 Ingr\u00e9dients\u00a0pour 4 personnes : ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/un-plat-de-legumes-a-la-mode-iranienne\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:17+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25224\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/le-festival-du-theatre-de-segure-a-bien-eu-lieu\/\" class=\"_self cvplbd\" target=\"_self\" >Le festival du Th\u00e9\u00e2tre de S\u00e9gure \u00e0 bien eu lieu<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/le-festival-du-theatre-de-segure-a-bien-eu-lieu\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Le festival du Th\u00e9\u00e2tre de S\u00e9gure \u00e0 bien eu lieu\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/12\/Breves-du-Clairon-nvelle.jpg?resize=153%2C65&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Photo HR Non seulement\u00a0 le 5\u00e8me festival de S\u00e9gure a bien eu lieu du 18 au 22 ao\u00fbt, mais il est pass\u00e9 de 3 \u00e0 5 jours. On ne peut que saluer cette vitalit\u00e9, lorsque l\u2019on sait toutes les emb\u00fbches d\u00e9ploy\u00e9es par une voisine irascible, qui semble penser qu\u2019un th\u00e9\u00e2tre install\u00e9 \u00e0 quelques dizaines de m\u00e8tres de son domaine allait troubler sa qui\u00e9tude. Le pot de terre contre le pot ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/le-festival-du-theatre-de-segure-a-bien-eu-lieu\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/hubert\/\" rel=\"author\">Hubert Reys<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:56+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25242\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/cette-fois-ci-un-film-les-sorcieres-darkelare\/\" class=\"_self cvplbd\" target=\"_self\" >Cette fois-ci un film : Les sorci\u00e8res d\u2019Ark\u00e9lare<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/cette-fois-ci-un-film-les-sorcieres-darkelare\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Cette fois-ci un film : Les sorci\u00e8res d\u2019Ark\u00e9lare\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/La-chronique-des-successeurs.jpg?resize=300%2C81&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Les sorci\u00e8res d\u2019Ark\u00e9lare \u00a0 Les Sorci\u00e8res d&rsquo;Akelarre\u00a0: 2021, film r\u00e9alis\u00e9 par Pablo Ag\u00fcero avec Alex Brendem\u00fchl, Amaia Aberasturi \u00c9nigmes de la nature et fantasmes masculins, les femmes insolentes dont il est question dans ce film, furent coupables de f\u00e9minit\u00e9 et de libert\u00e9. Voici une histoire vraie, durant l\u2019inquisition, puissante et envoutante, o\u00f9 l\u2019autorit\u00e9 patriarcale est bouscul\u00e9e ; dans un monde o\u00f9 les hommes craignent les femmes qui n\u2019ont pas peur ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/09\/23\/cette-fois-ci-un-film-les-sorcieres-darkelare\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/lenaw\/\" rel=\"author\">Lena Waag<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2021-09-23T12:30:39+02:00\">23 septembre 2021<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-0ed4868rfw\">#pt-cv-view-0a21f34gl7  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-0a21f34gl7.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-0a21f34gl7.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-0a21f34gl7.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-0a21f34gl7 .pt-cv-title a, #pt-cv-view-0a21f34gl7  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-0a21f34gl7  .pt-cv-title a:hover, #pt-cv-view-0a21f34gl7  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-content , #pt-cv-view-0a21f34gl7  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-0a21f34gl7  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-0a21f34gl7  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-0a21f34gl7  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-0a21f34gl7 li a   { font-weight: 600 !important; }\n#pt-cv-gls-0a21f34gl7 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-3-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-post-border pt-cv-reused\" id=\"pt-cv-view-8090fb6z9g\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page cv-npf\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"0\"><div class='pt-cv-ifield'><div class=\"pt-cv-no-post\">Aucune publication trouv\u00e9e.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-fd39dd2vq3\">#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-color: #ede0ce; border-left-color: #ede0ce }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; border-right-color: #ede0ce; border-bottom-color: #ede0ce; }\n#pt-cv-view-8090fb6z9g .pt-cv-title a, #pt-cv-view-8090fb6z9g  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-8090fb6z9g  .pt-cv-hover-wrapper::before   { background-color: rgba(0,0,0,.3) !important; }\n#pt-cv-view-8090fb6z9g  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-8090fb6z9g:not(.pt-cv-nohover) .pt-cv-mask *   { color: #fff; }\n#pt-cv-view-8090fb6z9g .pt-cv-carousel-caption  { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-meta-fields * { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-specialp { background-color: #CC3333 !important }\n#pt-cv-view-8090fb6z9g .pt-cv-specialp * { color: #fff !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-pficon  { color: #bbb !important; }\n#pt-cv-view-8090fb6z9g  .add_to_cart_button, #pt-cv-view-8090fb6z9g  .add_to_cart_button *   { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-8090fb6z9g  .woocommerce-onsale   { color: #ffffff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-8090fb6z9g  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-8090fb6z9g  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-8090fb6z9g'] .active.pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .active .pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .selected.pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .dropdown-toggle   { color: #fff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-8090fb6z9g'] .pt-cv-filter-title   { color: #fff !important; background-color: #00aeef !important; }\n#pt-cv-gls-8090fb6z9g li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-gls-header  { color: #fff !important; background-color: #00aeef !important; }<\/style>\r\n\t\t\t <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-25184-2-2\"  class=\"panel-grid-cell\" ><div class=\"panel-cell-style panel-cell-style-for-25184-2-2\" ><div id=\"panel-25184-2-2-0\" class=\"so-panel widget widget_cl-popup widget-cl-popup panel-first-child\" data-index=\"5\" ><div class=\"panel-widget-style panel-widget-style-for-25184-2-2-0\" ><div class=\"cl-popup align_center\"><a href=\"javascript:void(0)\" class=\"cl-popup-trigger type_btn cl-btn\" style=\"color:#c60000;background-color:rgba(221,153,51,0.25);\"><span>M\u00e9dias pr\u00e9f\u00e9r\u00e9s du Clairon<\/span><\/a><div class=\"cl-popup-overlay\" style=\"background-color:rgba(2,0,0,0.67);\"><\/div><div class=\"cl-popup-wrap\"><div class=\"cl-popup-box size_m animation_flipVer\" style=\"border-radius:10px;\"><div class=\"cl-popup-box-h\"><div class=\"cl-popup-box-title\" style=\"color:#666666;background-color:#f2f2f2;\">Les m\u00e9dias choisis par le Clairon<\/div><div class=\"cl-popup-box-content\" style=\"color:#333333;background-color:#ffffff;\"><p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 12pt;\">De nombreux lecteurs du Clairon regrettent de ne pas avoir acc\u00e8s \u00e0 des m\u00e9dias qu\u2019ils souhaitent objectifs. Il nous a paru utile de leur proposer une liste de m\u00e9dias qui, comme nous, ont pour projet \u00e9ditorial de faire r\u00e9fl\u00e9chir leurs lecteurs, leurs auditeurs ou leurs spectateurs. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 12pt;\">Ce qui nous importe, c\u2019est qu\u2019ils ne soient pas des outils de formatage au service d\u2019une cause ou d\u2019une autre, mais qu\u2019ils contribuent \u00e0 ce que chaque individu puisse faire \u00e9voluer ses id\u00e9es&nbsp; en toute conscience.<\/span><\/p>\n<span style=\"color: #000000; font-size: 12pt;\">Les m\u00e9dias s\u00e9lectionn\u00e9s r\u00e9sultent des choix de la r\u00e9daction du Clairon.\nCette s\u00e9lection n\u2019est pas d\u00e9finitive, elle peut \u00e9voluer.<\/span>\n\n<span style=\"font-size: 12pt;\"><em><strong>Bien \u00e9videmment, la publicit\u00e9 que nous faisons pour ces m\u00e9dias est exclusivement le fruit de notre conviction de leur int\u00e9r\u00eat pour nos lecteurs.\n<span style=\"text-decoration: underline;\">Elle est donc gratuite<\/span> et ne b\u00e9n\u00e9ficie d'aucun retour de leur part, de quelque sorte que ce soit.<\/strong><\/em><\/span>\n\n<span style=\"color: #000000; font-size: 12pt;\"><em>En cliquant sur un logo, vous acc\u00e9dez au site du m\u00e9dia dans un nouvel onglet de votre navigateur.<\/em><\/span><\/div><div class=\"cl-popup-box-closer\" style=\"color:#666666;\"><\/div><\/div><\/div><div class=\"cl-popup-closer\"><\/div><\/div><\/div><\/div><\/div><div id=\"panel-25184-2-2-1\" class=\"so-panel widget widget_sow-image-grid panel-last-child\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image-grid so-widget-sow-image-grid-default-46e3cddde1e5-25184\"\n\t\t\t\n\t\t>\t<div\n\t\tclass=\"sow-image-grid-wrapper\"\n\t\t\t\t\t>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.bastamag.net\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"489\" height=\"269\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-basta-ombre.png?fit=489%2C269&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Excellent magazine gratuit en ligne, soutenu \u00e0 parts \u00e9gales par ses lecteurs et par des fondations - Existe depuis 2008 - Informations dans les domaines \u00e9conomique, social et environnemental - Son orientation ? L&#039;int\u00e9r\u00eat g\u00e9n\u00e9ral&quot;\" title=\"Basta !\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-basta-ombre.png?w=489&amp;ssl=1 489w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-basta-ombre.png?resize=300%2C165&amp;ssl=1 300w\" sizes=\"auto, (max-width: 489px) 100vw, 489px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.portail.bastamag.net\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"329\" height=\"107\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/Logo-Basta-Portail-ML-ombre.png?fit=329%2C107&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Initi\u00e9 par Basta !, ce portail vous donne acc\u00e8s \u00e0 de nombreux media alternatifs, peu connus du grand public mais dignes d&#039;int\u00e9r\u00eat&quot;\" title=\"Portail des media libres\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/Logo-Basta-Portail-ML-ombre.png?w=329&amp;ssl=1 329w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/Logo-Basta-Portail-ML-ombre.png?resize=300%2C98&amp;ssl=1 300w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.reporterre.net\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"538\" height=\"261\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-reporterre-ombre.png?fit=538%2C261&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"&quot;Le quotidien de l&#039;\u00e9cologie&quot; - Lanc\u00e9 en 2007 par le journaliste Herv\u00e9 Kempf, ce site gratuit d&#039;actualit\u00e9s traite principalement de probl\u00e9matiques environnementales &quot;\" title=\"Reporterre\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-reporterre-ombre.png?w=538&amp;ssl=1 538w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-reporterre-ombre.png?resize=300%2C146&amp;ssl=1 300w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.actu-environnement.com\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"331\" height=\"219\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Actu-Environnement-ombre.png?fit=331%2C219&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Depuis 2003, ce site de presse d\u00e9livre quotidiennement des informations sp\u00e9cialis\u00e9es sur les secteurs de l\u2019Environnement : d\u00e9chets, eau, \u00e9nergie, risques, am\u00e9nagement, biodiversit\u00e9, etc. Il est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 de presse ind\u00e9pendante CogiTerra&quot;\" title=\"Actu-Environnement\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Actu-Environnement-ombre.png?w=331&amp;ssl=1 331w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Actu-Environnement-ombre.png?resize=300%2C198&amp;ssl=1 300w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.agoravox.fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"95\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Agoravox-ombre.png?fit=350%2C95&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"M\u00e9dia citoyen, AgoraVox propose \u00e0 tout citoyen de devenir r\u00e9dacteur, en vue de mettre librement \u00e0 disposition de ses lecteurs des informations th\u00e9matiques in\u00e9dites, d\u00e9tect\u00e9es par les citoyens.&quot;\" title=\"AgoraVox\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Agoravox-ombre.png?w=350&amp;ssl=1 350w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Agoravox-ombre.png?resize=300%2C81&amp;ssl=1 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mediapart.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"199\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Mediapart-ombre.png?fit=499%2C199&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"&quot;Seuls nos lecteurs peuvent nous acheter&quot; - Ce quotidien payant d&#039;actualit\u00e9 en ligne, que l&#039;on ne pr\u00e9sente plus tant il est connu bien au-del\u00e0 de son lectorat, est, depuis 2008, une r\u00e9f\u00e9rence en mati\u00e8re d&#039;information et d&#039;investigation&quot;\" title=\"Mediapart\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Mediapart-ombre.png?w=499&amp;ssl=1 499w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Mediapart-ombre.png?resize=300%2C120&amp;ssl=1 300w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lemonde.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"351\" height=\"110\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Le-Monde-ombre.png?fit=351%2C110&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Quotidien g\u00e9n\u00e9raliste du soir, Le Monde a \u00e9t\u00e9 fond\u00e9 par Hubert Beuve-Mery en 1944. Edit\u00e9 initialement sur support papier, il est diffus\u00e9 depuis plusieurs ann\u00e9es sur l&#039;internet.&quot;\" title=\"Le Monde\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Le-Monde-ombre.png?w=351&amp;ssl=1 351w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Le-Monde-ombre.png?resize=300%2C94&amp;ssl=1 300w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.monde-diplomatique.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"433\" height=\"116\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Diplo-ombre.png?fit=433%2C116&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Fond\u00e9 en 1954 par Hubert Beuve-M\u00e9ry, le &quot;Diplo&quot;, initialement destin\u00e9  aux cercles diplomatiques, est un mensuel payant,combinant analyses, enqu\u00eates et reportages qui s&#039;affirme comme un &quot;journal de r\u00e9f\u00e9rence pour tous ceux qui veulent comprendre le monde, mais aussi le changer&quot; - R\u00e9guli\u00e8rement, des articles en libre acc\u00e8s permettent de se faire  une id\u00e9e juste de la qualit\u00e9 de ce mensuel de haute tenue.&quot;\" title=\"Le Monde Diplomatique\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Diplo-ombre.png?w=433&amp;ssl=1 433w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Diplo-ombre.png?resize=300%2C80&amp;ssl=1 300w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alternatives-economiques.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-AlterEco-ombre.png?fit=240%2C240&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Fond\u00e9 par Denis Clerc en 1980, le mensuel &quot;Alternavives Economiques&quot; s\u2019int\u00e9resse \u00e0 &quot;l\u2019\u00e9conomie comme enjeu collectif et social, \u00e0 travers des th\u00e9matiques vari\u00e9es : Europe, mondialisation, travail, emploi, sant\u00e9, retraites, famille, transports, solidarit\u00e9, \u00e9ducation, cadre de vie, environnement...&quot;. Il est compl\u00e9t\u00e9 par un quotidien payant d&#039;actualit\u00e9s en ligne sur les m\u00eames th\u00e8mes&quot;\" title=\"Alternatives \u00c9conomiques\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-AlterEco-ombre.png?w=240&amp;ssl=1 240w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-AlterEco-ombre.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lecanardenchaine.fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"525\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Canard-Enchaine-ombre.png?fit=630%2C525&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Peu de gens ignorent &quot;le journal satirique paraissant le mercredi&quot;. Et cela depuis plus d&#039;un si\u00e8cle. Chaque semaine, il nous rappelle que &quot;la libert\u00e9 de la presse ne s&#039;use que si l&#039;on ne s&#039;en sert pas&quot;. Derri\u00e8re un ton fantaisiste, ses articles r\u00e9v\u00e8lent des informations parfois explosives et toujours minutieusement v\u00e9rifi\u00e9es. &quot;\" title=\"Le Canard Encha\u00een\u00e9\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Canard-Enchaine-ombre.png?w=630&amp;ssl=1 630w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Canard-Enchaine-ombre.png?resize=300%2C250&amp;ssl=1 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/charliehebdo.fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"361\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Charlie-Hebdo-ombre.png?fit=660%2C361&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Hebdomadaire satirique fran\u00e7ais fond\u00e9 en 1970 par Fran\u00e7ois Cavanna et le professeur Choron, Charlie Hebdo est connu pour ses dessins satiriques, notamment au travers de ses c\u00e9l\u00e8bres couvertures et de celles &quot;auxquelles vous avez \u00e9chapp\u00e9&quot;. Il pratique aussi le journalisme d&#039;investigation, sur des domaines tels que les sectes, les religions, l&#039;extr\u00eame droite, l&#039;islamisme, la politique, la culture.&quot;\" title=\"Charlie Hebdo\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Charlie-Hebdo-ombre.png?w=660&amp;ssl=1 660w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Charlie-Hebdo-ombre.png?resize=300%2C164&amp;ssl=1 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.franceculture.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"243\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Franc-Culture-ombre.png?fit=249%2C243&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"&quot;France Culture, l&#039;esprit d&#039;ouverture&quot; - Baptis\u00e9e sous ce nom en 1963, cette antenne de Radio France est l&#039;une des plus riches qui soit : Actualit\u00e9s, Savoirs, Art et Cr\u00e9ation, Fictions, Documentaires et Conf\u00e9rences, il y en a pour toutes les curiosit\u00e9s. Son site web permet non seulement d&#039;\u00e9couter les \u00e9missions en direct, mais aussi de les r\u00e9\u00e9couter sans limite dans le temps, de lire des articles originaux et d&#039;\u00e9couter des &quot;podcasts&quot; non diffus\u00e9s \u00e0 la radio. Edite aussi la revue trimestrielle &quot;Papiers&quot;&quot;\" title=\"France Culture\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.arte.tv\/fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"346\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Arte-ombre.png?fit=604%2C346&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Ouverte en 1992, l&#039;antenne franco-allemande ARTE (Association Relative \u00e0 la T\u00e9l\u00e9vision Europ\u00e9enne) a pour mission de &quot;rapprocher les europ\u00e9ens&quot;. Son projet est de &quot;faire de la culture un lien vivant entre les hommes&quot;. Elle est financ\u00e9e \u00e0 95% par la contribution \u00e0 l&#039;audiovisuel  public en Allemagne et en France. Ses programmes sont disponibles en 6 langues, permettant \u00e0 70% des europ\u00e9ens de la regarder dans leur langue maternelle. 85% de ses programmes sont produits dans l&#039;Union Europ\u00e9enne.&quot;\" title=\"ARTE\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Arte-ombre.png?w=604&amp;ssl=1 604w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Arte-ombre.png?resize=300%2C172&amp;ssl=1 300w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.acrimed.org\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"285\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Acrimed-ombre.png?fit=285%2C285&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Action CRItique MEDia (ACRIMED) est une association fond\u00e9e an 1996 par Pierre Bourdieu et Henri Maler. Son but est d&#039;\u00eatre un &quot;observatoire des media... au service d&#039;une critique ind\u00e9pendante, radicale et intransigeante&quot;&quot;\" title=\"ACRIMED\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Acrimed-ombre.png?w=285&amp;ssl=1 285w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Acrimed-ombre.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>T\\<\\\/strong\\>raitement\\<strong\\> D\\<\\\/strong\\>es\\<strong\\> N\\<\\\/strong\\>itrates\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>TDN<\/span>\\)<br\/>TH\\<\\\/strong\\>ermal\\<strong\\> O\\<\\\/strong\\>rganic\\<strong\\> R\\<\\\/strong\\>eduction\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>THOR<\/span>\\)\\<\\\/strong\\>\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Proc\u00e9d\u00e9 envisag\u00e9 par la soci\u00e9t\u00e9 AREVA pour retraiter les d\u00e9chets nitrat\u00e9s et radio\\-actifs issus de son activit\u00e9 d'enrichissement de l'uranium, phase I de la pr\u00e9paration du combustible des centrales nucl\u00e9aires\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Cette activit\u00e9 est mise en \u0153uvre dans l'usine de Malv\u00e9si \u00e0 quelques kilom\u00e8tres de Narbonne\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Ce proc\u00e9d\u00e9, potentiellement tr\u00e8s toxique pour la sant\u00e9 et l'environnement, est au centre d'une vive opposition de la part des riverains et \u00e0 laquelle le Clairon s'associe \\(\\<a href\\='https\\:\\\/\\\/le\\-clairon\\-nouveau\\.fr\\\/wordpress\\\/dossiers\\\/dossier\\-malvesi\\-areva\\\/' target\\='_blank' rel\\='noopener'\\>voir notre dossier\\<\\\/a\\> sur le sujet\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips37',tt_store_content,'3610'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>Agence Nationale pour la gestion des D\u00e9chets RAdioactifs\\<\\\/strong\\>\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Agence_nationale_pour_la_gestion_des_d%C3%A9chets_radioactifs' target\\='_blank' rel\\='noopener'\\>Voir la fiche Wikipedia de l'ANDRA\\<\\\/a\\><br\/>\\<a href\\='http\\:\\\/\\\/www\\.andra\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>Voir le site de l'agence\\<\\\/a\\>\"; toolTips('.classtoolTips79',tt_store_content,'3612'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br\/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><br\/><br\/>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>tablissement \\<strong\\>F\\<\\\/strong\\>ran\u00e7ais du \\<strong\\>S\\<\\\/strong\\>ang\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p\\>\\<a href\\='https\\:\\\/\\\/www\\.efs\\.sante\\.fr\\\/' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Acc\u00e9der ici au site de l'EFS\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips150',tt_store_content,'21261'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9pertoire \\<strong\\>N\\<\\\/strong\\>ational des \\<strong\\>A\\<\\\/strong\\>ssociations\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips159',tt_store_content,'24374'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(COR\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br\/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;<br\/><br\/>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>\\<span class\\='ILfuVd'\\>La politique agricole commune \\(\\<b\\><span class='tooltipsall tooltip_post_id_11364 classtoolTips174'>PAC<\/span>\\<\\\/b\\>\\) est une politique mise en place \u00e0 l'\u00e9chelle de l'Union europ\u00e9enne\\. \u00c0 l'origine, elle est fond\u00e9e principalement sur des mesures de contr\u00f4le des prix et de subventionnement, visant \u00e0 moderniser et d\u00e9velopper l'agriculture\\.\\<\\\/span\\> \\(source Wikipedia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips174',tt_store_content,'11364'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>H\\<\\\/strong\\>ydrocarbure \\<strong\\>A\\<\\\/strong\\>romatique \\<strong\\>P\\<\\\/strong\\>olycyclique\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Depuis de nombreuses ann\u00e9es, les <span class='tooltipsall tooltip_post_id_20397 classtoolTips184'>HAP<\/span> sont tr\u00e8s \u00e9tudi\u00e9s car ce sont des compos\u00e9s pr\u00e9sents dans tous les milieux environnementaux et qui montrent une forte toxicit\u00e9\\. On a pu \u00e9tablir la canc\u00e9rog\u00e9n\u00e8se de certains HPA, tels que le Benzo\\[a\\]anthrac\u00e8ne, le Chrys\u00e8ne et d'autres\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les HAP proviennent principalement de la combustion \u00e0 haute temp\u00e9rature \\(500\u00b0 C et plus\\) de mati\u00e8res fossiles telles que le bois, le charbon et le p\u00e9trole\\. Dans l'environnement, la production de HAP provient donc&nbsp; du chauffage domestique, de la circulation automobile, des centrales \u00e9lectriques fonctionnant au charbon ou au p\u00e9trole \\('fioul'\\), ainsi que des incin\u00e9rateurs\\.\\<\\\/p\\><br\/>\\<p\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Hydrocarbure_aromatique_polycyclique' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Voir ici l'article Wikipedia consacr\u00e9 aux HAP\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips184',tt_store_content,'20397'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br\/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<br\/><br\/>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<br\/><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br\/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_21204 classtoolTips199'>COV<\/span> \\= Compos\u00e9 Organique Volatile\\<\\\/p\\>\"; toolTips('.classtoolTips199',tt_store_content,'21204'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_24572 classtoolTips211'>MIT<\/span> \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>d\u00e9chets \u00e0 Vie Courte \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips212',tt_store_content,'19201'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br\/>ou<br\/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"<div class='tooltips_youtube_class' ><iframe width='100%' height='100%' src='http:\/\/www.youtube.com\/embed\/terawatt?rel=0&autoplay=1' frameborder='0' allowfullscreen><\/iframe><\/div>\\<p\\>\\<strong\\>TERAWATT \\(<span class='tooltipsall tooltip_post_id_30105 classtoolTips219'>TW<\/span>\\) \\= 1000 000 000 000 <span class='tooltipsall tooltip_post_id_30101 classtoolTips216'>KW<\/span>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips219',tt_store_content,'30105'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\><span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nm<\/span> \\= n\\<\\\/strong\\>ano\\<strong\\>m\\<\\\/strong\\>\u00e8tre \\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<em\\>le <span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nanom\u00e8tre<\/span>, de symbole nm, est une unit\u00e9 de longueur du Syst\u00e8me international\\. C'est un sous\\-multiple du m\u00e8tre, il vaut un milliardi\u00e8me de m\u00e8tre, soit un millioni\u00e8me de millim\u00e8tre\\.\\<\\\/em\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<em\\> 1 nm \\= 10\u207b\u00b3 \u00b5m \\= 10\\<sup\\>\u20136\\<\\\/sup\\> mm \\= 10\\<sup\\>\u20139\\<\\\/sup\\> m\\.\\<\\\/em\\>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips222',tt_store_content,'21736'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script>","protected":false},"excerpt":{"rendered":"<p>\u00c9lections pr\u00e9sidentielles Concentrons-nous sur les programmes avant de nous int\u00e9resser aux candidats Si l&rsquo;aust\u00e9rit\u00e9 permet de doper la production, la d\u00e9croissance permet de pr\u00e9server la vie Que voulons-nous ? La d\u00e9mocratie passe par le d\u00e9bat, les \u00e9bats et l&rsquo;invective an\u00e9antissent toute expression d\u00e9mocratique Huit mois pour choisir un.e pr\u00e9sident.e Huit mois de vigilance redoubl\u00e9e vis-\u00e0-visLire la suite &rarr;<script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>T\\<\\\/strong\\>raitement\\<strong\\> D\\<\\\/strong\\>es\\<strong\\> N\\<\\\/strong\\>itrates\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>TDN<\/span>\\)<br \/>TH\\<\\\/strong\\>ermal\\<strong\\> O\\<\\\/strong\\>rganic\\<strong\\> R\\<\\\/strong\\>eduction\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>THOR<\/span>\\)\\<\\\/strong\\>\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Proc\u00e9d\u00e9 envisag\u00e9 par la soci\u00e9t\u00e9 AREVA pour retraiter les d\u00e9chets nitrat\u00e9s et radio\\-actifs issus de son activit\u00e9 d'enrichissement de l'uranium, phase I de la pr\u00e9paration du combustible des centrales nucl\u00e9aires\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Cette activit\u00e9 est mise en \u0153uvre dans l'usine de Malv\u00e9si \u00e0 quelques kilom\u00e8tres de Narbonne\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Ce proc\u00e9d\u00e9, potentiellement tr\u00e8s toxique pour la sant\u00e9 et l'environnement, est au centre d'une vive opposition de la part des riverains et \u00e0 laquelle le Clairon s'associe \\(\\<a href\\='https\\:\\\/\\\/le\\-clairon\\-nouveau\\.fr\\\/wordpress\\\/dossiers\\\/dossier\\-malvesi\\-areva\\\/' target\\='_blank' rel\\='noopener'\\>voir notre dossier\\<\\\/a\\> sur le sujet\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips37',tt_store_content,'3610'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>Agence Nationale pour la gestion des D\u00e9chets RAdioactifs\\<\\\/strong\\>\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Agence_nationale_pour_la_gestion_des_d%C3%A9chets_radioactifs' target\\='_blank' rel\\='noopener'\\>Voir la fiche Wikipedia de l'<span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\<\\\/a\\><br \/>\\<a href\\='http\\:\\\/\\\/www\\.andra\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>Voir le site de l'agence\\<\\\/a\\>\"; toolTips('.classtoolTips79',tt_store_content,'3612'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br \/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><\/p>\n<p>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>tablissement \\<strong\\>F\\<\\\/strong\\>ran\u00e7ais du \\<strong\\>S\\<\\\/strong\\>ang\\<\\\/span\\>\\<\\\/p\\><br \/>\\<p\\>\\<a href\\='https\\:\\\/\\\/www\\.efs\\.sante\\.fr\\\/' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Acc\u00e9der ici au site de l'<span class='tooltipsall tooltip_post_id_21261 classtoolTips150'>EFS<\/span>\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips150',tt_store_content,'21261'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9pertoire \\<strong\\>N\\<\\\/strong\\>ational des \\<strong\\>A\\<\\\/strong\\>ssociations\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips159',tt_store_content,'24374'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br \/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>\\<span class\\='ILfuVd'\\>La politique agricole commune \\(\\<b\\><span class='tooltipsall tooltip_post_id_11364 classtoolTips174'>PAC<\/span>\\<\\\/b\\>\\) est une politique mise en place \u00e0 l'\u00e9chelle de l'Union europ\u00e9enne\\. \u00c0 l'origine, elle est fond\u00e9e principalement sur des mesures de contr\u00f4le des prix et de subventionnement, visant \u00e0 moderniser et d\u00e9velopper l'agriculture\\.\\<\\\/span\\> \\(source Wikipedia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips174',tt_store_content,'11364'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>H\\<\\\/strong\\>ydrocarbure \\<strong\\>A\\<\\\/strong\\>romatique \\<strong\\>P\\<\\\/strong\\>olycyclique\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Depuis de nombreuses ann\u00e9es, les <span class='tooltipsall tooltip_post_id_20397 classtoolTips184'>HAP<\/span> sont tr\u00e8s \u00e9tudi\u00e9s car ce sont des compos\u00e9s pr\u00e9sents dans tous les milieux environnementaux et qui montrent une forte toxicit\u00e9\\. On a pu \u00e9tablir la canc\u00e9rog\u00e9n\u00e8se de certains HPA, tels que le Benzo\\[a\\]anthrac\u00e8ne, le Chrys\u00e8ne et d'autres\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les HAP proviennent principalement de la combustion \u00e0 haute temp\u00e9rature \\(500\u00b0 C et plus\\) de mati\u00e8res fossiles telles que le bois, le charbon et le p\u00e9trole\\. Dans l'environnement, la production de HAP provient donc&nbsp; du chauffage domestique, de la circulation automobile, des centrales \u00e9lectriques fonctionnant au charbon ou au p\u00e9trole \\('fioul'\\), ainsi que des incin\u00e9rateurs\\.\\<\\\/p\\><br \/>\\<p\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Hydrocarbure_aromatique_polycyclique' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Voir ici l'article Wikipedia consacr\u00e9 aux HAP\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips184',tt_store_content,'20397'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br \/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<\/p>\n<p>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br \/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_21204 classtoolTips199'>COV<\/span> \\= Compos\u00e9 Organique Volatile\\<\\\/p\\>\"; toolTips('.classtoolTips199',tt_store_content,'21204'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_24572 classtoolTips211'>MIT<\/span> \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>d\u00e9chets \u00e0 Vie Courte \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips212',tt_store_content,'19201'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br \/>ou<br \/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"<\/p>\n<div class='tooltips_youtube_class' ><iframe width='100%' height='100%' src='http:\/\/www.youtube.com\/embed\/terawatt?rel=0&autoplay=1' frameborder='0' allowfullscreen><\/iframe><\/div>\n<p>\\<p\\>\\<strong\\>TERAWATT \\(<span class='tooltipsall tooltip_post_id_30105 classtoolTips219'>TW<\/span>\\) \\= 1000 000 000 000 <span class='tooltipsall tooltip_post_id_30101 classtoolTips216'>KW<\/span>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips219',tt_store_content,'30105'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\><span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nm<\/span> \\= n\\<\\\/strong\\>ano\\<strong\\>m\\<\\\/strong\\>\u00e8tre \\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<em\\>le <span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nanom\u00e8tre<\/span>, de symbole nm, est une unit\u00e9 de longueur du Syst\u00e8me international\\. C'est un sous\\-multiple du m\u00e8tre, il vaut un milliardi\u00e8me de m\u00e8tre, soit un millioni\u00e8me de millim\u00e8tre\\.\\<\\\/em\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<em\\> 1 nm \\= 10\u207b\u00b3 \u00b5m \\= 10\\<sup\\>\u20136\\<\\\/sup\\> mm \\= 10\\<sup\\>\u20139\\<\\\/sup\\> m\\.\\<\\\/em\\>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips222',tt_store_content,'21736'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script><\/p>\n","protected":false},"author":1,"featured_media":18234,"parent":1235,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"coauthors":[8],"class_list":["post-25184","page","type-page","status-publish","has-post-thumbnail","hentry","has-thumb"],"acf":[],"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/P9B5TM-6yc","_links":{"self":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/25184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=25184"}],"version-history":[{"count":0,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/25184\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/1235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media\/18234"}],"wp:attachment":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=25184"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/coauthors?post=25184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}