{"id":25907,"date":"2022-02-22T14:24:21","date_gmt":"2022-02-22T13:24:21","guid":{"rendered":"https:\/\/le-clairon-nouveau.fr\/wordpress\/?page_id=25907"},"modified":"2022-02-23T10:01:11","modified_gmt":"2022-02-23T09:01:11","slug":"unes-edition-84","status":"publish","type":"page","link":"https:\/\/le-clairon-nouveau.fr\/wordpress\/unes\/unes-edition-84\/","title":{"rendered":"\u00c9dition n\u00b0 84 &#8211; F\u00e9vrier \/ Mars 2022"},"content":{"rendered":"<div id=\"pl-25907\"  class=\"panel-layout\" ><div id=\"pg-25907-0\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-25907-0\" ><div id=\"pgc-25907-0-0\"  class=\"panel-grid-cell\" ><div class=\"panel-cell-style panel-cell-style-for-25907-0-0\" ><div id=\"panel-25907-0-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"panel-widget-style panel-widget-style-for-25907-0-0-0\" ><div id=\"pl-w6215f7d7bfc1f\"  class=\"panel-layout\" ><div id=\"pg-w6215f7d7bfc1f-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w6215f7d7bfc1f-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w6215f7d7bfc1f-0-0-0\" class=\"so-panel widget widget_sow-hero panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-hero so-widget-sow-hero-default-b7fc812a4403 so-widget-fittext-wrapper\"\n\t\t\t data-fit-text-compressor=\"2.5\"\n\t\t>\t\t\t\t<div class=\"sow-slider-base\" style=\"display: none\" tabindex=\"0\">\n\t\t\t\t\t<ul\n\t\t\t\t\tclass=\"sow-slider-images\"\n\t\t\t\t\tdata-settings=\"{&quot;pagination&quot;:true,&quot;speed&quot;:1200,&quot;timeout&quot;:10000,&quot;paused&quot;:false,&quot;pause_on_hover&quot;:true,&quot;swipe&quot;:true,&quot;nav_always_show_desktop&quot;:&quot;&quot;,&quot;nav_always_show_mobile&quot;:&quot;&quot;,&quot;breakpoint&quot;:&quot;780px&quot;,&quot;unmute&quot;:false,&quot;anchor&quot;:null}\"\n\t\t\t\t\tstyle=\"min-height: 200px\"\t\t\t\t\tdata-anchor-id=\"\"\n\t\t\t\t>\t\t<li class=\"sow-slider-image\" style=\"visibility: visible;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">Quel avenir souhaitez-vous pour votre pays ?<br \/>\nQuelle candidature repr\u00e9sente le mieux cet avenir ?<\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">Un candidat qui raisonne en termes d\u2019amis\/ennemis<br \/>\npr\u00e9pare la guerre de tous contre tous<\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\"><strong>Pour d\u00e9cider de votre vote, quelle est votre source d'informations privil\u00e9gi\u00e9e :<br \/>\nles (d)\u00e9bats radio \/ t\u00e9l\u00e9vis\u00e9s, la presse \u00e9crite ou les programmes des candidats ?<\/strong><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">Un candidat qui privil\u00e9gie la d\u00e9nonciation de ses adversaires<br \/>\nn'a peut-\u00eatre pas grand'chose \u00e0 proposer<\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">Reconduire Macron pr\u00e9sident, c\u2019est prendre le risque<br \/>\nde le conforter dans ses certitudes<br \/>\net de renforcer sa gestion autocratique de l'\u00c9tat<\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">Le don de sang reste une priorit\u00e9 quotidienne pour nos services de sant\u00e9<\/h2>\n<div class=\"sow-hero-buttons\" style=\"text-align: center\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-atom-b98bfa6330fe\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-center\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/dondesang.efs.sante.fr\/trouver-une-collecte\"\n\t\t\t\t\tclass=\"sowb-button ow-icon-placement-left ow-button-hover\" target=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\t<span>\n\t\t\t\n\t\t\tVoir les prochaines collectes\t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t<\/ul>\t\t\t\t<ol class=\"sow-slider-pagination\">\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"0\" aria-label=\"Display slide 1\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"1\" aria-label=\"Display slide 2\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"2\" aria-label=\"Display slide 3\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"3\" aria-label=\"Display slide 4\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"4\" aria-label=\"Display slide 5\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"5\" aria-label=\"Display slide 6\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-next\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"next\" aria-label=\"Next slide\" data-action=\"next\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-right\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-prev\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"previous\" aria-label=\"Previous slide\" data-action=\"prev\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-left\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w6215f7d7bfc1f-1\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-w6215f7d7bfc1f-1\" ><div id=\"pgc-w6215f7d7bfc1f-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w6215f7d7bfc1f-1-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"panel-widget-style panel-widget-style-for-w6215f7d7bfc1f-1-0-0\" ><div class=\"textwidget\"><p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><em>Publicit\u00e9 Citoyenne<\/em><\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-25907-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-25907-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-25907-1-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"textwidget\"><p style=\"text-align: center;\"><span id=\"textillate-zbyist\"><span style=\"visibility: hidden;\"><span class=\"tlt-texts\" style=\"display:none;\"><br \/>\n<span data-in-delay=\"50\" data-out-delay=\"50\" data-in-effect=\"flipInY\" data-in-sync=\"true\" data-out-effect=\"flipOutY\" data-out-sync=\"true\"><span style=\"color: #000000;\">A titre temporaire, seuls les articles \u00e0 compter de d\u00e9cembre 2019 (\u00e9dition n\u00b0 60) sont disponibles<\/span><\/span> <br \/>\n<span data-in-delay=\"50\" data-out-delay=\"50\" data-in-effect=\"flipInY\" data-in-sync=\"true\" data-out-effect=\"flipOutY\" data-out-sync=\"true\"><span style=\"color: #520000;\">Nous vous tiendrons r\u00e9guli\u00e8rement inform\u00e9.e.s de la republication des articles des \u00e9ditions pr\u00e9c\u00e9dentes<\/span> <\/span> <br \/>\n<\/span>&nbsp;<\/span><\/span><\/p>\n<\/div><\/div><\/div><\/div><div id=\"pg-25907-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-25907-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-25907-2-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child\" data-index=\"2\" ><div class=\"panel-widget-style panel-widget-style-for-25907-2-0-0\" ><div class=\"textwidget\"><h3 style=\"text-align: center;\"><span style=\"color: #8f4511;\">\u00c9ditorial<\/span><\/h3>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-post-border pt-cv-justify pt-cv-reused\" id=\"pt-cv-view-a2290f1fn4\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25911\"><div class='pt-cv-ifield'><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/le-vote-est-fait-avant-les-elections\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd\" target=\"_self\" ><img decoding=\"async\" width=\"300\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/Le-projet-de-Trump-cest-Trump.jpg?resize=504%2C390&amp;ssl=1\" class=\"pt-cv-thumbnail img-rounded cvp-substitute no-lazyload \" alt=\"Le vote est fait avant les \u00e9lections\" title=\"\" data-no-lazy=\"1\" \/><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/le-vote-est-fait-avant-les-elections\/\" class=\"_self cvplbd\" target=\"_self\" >Le vote est fait avant les \u00e9lections<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/hubert\/\" rel=\"author\">Hubert Reys<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2022-02-23T12:30:54+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">R\u00e9tablir une pleine d\u00e9mocratie de repr\u00e9sentation et d\u2019exercice conditionne la r\u00e9ussite de tous nos projets de lutte contre le changement climatique et environnemental ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/le-vote-est-fait-avant-les-elections\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-06df93e9zb\">#pt-cv-view-a2290f1fn4.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-a2290f1fn4.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-a2290f1fn4 .pt-cv-title a, #pt-cv-view-a2290f1fn4  .panel-title { font-size: 18px !important; line-height: 1.3 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-content , #pt-cv-view-a2290f1fn4  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-a2290f1fn4  .pt-cv-hover-wrapper::before   { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-a2290f1fn4:not(.pt-cv-nohover) .pt-cv-mask *   { color: #fff; }\n#pt-cv-view-a2290f1fn4 .pt-cv-carousel-caption  { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-specialp { background-color: #CC3333 !important }\n#pt-cv-view-a2290f1fn4 .pt-cv-specialp * { color: #fff !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-pficon  { color: #bbb !important; }\n#pt-cv-view-a2290f1fn4  .add_to_cart_button, #pt-cv-view-a2290f1fn4  .add_to_cart_button *   { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-a2290f1fn4  .woocommerce-onsale   { color: #ffffff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-a2290f1fn4  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-a2290f1fn4  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-a2290f1fn4'] .active.pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .active .pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .selected.pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .dropdown-toggle   { color: #fff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-a2290f1fn4'] .pt-cv-filter-title   { color: #fff !important; background-color: #00aeef !important; }\n#pt-cv-gls-a2290f1fn4 li a   { font-weight: 600 !important; }\n#pt-cv-gls-a2290f1fn4 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-gls-header  { background-color: #00aeef !important; }\n#pt-cv-view-a2290f1fn4 .img-rounded, #pt-cv-view-a2290f1fn4 .pt-cv-hover-wrapper { -webkit-border-radius: 3px !important; -moz-border-radius: 3px !important; border-radius: 3px !important; }\n#pt-cv-view-a2290f1fn4 { text-align: justify; }<\/style>\r\n\t\t\t <br><\/p>\n<\/div><\/div><\/div><div id=\"panel-25907-2-0-1\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-last-child\" data-index=\"3\" ><div class=\"panel-widget-style panel-widget-style-for-25907-2-0-1\" ><div class=\"textwidget\"><h3 style=\"text-align: center;\"><span style=\"color: #993300;\">Ils ont contribu\u00e9 \u00e0 cette \u00e9dition<\/span><\/h3>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-reused\" id=\"pt-cv-view-edf64eb5yg\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25896\"><div class='pt-cv-ifield'><div class=\"pt-cv-content\"><p><strong><span style=\"color: #3366ff\">Articles<\/span><br \/>\n<\/strong><\/p>\n<p>Catherine Burger (Aude)<br \/>\nAlbert Cormary pour <span class='tooltipsall tooltip_post_id_7258 classtoolTips84'>SDN11<\/span> (Aude)<br \/>\nJardinaude (Aude)<br \/>\nL\u2019appelou (Aude)<br \/>\nLaurent Fabas (Aude))<br \/>\nSophie Masini (Alsace)<br \/>\nPatricia Renaud (Savoie)<br \/>\nA.Gisselbrecht\u00a0 (Alsace)<br \/>\nHubert Reys (Aude)<br \/>\nCurly Mac Toole (Paris)<br \/>\nLouise B. Velpeau (Aude)<br \/>\nColette Vexenat (Aude)<br \/>\nLena Waag (H\u00e9rault \/ Alsace)<\/p>\n<p><span style=\"color: #3366ff;font-size: 14pt\"><strong>R\u00e9daction, Edition, Publication\u00a0:<\/strong><\/span><\/p>\n<p>Jean Cordier<br \/>\nHubert Reys<\/p>\n<p><span style=\"font-size: 14pt;color: #3366ff\"><strong>Coach\u00a0:<\/strong><\/span><\/p>\n<p>Dundee\u00a0 <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-23450\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur.jpg?resize=32%2C48&#038;ssl=1\" alt=\"\" width=\"32\" height=\"48\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=201%2C300&amp;ssl=1 201w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=685%2C1024&amp;ssl=1 685w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=768%2C1147&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=1028%2C1536&amp;ssl=1 1028w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=1371%2C2048&amp;ssl=1 1371w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?w=1714&amp;ssl=1 1714w\" sizes=\"auto, (max-width: 32px) 100vw, 32px\" \/> : L\u2019avenir appartient \u00e0 celui dont le chien se l\u00e8ve t\u00f4t<\/p>\n<p>&nbsp;<\/p>\n<script type=\"text\/javascript\"> var tt_store_content = \"Sortir du nucl\u00e9aire Aude\"; toolTips('.classtoolTips84',tt_store_content,'7258'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<\/a><a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/span><\/a><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<\/a><a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/span><\/a><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/p><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br \/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<br \/><br \/>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<br \/><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br \/>\\<\/a><a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/a><\/span><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/span><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/a><\/sup><\/a><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/a><\/sup><\/a><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/span><\/p><\/script><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-37a9464shv\">#pt-cv-view-edf64eb5yg.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-edf64eb5yg.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-edf64eb5yg .pt-cv-title a, #pt-cv-view-edf64eb5yg  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-content , #pt-cv-view-edf64eb5yg  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-readmore  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-edf64eb5yg  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-edf64eb5yg  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-edf64eb5yg li a   { font-weight: 600 !important; }\n#pt-cv-gls-edf64eb5yg li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t <br><\/p>\n<\/div><\/div><\/div><\/div><div id=\"pgc-25907-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-25907-2-1-0\" class=\"so-panel widget widget_ink-tabs panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"panel-widget-style panel-widget-style-for-25907-2-1-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-ink-tabs so-widget-ink-tabs-tabs-668eb67c20e6-25907\"\n\t\t\t\n\t\t>\n<div class=\"iw-so-tabs iw-so-tabs-horizontal iw-so-tabs-fullwidth\">\n\n\t<ul class=\"iw-so-tabs-nav\">\n\n\t\t\t\t\t<li class=\"iw-so-tab-title iw-so-tab-active\" id=\"ink-tabs-828010003-1\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-1-content\">\n\t\t\t\t\t<span class=\"sow-icon-icomoon\" data-sow-icon=\"&#xe904;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Actualit\u00e9s<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-2\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-2-content\">\n\t\t\t\t\t<span class=\"sow-icon-icomoon\" data-sow-icon=\"&#xe92e;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Culture et Art de Vivre<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-3\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-3-content\">\n\t\t\t\t\t<span class=\"sow-icon-icomoon\" data-sow-icon=\"&#xe921;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Changer les Institutions<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-4\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-4-content\">\n\t\t\t\t\t<span class=\"sow-icon-icomoon\" data-sow-icon=\"&#xea84;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Expression Libre<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\n\t<\/ul>\n\n\t<div class=\"iw-so-tabs-content\">\n\n\t\t\t\t\t<div class=\"iw-so-tabs-panel iw-so-tab-active\" id=\"ink-tabs-828010003-1-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-54904956ml\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25879\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/accaparement-massif-de-leau-un-communique-de-la-confederation-paysanne\/\" class=\"_self cvplbd\" target=\"_self\" >Accaparement massif de l&rsquo;eau : un communiqu\u00e9 de la Conf\u00e9d\u00e9ration Paysanne<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/accaparement-massif-de-leau-un-communique-de-la-confederation-paysanne\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Accaparement massif de l&#039;eau : un communiqu\u00e9 de la Conf\u00e9d\u00e9ration Paysanne\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/LOGO-CP11.png?resize=494%2C178&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Le 17 f\u00e9vrier 2022 Communiqu\u00e9 de presse M\u00e9ga-bassines Audition comme mis en cause du porte-parole national Nicolas Girod Le porte-parole national de la Conf\u00e9d\u00e9ration paysanne est convoqu\u00e9 ce jeudi 17 f\u00e9vrier \u00e0 9h \u00e0 la gendarmerie de Salins-les-Bains dans le Jura, dans le cadre d&rsquo;une audition comme mis en cause pour vol aggrav\u00e9 suite au d\u00e9montage de la pompe de la bassine de Cram-Chaban lors de la mobilisation du 6 ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/accaparement-massif-de-leau-un-communique-de-la-confederation-paysanne\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:55+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25889\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/relance-du-nucleaire-par-macron-la-reaction-de-sdn-11\/\" class=\"_self cvplbd\" target=\"_self\" >Relance du nucl\u00e9aire par Macron : La r\u00e9action de SDN 11<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/relance-du-nucleaire-par-macron-la-reaction-de-sdn-11\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Relance du nucl\u00e9aire par Macron : La r\u00e9action de SDN 11\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/Presentation1.jpg?resize=604%2C135&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">La relance du nucl\u00e9aire annonc\u00e9e par E. Macron le 10 f\u00e9vrier dernier a soulev\u00e9 beaucoup de r\u00e9actions. Comment un sujet aussi crucial peut-il \u00eatre trait\u00e9 avec autant de d\u00e9sinvolture et sans d\u00e9bat\u00a0? Voici la r\u00e9action de Sortir du Nucl\u00e9aire 11 La r\u00e9daction du Clairon \u00a0\u00a0 \u00a0\u00a0\u00a0 Alors que la campagne pour les pr\u00e9sidentielles s\u2019acc\u00e9l\u00e8re, le pr\u00e9sident-pas-encore-candidat (au moment o\u00f9 <span class='tooltipsall tooltip_post_id_29829 classtoolTips180'>ces<\/span> lignes sont \u00e9crites) nous a promis un avenir \u00e9nerg\u00e9tique radieux ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/relance-du-nucleaire-par-macron-la-reaction-de-sdn-11\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/albert\/\" rel=\"author\">Albert Cormary<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:46+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25855\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/en-savoir-plus-sur-les-abeilles-une-conference-organisee-par-jardinaude\/\" class=\"_self cvplbd\" target=\"_self\" >En savoir plus sur les abeilles : une conf\u00e9rence organis\u00e9e par Jardinaude<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/en-savoir-plus-sur-les-abeilles-une-conference-organisee-par-jardinaude\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container cvp-block\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"En savoir plus sur les abeilles : une conf\u00e9rence organis\u00e9e par Jardinaude\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/Jardinaude.jpg?resize=481%2C85&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Le d\u00e9clin des populations d\u2019insectes est vraiment inqui\u00e9tant\u2026 S\u2019ajoutant \u00e0 la mortalit\u00e9 cr\u00e9\u00e9e par les pr\u00e9dateurs (frelon asiatique, varroa\u2026) les probl\u00e8mes provoqu\u00e9s par les traitements chimiques (insecticides, fongicides\u2026) des c\u00e9r\u00e9ales, vignes, vergers\u2026 sont autrement plus graves pour la population d\u2019insectes sauvages. \u00ab Les n\u00e9onicotino\u00efdes en particulier se lient aux r\u00e9cepteurs qui se retrouvent sur les neurones de leur syst\u00e8me nerveux central . Leur suractivation g\u00e9n\u00e8re un blocage qui engendre une paralysie mortelle. \u00bb ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/en-savoir-plus-sur-les-abeilles-une-conference-organisee-par-jardinaude\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:28+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25839\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/a-propos-de-laberrante-relance-du-nucleaire-par-e-macron\/\" class=\"_self cvplbd\" target=\"_self\" >A PROPOS DE L\u2019ABERRANTE RELANCE DU NUCL\u00c9AIRE PAR E.MACRON<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/a-propos-de-laberrante-relance-du-nucleaire-par-e-macron\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container cvp-block\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"A PROPOS DE L\u2019ABERRANTE RELANCE DU NUCL\u00c9AIRE PAR E.MACRON\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/startup-nation.-image-Gerd-Altmann-de-Pixabay.png?resize=593%2C265&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Comment d\u00e9cider d\u2019un sujet aussi crucial que l'avenir \u00e9nerg\u00e9tique de la France dans un contexte de crise climatique sans l\u2019avoir soumis pr\u00e9alablement \u00e0 un d\u00e9bat public ?  ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/a-propos-de-laberrante-relance-du-nucleaire-par-e-macron\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/curly\/\" rel=\"author\">Curly Mc Toole<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:21+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25822\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/liberalisme-un-mot-employe-actuellement-a-toutes-les-sauces\/\" class=\"_self cvplbd\" target=\"_self\" >Lib\u00e9ralisme : un mot employ\u00e9 actuellement \u00e0 toutes les sauces<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/liberalisme-un-mot-employe-actuellement-a-toutes-les-sauces\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Lib\u00e9ralisme : un mot employ\u00e9 actuellement \u00e0 toutes les sauces\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/refugies-solidarite-image-Peggy-Marco-Pixabay-1.jpg?resize=503%2C433&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Cessons de mettre en cause le lib\u00e9ralisme \u00e0 mauvais escient. Nous faisons le lit des d\u00e9magogues extr\u00e9mistes. D\u00e9battons plut\u00f4t sur le vrai sujet : Le Capitalisme financier.   ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/liberalisme-un-mot-employe-actuellement-a-toutes-les-sauces\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/laurent\/\" rel=\"author\">Laurent Fabas<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:16+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-54a95bevk9\">#pt-cv-view-54904956ml  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-54904956ml.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-54904956ml.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-54904956ml.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-54904956ml .pt-cv-title a, #pt-cv-view-54904956ml  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-54904956ml  .pt-cv-title a:hover, #pt-cv-view-54904956ml  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-54904956ml .pt-cv-content , #pt-cv-view-54904956ml  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-54904956ml  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-54904956ml .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-54904956ml .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-54904956ml .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-54904956ml  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-54904956ml  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-54904956ml li a   { font-weight: 600 !important; }\n#pt-cv-gls-54904956ml li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><br \/>\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#be8552;border-radius:10px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:#f1b885;color:#88360d;border-top-left-radius:8px;border-top-right-radius:8px\">Les Br\u00e8ves du mois<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:8px;border-bottom-right-radius:8px\"><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-scrollable pt-cv-colsys pt-cv-nolf pt-cv-reused\" id=\"pt-cv-view-176b9dand1\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page cv-npf\" data-cvc=\"3\"><div id=\"136de9fcks\" class=\"pt-cv-carousel pt-cv-slide\" data-ride=\"cvcarousel\" data-interval=5000>\n<div class=\"carousel-inner\"><div class=\"item active\"><div class=\"row\"><div class=\"col-md-4 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"0\"><div class=\"pt-cv-no-post\">Aucune publication trouv\u00e9e.<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-c1a0558s6x\">#pt-cv-view-176b9dand1 .pt-cv-content-item { padding-left: 5px !important; padding-right: 5px !important; }\n#pt-cv-view-176b9dand1  { margin-left: -5px !important; margin-right: -5px !important; }\n#pt-cv-view-176b9dand1 .pt-cv-carousel-caption { padding-top: 0px !important; padding-left: 0px !important; padding-bottom: 5px !important; padding-right: 0px !important; }\n#pt-cv-view-176b9dand1 .pt-cv-carousel-caption { left : 5px !important }\n#pt-cv-view-176b9dand1 .carousel-control.left { right : 40px }\n#pt-cv-view-176b9dand1 .pt-cv-carousel-caption { right : 5px !important }\n#pt-cv-view-176b9dand1 .carousel-control.right { right : 5px }\n#pt-cv-view-176b9dand1 .row {margin: 0 0 !important}\n#pt-cv-view-176b9dand1  .pt-cv-carousel-caption   { background-color: rgba(234,212,86,0.2) !important; }\n#pt-cv-view-176b9dand1.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-176b9dand1.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-176b9dand1.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-176b9dand1 .pt-cv-title a, #pt-cv-view-176b9dand1  .panel-title { font-family: 'Nunito', Arial, serif !important; font-size: 14px !important; color: #cc2e2e !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-176b9dand1  .pt-cv-title a:hover, #pt-cv-view-176b9dand1  .panel-title:hover   { color: rgba(204,46,46,0.41) !important; }\n#pt-cv-view-176b9dand1 .pt-cv-content , #pt-cv-view-176b9dand1  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 12px !important; line-height: 1.3 !important; }\n#pt-cv-view-176b9dand1  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(214,214,214,0.77) !important; }\n#pt-cv-view-176b9dand1 .pt-cv-meta-fields * { font-size: 12px !important; line-height: 1.3 !important; }\n#pt-cv-view-176b9dand1 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-176b9dand1 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-176b9dand1  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-176b9dand1  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-176b9dand1 li a   { font-weight: 600 !important; }\n#pt-cv-gls-176b9dand1 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Nunito' rel='stylesheet' type='text\/css'> <br><\/div><\/div><br \/>\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#be8552;border-radius:10px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:#f1b885;color:#88360d;border-top-left-radius:8px;border-top-right-radius:8px\">La chronique des Successeurs<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:8px;border-bottom-right-radius:8px\"><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-reused\" id=\"pt-cv-view-8d96c5df5a\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"25845\"><div class='pt-cv-ifield'><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/make-our-planet-great-again\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-left cvplbd\" target=\"_self\" ><img decoding=\"async\" width=\"300\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/09\/La-chronique-des-successeurs.jpg?resize=226%2C61&amp;ssl=1\" class=\"pt-cv-thumbnail img-none pull-left cvp-substitute no-lazyload \" alt=\"\u00ab Make our planet great again \u00bb\" title=\"\" data-no-lazy=\"1\" \/><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/make-our-planet-great-again\/\" class=\"_self cvplbd\" target=\"_self\" >\u00ab Make our planet great again \u00bb<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/lenaw\/\" rel=\"author\">Lena Waag<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2022-02-23T12:30:17+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">La plan\u00e8te bleue et sa lune (image Arek Socha de Pixabay) En d\u00e9tournant le slogan de campagne de Donald Trump, Emmanuel Macron s\u2019\u00e9tait assur\u00e9 un succ\u00e8s \u00e9norme sur les r\u00e9seaux sociaux. \u00ab\u00a0Le climat doit \u00eatre au c\u0153ur du projet national et europ\u00e9en\u00a0\u00bb avait-il dit. On y croyait presque. Mais que s\u2019est-il r\u00e9ellement pass\u00e9 ces derni\u00e8res ann\u00e9es ? On sait le sabotage de la loi climat par les Lobbies et le gouvernement, et les propositions avort\u00e9es de la convention citoyenne qui avait pourtant pr\u00e9vu un ensemble de mesures coh\u00e9rent et complet. Ces m\u00eames Lobbies avaient aussi pouss\u00e9 \u00e0 la d\u00e9mission Nicolas Hulot, alors ministre de la transition \u00e9cologique. Le 15 d\u00e9cembre 2021, notre pr\u00e9sident dressait son bilan pendant 2h sur tf1, et ni lui ni les journalistes qui l\u2019interrogeaient n\u2019ont jug\u00e9 bon de dire un mot (ou plusieurs) sur l\u2019\u00e9cologie. Motus\u00a0!! Rappelons que la France s\u2019\u00e9tait engag\u00e9e, en alignement avec l\u2019accord de Paris, \u00e0 r\u00e9duire nos \u00e9missions de gaz \u00e0 effet de serre de 40% d\u2019ici \u00e0 2030. La r\u00e9alit\u00e9 est toute autre\u00a0: le gouvernement a revu \u00e0 la baisse ses ambitions pour la p\u00e9riode 2019-2023. Le nouvel objectif est de 1,5% de r\u00e9duction annuelle au lieu des 2,3% initiaux. Il ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/make-our-planet-great-again\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-b91456aswj\">#pt-cv-view-8d96c5df5a  .pt-cv-ifield   { background-color: rgba(234,212,86,0.2) !important; }\n#pt-cv-view-8d96c5df5a.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-8d96c5df5a.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-8d96c5df5a.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-8d96c5df5a .pt-cv-title a, #pt-cv-view-8d96c5df5a  .panel-title { color: #cc2e2e !important; font-weight: 600 !important; }\n#pt-cv-view-8d96c5df5a  .pt-cv-title a:hover, #pt-cv-view-8d96c5df5a  .panel-title:hover   { color: rgba(204,46,46,0.41) !important; }\n#pt-cv-view-8d96c5df5a .pt-cv-content , #pt-cv-view-8d96c5df5a  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-8d96c5df5a .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-8d96c5df5a .pt-cv-readmore:hover  { color: #ff413a !important; font-weight: 600 !important; }\n#pt-cv-view-8d96c5df5a  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-8d96c5df5a  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-8d96c5df5a li a   { font-weight: 600 !important; }\n#pt-cv-gls-8d96c5df5a li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t <br><\/div><\/div><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-2-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-0a21f34gl7\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25818\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/essai-sur-les-hommes-de-la-terreur\/\" class=\"_self cvplbd\" target=\"_self\" >ESSAI SUR LES HOMMES DE LA TERREUR<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/essai-sur-les-hommes-de-la-terreur\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"ESSAI SUR LES HOMMES DE LA TERREUR\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/IMG_20220216_174302.jpg?resize=263%2C413&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Traduit de l\u2019allemand par Daniel Mirsky ; folio 2016 Image H.Reys En France, les proc\u00e8s actuels des terroristes du 13 novembre 2015 et de l\u2019attentat de Saint-\u00c9tienne-du-Rouvray nous rappellent cette question lancinante\u00a0: qu\u2019est ce qui se passe dans la t\u00eate d\u2019un individu pour que soudain \u00ab\u00a0il p\u00e8te les plombs\u00a0\u00bb et devient un tueur de masse qui tue en continu dans un court laps de temps, tout en semblant d\u00e9nu\u00e9 de ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/essai-sur-les-hommes-de-la-terreur\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:56+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25855\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/en-savoir-plus-sur-les-abeilles-une-conference-organisee-par-jardinaude\/\" class=\"_self cvplbd\" target=\"_self\" >En savoir plus sur les abeilles : une conf\u00e9rence organis\u00e9e par Jardinaude<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/en-savoir-plus-sur-les-abeilles-une-conference-organisee-par-jardinaude\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container cvp-block\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"En savoir plus sur les abeilles : une conf\u00e9rence organis\u00e9e par Jardinaude\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/Jardinaude.jpg?resize=481%2C85&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Le d\u00e9clin des populations d\u2019insectes est vraiment inqui\u00e9tant\u2026 S\u2019ajoutant \u00e0 la mortalit\u00e9 cr\u00e9\u00e9e par les pr\u00e9dateurs (frelon asiatique, varroa\u2026) les probl\u00e8mes provoqu\u00e9s par les traitements chimiques (insecticides, fongicides\u2026) des c\u00e9r\u00e9ales, vignes, vergers\u2026 sont autrement plus graves pour la population d\u2019insectes sauvages. \u00ab Les n\u00e9onicotino\u00efdes en particulier se lient aux r\u00e9cepteurs qui se retrouvent sur les neurones de leur syst\u00e8me nerveux central . Leur suractivation g\u00e9n\u00e8re un blocage qui engendre une paralysie mortelle. \u00bb ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/en-savoir-plus-sur-les-abeilles-une-conference-organisee-par-jardinaude\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:28+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25829\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/enquete-sur-un-scandale-detat\/\" class=\"_self cvplbd\" target=\"_self\" >Enqu\u00eate sur un scandale d&rsquo;Etat<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/enquete-sur-un-scandale-detat\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Enqu\u00eate sur un scandale d&#039;Etat\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/mysterious-gangster-image-Sammy-Sander-de-Pixabay.jpg?resize=458%2C305&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">France \u2013 2h03 \u2013 2021 Un film de Thierry de Peretti avec Roschdy Zem, Vincent Lindon, Pio Marma\u00ef. mysterious gangster &#8211; image Sammy-Sander de Pixabay En octobre 2015, 7 tonnes de cannabis sont saisies en plein Paris. Les politiques sont ravis et totalement fiers de cette r\u00e9ussite, mais dans le m\u00eame temps Hubert Antoine (Roschdy Zem) contacte un jeune journaliste \u00e0 Lib\u00e9ration St\u00e9phane Vilner (Pio Marma\u00ef) et lui annonce l&rsquo;existence ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/enquete-sur-un-scandale-detat\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/patren\/\" rel=\"author\">Patricia Renaud<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:51+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25833\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/les-promesses\/\" class=\"_self cvplbd\" target=\"_self\" >Les promesses<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/les-promesses\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Les promesses\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/Cite-image-Robertprax-Pixabay.jpg?resize=384%2C255&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">France \u2013 1h38 \u2013 2021 Un film de Thomas Kruithof avec Isabelle Huppert, Reda Kateb, Naidra Ayadi Des promesses, des promesses, encore et toujours des promesses ! Cit\u00e9 image robertprax Pixabay Ah !\u00a0 L&rsquo;ivresse du pouvoir quand tu nous tiens ! Cl\u00e9mence (Isabelle Huppert), maire d&rsquo;une commune du 9-3 est pr\u00eate \u00e0 rendre son tablier aux prochaines municipales mais pas sans avoir men\u00e9 \u00e0 bien son dernier projet : la ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/les-promesses\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/patren\/\" rel=\"author\">Patricia Renaud<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:21+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25874\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/une-recette-de-gateau-aux-carottes\/\" class=\"_self cvplbd\" target=\"_self\" >Une recette de g\u00e2teau aux carottes<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/une-recette-de-gateau-aux-carottes\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Une recette de g\u00e2teau aux carottes\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/Carott-cake-1.jpg?resize=510%2C257&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">A priori cela \u00e9tonne\u00a0: faire une g\u00e2teau aux carottes quelle id\u00e9e\u00a0! Et puis en cherchant on s\u2019aper\u00e7oit qu\u2019en version anglo-saxonne le Carrot cake fait un v\u00e9ritable tabac, particuli\u00e8rement aux USA o\u00f9 il est accommod\u00e9 \u00e0 toutes les cr\u00e8mes. Il parait qu\u2019en fait son origine serait Suisse ! Photo H.R. Ingr\u00e9dients\u00a0: 200 gr de carottes r\u00e2p\u00e9es (env. 3 belles carottes)\u00a0; 2 \u0153ufs entiers\u00a0; 200 gr de sucre\u00a0; 150 gr de farine\u00a0; ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/une-recette-de-gateau-aux-carottes\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/catburg\/\" rel=\"author\">Catherine Burger<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:37+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25899\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/parfums\/\" class=\"_self cvplbd\" target=\"_self\" >PARFUMS<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/parfums\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"PARFUMS\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/Peyriac-84.jpg?resize=515%2C386&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Peyriac de mer photo PB Sur l\u2019orgue \u00e0 parfums de mon enfance Mon nez s\u2019envole au gr\u00e9 des fragrances Avant que ce monde ne l\u2019engloutisse Dans une anosmie en pr\u00e9cipice Sur la petite table blanche en formica Dansent les premi\u00e8res asperges du march\u00e9 Des blettes, un chou-fleur en bouquet Petits pois et carottes barbotent dans le plat Sous le soleil d\u00e9j\u00e0 fier Se d\u00e9ploie le printemps O\u00f9 je courais enfant ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/parfums\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:12+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-ffca3ecgko\">#pt-cv-view-0a21f34gl7  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-0a21f34gl7.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-0a21f34gl7.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-0a21f34gl7.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-0a21f34gl7 .pt-cv-title a, #pt-cv-view-0a21f34gl7  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-0a21f34gl7  .pt-cv-title a:hover, #pt-cv-view-0a21f34gl7  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-content , #pt-cv-view-0a21f34gl7  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-0a21f34gl7  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-0a21f34gl7  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-0a21f34gl7  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-0a21f34gl7 li a   { font-weight: 600 !important; }\n#pt-cv-gls-0a21f34gl7 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-3-content\">\n\t\t\t\t<p style=\"text-align: justify; color: #966400; font-size: 85%;\"><em>Cette rubrique, cr\u00e9\u00e9e en Novembre 2021 \u00e0 l'occasion de la campagne 2022 pour l'\u00e9lection du Pr\u00e9sident de la R\u00e9publique Fran\u00e7aise, vous propose des articles visant \u00e0 nourrir la r\u00e9flexion et l'engagement sur un n\u00e9cessaire changement de nos institutions politiques.&nbsp;<br \/>\n<\/em><\/p>\n<p style=\"text-align: justify; color: #966400; font-size: 85%;\"><em>Vous trouverez ici les articles de l'\u00e9dition en cours. Pour retrouver l'ensemble des articles parus au fil des diff\u00e9rentes \u00e9ditions, veuillez vous rendre <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/pages-visibles\/dossiers\/changer-institutions-politiques\/\">dans le dossier correspondant<\/a>.<\/em><\/p>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-48ee47btyo\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"25822\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/liberalisme-un-mot-employe-actuellement-a-toutes-les-sauces\/\" class=\"_self cvplbd\" target=\"_self\" >Lib\u00e9ralisme : un mot employ\u00e9 actuellement \u00e0 toutes les sauces<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/liberalisme-un-mot-employe-actuellement-a-toutes-les-sauces\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Lib\u00e9ralisme : un mot employ\u00e9 actuellement \u00e0 toutes les sauces\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/02\/refugies-solidarite-image-Peggy-Marco-Pixabay-1.jpg?resize=503%2C433&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Cessons de mettre en cause le lib\u00e9ralisme \u00e0 mauvais escient. Nous faisons le lit des d\u00e9magogues extr\u00e9mistes. D\u00e9battons plut\u00f4t sur le vrai sujet : Le Capitalisme financier.   ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/02\/23\/liberalisme-un-mot-employe-actuellement-a-toutes-les-sauces\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/laurent\/\" rel=\"author\">Laurent Fabas<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2022-02-23T12:30:16+01:00\">23 f\u00e9vrier 2022<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-cde455bln9\">#pt-cv-view-48ee47btyo  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-48ee47btyo.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-48ee47btyo.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-48ee47btyo.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-48ee47btyo .pt-cv-title a, #pt-cv-view-48ee47btyo  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-48ee47btyo  .pt-cv-title a:hover, #pt-cv-view-48ee47btyo  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-48ee47btyo .pt-cv-content , #pt-cv-view-48ee47btyo  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-48ee47btyo  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-48ee47btyo .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-48ee47btyo .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-48ee47btyo .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-48ee47btyo  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-48ee47btyo  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-48ee47btyo li a   { font-weight: 600 !important; }\n#pt-cv-gls-48ee47btyo li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-4-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-post-border pt-cv-reused\" id=\"pt-cv-view-8090fb6z9g\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page cv-npf\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"0\"><div class='pt-cv-ifield'><div class=\"pt-cv-no-post\">Aucune publication trouv\u00e9e.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-e79452d3kf\">#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-color: #ede0ce; border-left-color: #ede0ce }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; border-right-color: #ede0ce; border-bottom-color: #ede0ce; }\n#pt-cv-view-8090fb6z9g .pt-cv-title a, #pt-cv-view-8090fb6z9g  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-8090fb6z9g  .pt-cv-hover-wrapper::before   { background-color: rgba(0,0,0,.3) !important; }\n#pt-cv-view-8090fb6z9g  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-8090fb6z9g:not(.pt-cv-nohover) .pt-cv-mask *   { color: #fff; }\n#pt-cv-view-8090fb6z9g .pt-cv-carousel-caption  { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-meta-fields * { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-specialp { background-color: #CC3333 !important }\n#pt-cv-view-8090fb6z9g .pt-cv-specialp * { color: #fff !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-pficon  { color: #bbb !important; }\n#pt-cv-view-8090fb6z9g  .add_to_cart_button, #pt-cv-view-8090fb6z9g  .add_to_cart_button *   { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-8090fb6z9g  .woocommerce-onsale   { color: #ffffff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-8090fb6z9g  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-8090fb6z9g  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-8090fb6z9g'] .active.pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .active .pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .selected.pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .dropdown-toggle   { color: #fff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-8090fb6z9g'] .pt-cv-filter-title   { color: #fff !important; background-color: #00aeef !important; }\n#pt-cv-gls-8090fb6z9g li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-gls-header  { color: #fff !important; background-color: #00aeef !important; }<\/style>\r\n\t\t\t <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-25907-2-2\"  class=\"panel-grid-cell\" ><div class=\"panel-cell-style panel-cell-style-for-25907-2-2\" ><div id=\"panel-25907-2-2-0\" class=\"so-panel widget widget_cl-popup widget-cl-popup panel-first-child\" data-index=\"5\" ><div class=\"panel-widget-style panel-widget-style-for-25907-2-2-0\" ><div class=\"cl-popup align_center\"><a href=\"javascript:void(0)\" class=\"cl-popup-trigger type_btn cl-btn\" style=\"color:#c60000;background-color:rgba(221,153,51,0.25);\"><span>M\u00e9dias pr\u00e9f\u00e9r\u00e9s du Clairon<\/span><\/a><div class=\"cl-popup-overlay\" style=\"background-color:rgba(2,0,0,0.67);\"><\/div><div class=\"cl-popup-wrap\"><div class=\"cl-popup-box size_l animation_flipVer\" style=\"border-radius:10px;\"><div class=\"cl-popup-box-h\"><div class=\"cl-popup-box-title\" style=\"color:#666666;background-color:#f2f2f2;\">Les m\u00e9dias choisis par le Clairon<\/div><div class=\"cl-popup-box-content\" style=\"color:#333333;background-color:#ffffff;\"><p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 12pt;\">De nombreux lecteurs du Clairon regrettent de ne pas avoir acc\u00e8s \u00e0 des m\u00e9dias qu\u2019ils souhaitent objectifs. Il nous a paru utile de leur proposer une liste de m\u00e9dias qui, comme nous, ont pour projet \u00e9ditorial de faire r\u00e9fl\u00e9chir leurs lecteurs, leurs auditeurs ou leurs spectateurs. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 12pt;\">Ce qui nous importe, c\u2019est qu\u2019ils ne soient pas des outils de formatage au service d\u2019une cause ou d\u2019une autre, mais qu\u2019ils contribuent \u00e0 ce que chaque individu puisse faire \u00e9voluer ses id\u00e9es&nbsp; en toute conscience.<\/span><\/p>\n<p><span style=\"color: #000000; font-size: 12pt;\">Les m\u00e9dias s\u00e9lectionn\u00e9s r\u00e9sultent des choix de la r\u00e9daction du Clairon.<br>\nCette s\u00e9lection n\u2019est pas d\u00e9finitive, elle peut \u00e9voluer.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><em><strong>Bien \u00e9videmment, la publicit\u00e9 que nous faisons pour ces m\u00e9dias est exclusivement le fruit de notre conviction de leur int\u00e9r\u00eat pour nos lecteurs.<br>\n<span style=\"text-decoration: underline;\">Elle est donc gratuite<\/span> et ne b\u00e9n\u00e9ficie d'aucun retour de leur part, de quelque sorte que ce soit.<\/strong><\/em><\/span><\/p>\n<p><span style=\"color: #000000; font-size: 12pt;\"><em>En cliquant sur un logo, vous acc\u00e9dez au site du m\u00e9dia dans un nouvel onglet de votre navigateur.<\/em><\/span><\/p><\/div><div class=\"cl-popup-box-closer\" style=\"color:#666666;\"><\/div><\/div><\/div><div class=\"cl-popup-closer\"><\/div><\/div><\/div><\/div><\/div><div id=\"panel-25907-2-2-1\" class=\"so-panel widget widget_sow-image-grid panel-last-child\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image-grid so-widget-sow-image-grid-default-46e3cddde1e5-25907\"\n\t\t\t\n\t\t>\t<div\n\t\tclass=\"sow-image-grid-wrapper\"\n\t\t\t\t\t>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.bastamag.net\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"489\" height=\"269\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-basta-ombre.png?fit=489%2C269&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Excellent magazine gratuit en ligne, soutenu \u00e0 parts \u00e9gales par ses lecteurs et par des fondations - Existe depuis 2008 - Informations dans les domaines \u00e9conomique, social et environnemental - Son orientation ? L&#039;int\u00e9r\u00eat g\u00e9n\u00e9ral&quot;\" title=\"Basta !\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-basta-ombre.png?w=489&amp;ssl=1 489w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-basta-ombre.png?resize=300%2C165&amp;ssl=1 300w\" sizes=\"auto, (max-width: 489px) 100vw, 489px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.portail.bastamag.net\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"329\" height=\"107\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/Logo-Basta-Portail-ML-ombre.png?fit=329%2C107&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Initi\u00e9 par Basta !, ce portail vous donne acc\u00e8s \u00e0 de nombreux media alternatifs, peu connus du grand public mais dignes d&#039;int\u00e9r\u00eat&quot;\" title=\"Portail des media libres\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/Logo-Basta-Portail-ML-ombre.png?w=329&amp;ssl=1 329w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/Logo-Basta-Portail-ML-ombre.png?resize=300%2C98&amp;ssl=1 300w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.reporterre.net\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"538\" height=\"261\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-reporterre-ombre.png?fit=538%2C261&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"&quot;Le quotidien de l&#039;\u00e9cologie&quot; - Lanc\u00e9 en 2007 par le journaliste Herv\u00e9 Kempf, ce site gratuit d&#039;actualit\u00e9s traite principalement de probl\u00e9matiques environnementales &quot;\" title=\"Reporterre\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-reporterre-ombre.png?w=538&amp;ssl=1 538w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-reporterre-ombre.png?resize=300%2C146&amp;ssl=1 300w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.actu-environnement.com\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"331\" height=\"219\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Actu-Environnement-ombre.png?fit=331%2C219&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Depuis 2003, ce site de presse d\u00e9livre quotidiennement des informations sp\u00e9cialis\u00e9es sur les secteurs de l\u2019Environnement : d\u00e9chets, eau, \u00e9nergie, risques, am\u00e9nagement, biodiversit\u00e9, etc. Il est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 de presse ind\u00e9pendante CogiTerra&quot;\" title=\"Actu-Environnement\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Actu-Environnement-ombre.png?w=331&amp;ssl=1 331w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Actu-Environnement-ombre.png?resize=300%2C198&amp;ssl=1 300w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.agoravox.fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"95\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Agoravox-ombre.png?fit=350%2C95&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"M\u00e9dia citoyen, AgoraVox propose \u00e0 tout citoyen de devenir r\u00e9dacteur, en vue de mettre librement \u00e0 disposition de ses lecteurs des informations th\u00e9matiques in\u00e9dites, d\u00e9tect\u00e9es par les citoyens.&quot;\" title=\"AgoraVox\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Agoravox-ombre.png?w=350&amp;ssl=1 350w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Agoravox-ombre.png?resize=300%2C81&amp;ssl=1 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mediapart.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"199\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Mediapart-ombre.png?fit=499%2C199&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"&quot;Seuls nos lecteurs peuvent nous acheter&quot; - Ce quotidien payant d&#039;actualit\u00e9 en ligne, que l&#039;on ne pr\u00e9sente plus tant il est connu bien au-del\u00e0 de son lectorat, est, depuis 2008, une r\u00e9f\u00e9rence en mati\u00e8re d&#039;information et d&#039;investigation&quot;\" title=\"Mediapart\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Mediapart-ombre.png?w=499&amp;ssl=1 499w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Mediapart-ombre.png?resize=300%2C120&amp;ssl=1 300w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lemonde.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"351\" height=\"110\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Le-Monde-ombre.png?fit=351%2C110&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Quotidien g\u00e9n\u00e9raliste du soir, Le Monde a \u00e9t\u00e9 fond\u00e9 par Hubert Beuve-Mery en 1944. Edit\u00e9 initialement sur support papier, il est diffus\u00e9 depuis plusieurs ann\u00e9es sur l&#039;internet.&quot;\" title=\"Le Monde\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Le-Monde-ombre.png?w=351&amp;ssl=1 351w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Le-Monde-ombre.png?resize=300%2C94&amp;ssl=1 300w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.monde-diplomatique.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"433\" height=\"116\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Diplo-ombre.png?fit=433%2C116&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Fond\u00e9 en 1954 par Hubert Beuve-M\u00e9ry, le &quot;Diplo&quot;, initialement destin\u00e9  aux cercles diplomatiques, est un mensuel payant,combinant analyses, enqu\u00eates et reportages qui s&#039;affirme comme un &quot;journal de r\u00e9f\u00e9rence pour tous ceux qui veulent comprendre le monde, mais aussi le changer&quot; - R\u00e9guli\u00e8rement, des articles en libre acc\u00e8s permettent de se faire  une id\u00e9e juste de la qualit\u00e9 de ce mensuel de haute tenue.&quot;\" title=\"Le Monde Diplomatique\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Diplo-ombre.png?w=433&amp;ssl=1 433w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Diplo-ombre.png?resize=300%2C80&amp;ssl=1 300w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alternatives-economiques.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-AlterEco-ombre.png?fit=240%2C240&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Fond\u00e9 par Denis Clerc en 1980, le mensuel &quot;Alternavives Economiques&quot; s\u2019int\u00e9resse \u00e0 &quot;l\u2019\u00e9conomie comme enjeu collectif et social, \u00e0 travers des th\u00e9matiques vari\u00e9es : Europe, mondialisation, travail, emploi, sant\u00e9, retraites, famille, transports, solidarit\u00e9, \u00e9ducation, cadre de vie, environnement...&quot;. Il est compl\u00e9t\u00e9 par un quotidien payant d&#039;actualit\u00e9s en ligne sur les m\u00eames th\u00e8mes&quot;\" title=\"Alternatives \u00c9conomiques\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-AlterEco-ombre.png?w=240&amp;ssl=1 240w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-AlterEco-ombre.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lecanardenchaine.fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"525\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Canard-Enchaine-ombre.png?fit=630%2C525&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Peu de gens ignorent &quot;le journal satirique paraissant le mercredi&quot;. Et cela depuis plus d&#039;un si\u00e8cle. Chaque semaine, il nous rappelle que &quot;la libert\u00e9 de la presse ne s&#039;use que si l&#039;on ne s&#039;en sert pas&quot;. Derri\u00e8re un ton fantaisiste, ses articles r\u00e9v\u00e8lent des informations parfois explosives et toujours minutieusement v\u00e9rifi\u00e9es. &quot;\" title=\"Le Canard Encha\u00een\u00e9\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Canard-Enchaine-ombre.png?w=630&amp;ssl=1 630w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Canard-Enchaine-ombre.png?resize=300%2C250&amp;ssl=1 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/charliehebdo.fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"361\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Charlie-Hebdo-ombre.png?fit=660%2C361&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Hebdomadaire satirique fran\u00e7ais fond\u00e9 en 1970 par Fran\u00e7ois Cavanna et le professeur Choron, Charlie Hebdo est connu pour ses dessins satiriques, notamment au travers de ses c\u00e9l\u00e8bres couvertures et de celles &quot;auxquelles vous avez \u00e9chapp\u00e9&quot;. Il pratique aussi le journalisme d&#039;investigation, sur des domaines tels que les sectes, les religions, l&#039;extr\u00eame droite, l&#039;islamisme, la politique, la culture.&quot;\" title=\"Charlie Hebdo\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Charlie-Hebdo-ombre.png?w=660&amp;ssl=1 660w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Charlie-Hebdo-ombre.png?resize=300%2C164&amp;ssl=1 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.franceculture.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"243\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Franc-Culture-ombre.png?fit=249%2C243&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"&quot;France Culture, l&#039;esprit d&#039;ouverture&quot; - Baptis\u00e9e sous ce nom en 1963, cette antenne de Radio France est l&#039;une des plus riches qui soit : Actualit\u00e9s, Savoirs, Art et Cr\u00e9ation, Fictions, Documentaires et Conf\u00e9rences, il y en a pour toutes les curiosit\u00e9s. Son site web permet non seulement d&#039;\u00e9couter les \u00e9missions en direct, mais aussi de les r\u00e9\u00e9couter sans limite dans le temps, de lire des articles originaux et d&#039;\u00e9couter des &quot;podcasts&quot; non diffus\u00e9s \u00e0 la radio. Edite aussi la revue trimestrielle &quot;Papiers&quot;&quot;\" title=\"France Culture\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.arte.tv\/fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"346\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Arte-ombre.png?fit=604%2C346&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Ouverte en 1992, l&#039;antenne franco-allemande ARTE (Association Relative \u00e0 la T\u00e9l\u00e9vision Europ\u00e9enne) a pour mission de &quot;rapprocher les europ\u00e9ens&quot;. Son projet est de &quot;faire de la culture un lien vivant entre les hommes&quot;. Elle est financ\u00e9e \u00e0 95% par la contribution \u00e0 l&#039;audiovisuel  public en Allemagne et en France. Ses programmes sont disponibles en 6 langues, permettant \u00e0 70% des europ\u00e9ens de la regarder dans leur langue maternelle. 85% de ses programmes sont produits dans l&#039;Union Europ\u00e9enne.&quot;\" title=\"ARTE\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Arte-ombre.png?w=604&amp;ssl=1 604w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Arte-ombre.png?resize=300%2C172&amp;ssl=1 300w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.acrimed.org\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"285\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Acrimed-ombre.png?fit=285%2C285&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Action CRItique MEDia (ACRIMED) est une association fond\u00e9e an 1996 par Pierre Bourdieu et Henri Maler. Son but est d&#039;\u00eatre un &quot;observatoire des media... au service d&#039;une critique ind\u00e9pendante, radicale et intransigeante&quot;&quot;\" title=\"ACRIMED\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Acrimed-ombre.png?w=285&amp;ssl=1 285w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Acrimed-ombre.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><script type=\"text\/javascript\"> var tt_store_content = \"Sortir du nucl\u00e9aire Aude\"; toolTips('.classtoolTips84',tt_store_content,'7258'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>C\\<\\\/strong\\>ommunal d'\\<strong\\>A\\<\\\/strong\\>ction \\<strong\\>S\\<\\\/strong\\>ociale\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Un centre communal d'action sociale \\(<span class='tooltipsall tooltip_post_id_18100 classtoolTips132'>CCAS<\/span>\\) est, en France, un \u00e9tablissement public administr\u00e9 par un conseil d'administration pr\u00e9sid\u00e9 par le maire de la commune\\. Il a pour mission d'animer une action g\u00e9n\u00e9rale de pr\u00e9vention et de d\u00e9veloppement social au sein de la commune en liaison \u00e9troite avec les institutions publiques et priv\u00e9es\\<\\\/p\\>\"; toolTips('.classtoolTips132',tt_store_content,'18100'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br\/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><br\/><br\/>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>tablissement \\<strong\\>F\\<\\\/strong\\>ran\u00e7ais du \\<strong\\>S\\<\\\/strong\\>ang\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p\\>\\<a href\\='https\\:\\\/\\\/www\\.efs\\.sante\\.fr\\\/' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Acc\u00e9der ici au site de l'<span class='tooltipsall tooltip_post_id_21261 classtoolTips150'>EFS<\/span>\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips150',tt_store_content,'21261'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>evenu de \\<strong\\>S\\<\\\/strong\\>olidarit\u00e9 \\<strong\\>A\\<\\\/strong\\>ctive\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Le revenu de solidarit\u00e9 active est une prestation sociale fran\u00e7aise, g\u00e9r\u00e9e par les conseils d\u00e9partementaux, vers\u00e9e par les <span class='tooltipsall tooltip_post_id_5652 classtoolTips155'>CAF<\/span> et les MSA et destin\u00e9e \u00e0 garantir \u00e0 ses b\u00e9n\u00e9ficiaires, qu'ils aient ou non la capacit\u00e9 de travailler, un revenu minimum, avec en contrepartie une obligation de chercher un emploi ou de d\u00e9finir et suivre un projet professionnel visant \u00e0 am\u00e9liorer sa situation financi\u00e8re\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Cette prestation sociale a \u00e9t\u00e9 mise en place en 2009, en remplacement du RMI \\(revenu minimum d'insertion\\), mis en place en 1988\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>En 2016, 2,5 millions de personnes \u00e9taient b\u00e9n\u00e9ficiaires du <span class='tooltipsall tooltip_post_id_5651 classtoolTips154'>RSA<\/span>\\.\\<\\\/p\\><br\/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Revenu_de_solidarit%C3%A9_active' target\\='_blank' rel\\='noopener'\\>Acc\u00e9der ici \u00e0 la fiche Wikipedia traitant du RSA\\<\\\/a\\><br\/>\\<a href\\='https\\:\\\/\\\/www\\.insee\\.fr\\\/fr\\\/metadonnees\\\/definition\\\/c1718' target\\='_blank' rel\\='noopener'\\>Acc\u00e9der ici \u00e0 la d\u00e9finition du RSA fournie par l'<span class='tooltipsall tooltip_post_id_6978 classtoolTips82'>INSEE<\/span>\\<\\\/a\\>\\<\\\/em\\>\"; toolTips('.classtoolTips154',tt_store_content,'5651'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9pertoire \\<strong\\>N\\<\\\/strong\\>ational des \\<strong\\>A\\<\\\/strong\\>ssociations\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips159',tt_store_content,'24374'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(COR\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br\/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;<br\/><br\/>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>\\<span class\\='ILfuVd'\\>La politique agricole commune \\(\\<b\\><span class='tooltipsall tooltip_post_id_11364 classtoolTips174'>PAC<\/span>\\<\\\/b\\>\\) est une politique mise en place \u00e0 l'\u00e9chelle de l'Union europ\u00e9enne\\. \u00c0 l'origine, elle est fond\u00e9e principalement sur des mesures de contr\u00f4le des prix et de subventionnement, visant \u00e0 moderniser et d\u00e9velopper l'agriculture\\.\\<\\\/span\\> \\(source Wikipedia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips174',tt_store_content,'11364'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>H\\<\\\/strong\\>ydrocarbure \\<strong\\>A\\<\\\/strong\\>romatique \\<strong\\>P\\<\\\/strong\\>olycyclique\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Depuis de nombreuses ann\u00e9es, les <span class='tooltipsall tooltip_post_id_20397 classtoolTips184'>HAP<\/span> sont tr\u00e8s \u00e9tudi\u00e9s car ce sont des compos\u00e9s pr\u00e9sents dans tous les milieux environnementaux et qui montrent une forte toxicit\u00e9\\. On a pu \u00e9tablir la canc\u00e9rog\u00e9n\u00e8se de certains HPA, tels que le Benzo\\[a\\]anthrac\u00e8ne, le Chrys\u00e8ne et d'autres\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les HAP proviennent principalement de la combustion \u00e0 haute temp\u00e9rature \\(500\u00b0 C et plus\\) de mati\u00e8res fossiles telles que le bois, le charbon et le p\u00e9trole\\. Dans l'environnement, la production de HAP provient donc&nbsp; du chauffage domestique, de la circulation automobile, des centrales \u00e9lectriques fonctionnant au charbon ou au p\u00e9trole \\('fioul'\\), ainsi que des incin\u00e9rateurs\\.\\<\\\/p\\><br\/>\\<p\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Hydrocarbure_aromatique_polycyclique' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Voir ici l'article Wikipedia consacr\u00e9 aux HAP\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips184',tt_store_content,'20397'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br\/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<br\/><br\/>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<br\/><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br\/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_21204 classtoolTips199'>COV<\/span> \\= Compos\u00e9 Organique Volatile\\<\\\/p\\>\"; toolTips('.classtoolTips199',tt_store_content,'21204'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_24572 classtoolTips211'>MIT<\/span> \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>d\u00e9chets \u00e0 Vie Courte \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips212',tt_store_content,'19201'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br\/>ou<br\/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"<div class='tooltips_youtube_class' ><iframe width='100%' height='100%' src='http:\/\/www.youtube.com\/embed\/terawatt?rel=0&autoplay=1' frameborder='0' allowfullscreen><\/iframe><\/div>\\<p\\>\\<strong\\>TERAWATT \\(<span class='tooltipsall tooltip_post_id_30105 classtoolTips219'>TW<\/span>\\) \\= 1000 000 000 000 <span class='tooltipsall tooltip_post_id_30101 classtoolTips216'>KW<\/span>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips219',tt_store_content,'30105'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\><span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nm<\/span> \\= n\\<\\\/strong\\>ano\\<strong\\>m\\<\\\/strong\\>\u00e8tre \\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<em\\>le <span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nanom\u00e8tre<\/span>, de symbole nm, est une unit\u00e9 de longueur du Syst\u00e8me international\\. C'est un sous\\-multiple du m\u00e8tre, il vaut un milliardi\u00e8me de m\u00e8tre, soit un millioni\u00e8me de millim\u00e8tre\\.\\<\\\/em\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<em\\> 1 nm \\= 10\u207b\u00b3 \u00b5m \\= 10\\<sup\\>\u20136\\<\\\/sup\\> mm \\= 10\\<sup\\>\u20139\\<\\\/sup\\> m\\.\\<\\\/em\\>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips222',tt_store_content,'21736'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script>","protected":false},"excerpt":{"rendered":"<p>Quel avenir souhaitez-vous pour votre pays ? Quelle candidature repr\u00e9sente le mieux cet avenir ? Un candidat qui raisonne en termes d\u2019amis\/ennemis pr\u00e9pare la guerre de tous contre tous Pour d\u00e9cider de votre vote, quelle est votre source d&rsquo;informations privil\u00e9gi\u00e9e : les (d)\u00e9bats radio \/ t\u00e9l\u00e9vis\u00e9s, la presse \u00e9crite ou les programmes des candidats ?Lire la suite &rarr;<script type=\"text\/javascript\"> var tt_store_content = \"Sortir du nucl\u00e9aire Aude\"; toolTips('.classtoolTips84',tt_store_content,'7258'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>C\\<\\\/strong\\>ommunal d'\\<strong\\>A\\<\\\/strong\\>ction \\<strong\\>S\\<\\\/strong\\>ociale\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Un centre communal d'action sociale \\(<span class='tooltipsall tooltip_post_id_18100 classtoolTips132'>CCAS<\/span>\\) est, en France, un \u00e9tablissement public administr\u00e9 par un conseil d'administration pr\u00e9sid\u00e9 par le maire de la commune\\. Il a pour mission d'animer une action g\u00e9n\u00e9rale de pr\u00e9vention et de d\u00e9veloppement social au sein de la commune en liaison \u00e9troite avec les institutions publiques et priv\u00e9es\\<\\\/p\\>\"; toolTips('.classtoolTips132',tt_store_content,'18100'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br \/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><\/p>\n<p>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>tablissement \\<strong\\>F\\<\\\/strong\\>ran\u00e7ais du \\<strong\\>S\\<\\\/strong\\>ang\\<\\\/span\\>\\<\\\/p\\><br \/>\\<p\\>\\<a href\\='https\\:\\\/\\\/www\\.efs\\.sante\\.fr\\\/' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Acc\u00e9der ici au site de l'<span class='tooltipsall tooltip_post_id_21261 classtoolTips150'>EFS<\/span>\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips150',tt_store_content,'21261'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>evenu de \\<strong\\>S\\<\\\/strong\\>olidarit\u00e9 \\<strong\\>A\\<\\\/strong\\>ctive\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le revenu de solidarit\u00e9 active est une prestation sociale fran\u00e7aise, g\u00e9r\u00e9e par les conseils d\u00e9partementaux, vers\u00e9e par les <span class='tooltipsall tooltip_post_id_5652 classtoolTips155'>CAF<\/span> et les MSA et destin\u00e9e \u00e0 garantir \u00e0 ses b\u00e9n\u00e9ficiaires, qu'ils aient ou non la capacit\u00e9 de travailler, un revenu minimum, avec en contrepartie une obligation de chercher un emploi ou de d\u00e9finir et suivre un projet professionnel visant \u00e0 am\u00e9liorer sa situation financi\u00e8re\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Cette prestation sociale a \u00e9t\u00e9 mise en place en 2009, en remplacement du RMI \\(revenu minimum d'insertion\\), mis en place en 1988\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>En 2016, 2,5 millions de personnes \u00e9taient b\u00e9n\u00e9ficiaires du <span class='tooltipsall tooltip_post_id_5651 classtoolTips154'>RSA<\/span>\\.\\<\\\/p\\><br \/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Revenu_de_solidarit%C3%A9_active' target\\='_blank' rel\\='noopener'\\>Acc\u00e9der ici \u00e0 la fiche Wikipedia traitant du RSA\\<\\\/a\\><br \/>\\<a href\\='https\\:\\\/\\\/www\\.insee\\.fr\\\/fr\\\/metadonnees\\\/definition\\\/c1718' target\\='_blank' rel\\='noopener'\\>Acc\u00e9der ici \u00e0 la d\u00e9finition du RSA fournie par l'<span class='tooltipsall tooltip_post_id_6978 classtoolTips82'>INSEE<\/span>\\<\\\/a\\>\\<\\\/em\\>\"; toolTips('.classtoolTips154',tt_store_content,'5651'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9pertoire \\<strong\\>N\\<\\\/strong\\>ational des \\<strong\\>A\\<\\\/strong\\>ssociations\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips159',tt_store_content,'24374'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br \/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>\\<span class\\='ILfuVd'\\>La politique agricole commune \\(\\<b\\><span class='tooltipsall tooltip_post_id_11364 classtoolTips174'>PAC<\/span>\\<\\\/b\\>\\) est une politique mise en place \u00e0 l'\u00e9chelle de l'Union europ\u00e9enne\\. \u00c0 l'origine, elle est fond\u00e9e principalement sur des mesures de contr\u00f4le des prix et de subventionnement, visant \u00e0 moderniser et d\u00e9velopper l'agriculture\\.\\<\\\/span\\> \\(source Wikipedia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips174',tt_store_content,'11364'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>H\\<\\\/strong\\>ydrocarbure \\<strong\\>A\\<\\\/strong\\>romatique \\<strong\\>P\\<\\\/strong\\>olycyclique\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Depuis de nombreuses ann\u00e9es, les <span class='tooltipsall tooltip_post_id_20397 classtoolTips184'>HAP<\/span> sont tr\u00e8s \u00e9tudi\u00e9s car ce sont des compos\u00e9s pr\u00e9sents dans tous les milieux environnementaux et qui montrent une forte toxicit\u00e9\\. On a pu \u00e9tablir la canc\u00e9rog\u00e9n\u00e8se de certains HPA, tels que le Benzo\\[a\\]anthrac\u00e8ne, le Chrys\u00e8ne et d'autres\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les HAP proviennent principalement de la combustion \u00e0 haute temp\u00e9rature \\(500\u00b0 C et plus\\) de mati\u00e8res fossiles telles que le bois, le charbon et le p\u00e9trole\\. Dans l'environnement, la production de HAP provient donc&nbsp; du chauffage domestique, de la circulation automobile, des centrales \u00e9lectriques fonctionnant au charbon ou au p\u00e9trole \\('fioul'\\), ainsi que des incin\u00e9rateurs\\.\\<\\\/p\\><br \/>\\<p\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Hydrocarbure_aromatique_polycyclique' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Voir ici l'article Wikipedia consacr\u00e9 aux HAP\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips184',tt_store_content,'20397'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br \/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<\/p>\n<p>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br \/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_21204 classtoolTips199'>COV<\/span> \\= Compos\u00e9 Organique Volatile\\<\\\/p\\>\"; toolTips('.classtoolTips199',tt_store_content,'21204'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_24572 classtoolTips211'>MIT<\/span> \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>d\u00e9chets \u00e0 Vie Courte \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips212',tt_store_content,'19201'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br \/>ou<br \/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"<\/p>\n<div class='tooltips_youtube_class' ><iframe width='100%' height='100%' src='http:\/\/www.youtube.com\/embed\/terawatt?rel=0&autoplay=1' frameborder='0' allowfullscreen><\/iframe><\/div>\n<p>\\<p\\>\\<strong\\>TERAWATT \\(<span class='tooltipsall tooltip_post_id_30105 classtoolTips219'>TW<\/span>\\) \\= 1000 000 000 000 <span class='tooltipsall tooltip_post_id_30101 classtoolTips216'>KW<\/span>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips219',tt_store_content,'30105'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\><span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nm<\/span> \\= n\\<\\\/strong\\>ano\\<strong\\>m\\<\\\/strong\\>\u00e8tre \\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<em\\>le <span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nanom\u00e8tre<\/span>, de symbole nm, est une unit\u00e9 de longueur du Syst\u00e8me international\\. C'est un sous\\-multiple du m\u00e8tre, il vaut un milliardi\u00e8me de m\u00e8tre, soit un millioni\u00e8me de millim\u00e8tre\\.\\<\\\/em\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<em\\> 1 nm \\= 10\u207b\u00b3 \u00b5m \\= 10\\<sup\\>\u20136\\<\\\/sup\\> mm \\= 10\\<sup\\>\u20139\\<\\\/sup\\> m\\.\\<\\\/em\\>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips222',tt_store_content,'21736'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script><\/p>\n","protected":false},"author":1,"featured_media":18234,"parent":1235,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"coauthors":[8],"class_list":["post-25907","page","type-page","status-publish","has-post-thumbnail","hentry","has-thumb"],"acf":[],"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/P9B5TM-6JR","_links":{"self":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/25907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=25907"}],"version-history":[{"count":0,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/25907\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/1235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media\/18234"}],"wp:attachment":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=25907"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/coauthors?post=25907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}