{"id":30836,"date":"2024-11-22T13:10:39","date_gmt":"2024-11-22T12:10:39","guid":{"rendered":"https:\/\/le-clairon-nouveau.fr\/wordpress\/?page_id=30836"},"modified":"2024-12-21T13:07:22","modified_gmt":"2024-12-21T12:07:22","slug":"unes-edition-115","status":"publish","type":"page","link":"https:\/\/le-clairon-nouveau.fr\/wordpress\/unes\/unes-edition-115\/","title":{"rendered":"\u00c9dition n\u00b0 115 &#8211; D\u00e9cembre 2024 \/ Janvier 2025"},"content":{"rendered":"<div id=\"pl-30836\"  class=\"panel-layout\" ><div id=\"pg-30836-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-30836-0-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><div id=\"pg-30836-1\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-30836-1\" data-stretch-type=\"full-width-stretch\" ><div id=\"pgc-30836-1-0\"  class=\"panel-grid-cell\" ><div class=\"panel-cell-style panel-cell-style-for-30836-1-0\" ><div id=\"panel-30836-1-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"panel-widget-style panel-widget-style-for-30836-1-0-0\" ><div id=\"pl-w6766af7a7786c\"  class=\"panel-layout\" ><div id=\"pg-w6766af7a7786c-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w6766af7a7786c-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w6766af7a7786c-0-0-0\" class=\"so-panel widget widget_sow-hero panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-hero so-widget-sow-hero-default-a57ef7e50593 so-widget-fittext-wrapper\"\n\t\t\t data-fit-text-compressor=\"4\"\n\t\t>\t\t\t\t<div class=\"sow-slider-base\" style=\"display: none\" tabindex=\"0\">\n\t\t\t\t\t<ul\n\t\t\t\t\tclass=\"sow-slider-images\"\n\t\t\t\t\tdata-settings=\"{&quot;pagination&quot;:true,&quot;speed&quot;:1200,&quot;timeout&quot;:10000,&quot;paused&quot;:false,&quot;pause_on_hover&quot;:true,&quot;swipe&quot;:true,&quot;nav_always_show_desktop&quot;:&quot;&quot;,&quot;nav_always_show_mobile&quot;:&quot;&quot;,&quot;breakpoint&quot;:&quot;780px&quot;,&quot;unmute&quot;:false,&quot;anchor&quot;:null}\"\n\t\t\t\t\tstyle=\"min-height: 200px\"\t\t\t\t\tdata-anchor-id=\"\"\n\t\t\t\t>\t\t<li class=\"sow-slider-image\" style=\"visibility: visible;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h1 class=\"gmail_default\" style=\"text-align: center\"><strong>\"C'\u00e9tait un temps d\u00e9raisonnable...\"<\/strong><\/h1>\n<h2 style=\"text-align: center\"><em>(Macron dissout l'Assembl\u00e9e Nationale, puis rejette le choix des urnes)<\/em><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h1 class=\"gmail_default\" style=\"text-align: center\">\"On avait mis les morts \u00e0 table...\"<\/h1>\n<h2 style=\"text-align: center\"><em>(Macron nomme Barnier puis Bayrou comme premiers ministres)<\/em><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h1 class=\"gmail_default\" style=\"text-align: center\">\"On faisait des <span class='tooltipsall tooltip_post_id_18357 classtoolTips220'>ch<\/span>\u00e2teaux de sable...\"<\/h1>\n<h2 style=\"text-align: center\"><em>(Quand la finance dicte les choix politiques)<\/em><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h1 class=\"gmail_default\" style=\"text-align: center\">\"On prenait les loups pour des chiens...\"<\/h1>\n<h2 style=\"text-align: center\"><em>(Quand le pouvoir joue avec le feu de l'extr\u00eame droite)<\/em><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h1 style=\"text-align: center\">\"Est-ce ainsi que les hommes vivent ?\"<\/h1>\n<h3 style=\"text-align: center\"><em>Louis Aragon<\/em><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h2 style=\"text-align: center\">Le don de sang reste une priorit\u00e9 quotidienne pour nos services de sant\u00e9<\/h2>\n<div class=\"sow-hero-buttons\" style=\"text-align: center\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-atom-67338c4c311d\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-center\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/dondesang.efs.sante.fr\/trouver-une-collecte\"\n\t\t\t\t\tclass=\"sowb-button ow-icon-placement-left ow-button-hover\" target=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\t<span>\n\t\t\t\n\t\t\tVoir les prochaines collectes\t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/li>\n\t\t<\/ul>\t\t\t\t<ol class=\"sow-slider-pagination\">\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"0\" aria-label=\"Display slide 1\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"1\" aria-label=\"Display slide 2\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"2\" aria-label=\"Display slide 3\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"3\" aria-label=\"Display slide 4\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"4\" aria-label=\"Display slide 5\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"5\" aria-label=\"Display slide 6\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-next\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"next\" aria-label=\"Next slide\" data-action=\"next\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-right\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-prev\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"previous\" aria-label=\"Previous slide\" data-action=\"prev\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-left\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w6766af7a7786c-1\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-w6766af7a7786c-1\" ><div id=\"pgc-w6766af7a7786c-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w6766af7a7786c-1-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"panel-widget-style panel-widget-style-for-w6766af7a7786c-1-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-74460ebe44c3 so-widget-fittext-wrapper\"\n\t\t\t data-fit-text-compressor=\"2\"\n\t\t><div class=\"sow-headline-container \">\n\t\t\t\t\t\t\t<h1 class=\"sow-headline\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.helloasso.com\/associations\/association-le-clairon-de-l-atax\/adhesions\/adhesion-2024\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\tVous souhaitez soutenir le Clairon ? Cliquez ici pour adh\u00e9rer \u00e0 notre association !<\/a>\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-w6766af7a7786c-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w6766af7a7786c-1-1-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"2\" ><div class=\"panel-widget-style panel-widget-style-for-w6766af7a7786c-1-1-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-1f583924a6db so-widget-fittext-wrapper\"\n\t\t\t data-fit-text-compressor=\"2\"\n\t\t><div class=\"sow-headline-container \">\n\t\t\t\t\t\t\t<h2 class=\"sow-headline\">\n\t\t\t\t\t\tPublicit\u00e9 citoyenne\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-30836-2\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-30836-2\" data-stretch-type=\"full-width-stretch\" ><div id=\"pgc-30836-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-30836-2-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"textwidget\"><p style=\"text-align: center;\"><span id=\"textillate-fbarin\"><span style=\"visibility: hidden;\"><span class=\"tlt-texts\" style=\"display:none;\"><br \/>\n<span data-in-delay=\"50\" data-out-delay=\"50\" data-in-effect=\"flipInY\" data-in-sync=\"true\" data-out-effect=\"flipOutY\" data-out-sync=\"true\"><span style=\"color: #000000;\">A titre temporaire, seuls les articles \u00e0 compter d'octobre 2019 (\u00e9dition n\u00b0 58) sont disponibles<\/span><\/span> <br \/>\n<span data-in-delay=\"50\" data-out-delay=\"50\" data-in-effect=\"flipInY\" data-in-sync=\"true\" data-out-effect=\"flipOutY\" data-out-sync=\"true\"><span style=\"color: #520000;\">Nous vous tiendrons r\u00e9guli\u00e8rement inform\u00e9.e.s de la republication des articles des \u00e9ditions pr\u00e9c\u00e9dentes<\/span> <\/span> <br \/>\n<\/span>&nbsp;<\/span><\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-30836-3\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-30836-3\" data-stretch-type=\"full-width-stretch\" ><div id=\"pgc-30836-3-0\"  class=\"panel-grid-cell\" ><div class=\"panel-cell-style panel-cell-style-for-30836-3-0\" ><div id=\"panel-30836-3-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child\" data-index=\"2\" ><div class=\"panel-widget-style panel-widget-style-for-30836-3-0-0\" ><div class=\"textwidget\"><h3 style=\"text-align: center;\"><span style=\"color: #8f4511;\">\u00c9ditorial<\/span><\/h3>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-post-border pt-cv-justify pt-cv-reused\" id=\"pt-cv-view-a2290f1fn4\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30892\"><div class='pt-cv-ifield'><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/avec-du-vieux-on-fait-du-vieux\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd\" target=\"_self\" ><img decoding=\"async\" width=\"300\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2024\/12\/vieux-crocodiles-2-Image-par-Archimar-de-Pixabay.jpg?resize=631%2C473&amp;ssl=1\" class=\"pt-cv-thumbnail img-rounded cvp-substitute no-lazyload \" alt=\"Avec du vieux on fait du vieux\" title=\"\" data-no-lazy=\"1\" \/><\/a>\n<h4 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/avec-du-vieux-on-fait-du-vieux\/\" class=\"_self cvplbd\" target=\"_self\" >Avec du vieux on fait du vieux<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/hubert\/\" rel=\"author\">Hubert Reys<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2024-12-21T12:30:22+01:00\">21 d\u00e9cembre 2024<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">Quelques r\u00e9flexions autour du changement de premier ministre ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/avec-du-vieux-on-fait-du-vieux\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-3d9df5dx4g\">#pt-cv-view-a2290f1fn4.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-a2290f1fn4.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-a2290f1fn4 .pt-cv-title a, #pt-cv-view-a2290f1fn4  .panel-title { font-size: 18px !important; line-height: 1.3 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-content , #pt-cv-view-a2290f1fn4  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-a2290f1fn4  .pt-cv-hover-wrapper::before   { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-a2290f1fn4:not(.pt-cv-nohover) .pt-cv-mask *   { color: #fff; }\n#pt-cv-view-a2290f1fn4 .pt-cv-carousel-caption  { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-specialp { background-color: #CC3333 !important }\n#pt-cv-view-a2290f1fn4 .pt-cv-specialp * { color: #fff !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-pficon  { color: #bbb !important; }\n#pt-cv-view-a2290f1fn4  .add_to_cart_button, #pt-cv-view-a2290f1fn4  .add_to_cart_button *   { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-a2290f1fn4  .woocommerce-onsale   { color: #ffffff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-a2290f1fn4  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-a2290f1fn4  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-a2290f1fn4'] .active.pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .active .pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .selected.pt-cv-filter-option, [id^='pt-cv-filter-bar-a2290f1fn4'] .dropdown-toggle   { color: #fff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-a2290f1fn4'] .pt-cv-filter-title   { color: #fff !important; background-color: #00aeef !important; }\n#pt-cv-gls-a2290f1fn4 li a   { font-weight: 600 !important; }\n#pt-cv-gls-a2290f1fn4 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-a2290f1fn4 .pt-cv-gls-header  { background-color: #00aeef !important; }\n#pt-cv-view-a2290f1fn4 .img-rounded, #pt-cv-view-a2290f1fn4 .pt-cv-hover-wrapper { -webkit-border-radius: 3px !important; -moz-border-radius: 3px !important; border-radius: 3px !important; }\n#pt-cv-view-a2290f1fn4 { text-align: justify; }<\/style>\r\n\t\t\t <br><\/p>\n<\/div><\/div><\/div><div id=\"panel-30836-3-0-1\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-last-child\" data-index=\"3\" ><div class=\"panel-widget-style panel-widget-style-for-30836-3-0-1\" ><div class=\"textwidget\"><h3 style=\"text-align: center;\"><span style=\"color: #993300;\">Ils ont contribu\u00e9 \u00e0 cette \u00e9dition<\/span><\/h3>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-reused\" id=\"pt-cv-view-edf64eb5yg\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30957\"><div class='pt-cv-ifield'><div class=\"pt-cv-content\"><p><span style=\"font-size: 14pt;color: #3366ff\"><strong>Articles, textes, photos, communiqu\u00e9s, etc.\u2026<\/strong><\/span><\/p>\n<p>Catherine Burger (Aude)<br \/>\nBruno Chareyron (<span class='tooltipsall tooltip_post_id_7025 classtoolTips55'>Criirad<\/span>)<br \/>\nDominique Drouet (Toulouse)<br \/>\nLaurent Fabas (Aude))<br \/>\nDidier Latorre (H\u00e9rault)<br \/>\nSophie Masini (Alsace)<br \/>\n<span class='tooltipsall tooltip_post_id_4451 classtoolTips213'>Jo<\/span>\u00ebl Raimondi (Aude)<br \/>\nJuliet Schweitzer (Aude)<br \/>\nHubert Reys (Aude)<br \/>\nR\u00e9my Soual (Aude)<br \/>\nCurly Mac Toole (Paris)<br \/>\nLouise B. Velpeau (Aude)<\/p>\n<p><span style=\"font-size: 14pt;color: #3366ff\"><strong>R\u00e9daction, \u00c9dition, Publication :<\/strong><\/span><\/p>\n<p>Jean Cordier<br \/>\nHubert Reys<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;color: #3366ff\"><strong>Coach\u00a0:<\/strong><\/span><\/p>\n<p>Dundee <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-23450\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur.jpg?resize=34%2C51&#038;ssl=1\" alt=\"\" width=\"34\" height=\"51\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=201%2C300&amp;ssl=1 201w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=685%2C1024&amp;ssl=1 685w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=768%2C1147&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=1028%2C1536&amp;ssl=1 1028w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?resize=1371%2C2048&amp;ssl=1 1371w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2018\/12\/dundee-sauveteur-scaled.jpg?w=1714&amp;ssl=1 1714w\" sizes=\"auto, (max-width: 34px) 100vw, 34px\" \/>L\u2019avenir appartient \u00e0 celui dont le chien se l\u00e8ve t\u00f4t<\/p>\n<p>&nbsp;<\/p>\n<script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \\<strong\\>C\\<\\\/strong\\>ommission de \\<strong\\>R\\<\\\/strong\\>echerche et d'\\<strong\\>I\\<\\\/strong\\>nformations \\<strong\\>I\\<\\\/strong\\>nd\u00e9pendantes sur la \\<strong\\>Rad\\<\\\/strong\\>ioactivit\u00e9 est une association fran\u00e7aise 'loi 1901'\\. Elle emploie une \u00e9quipe d'une douzaine de scientifiques\u00a0 et dispose d'un laboratoire d'analyse agr\u00e9e par le minist\u00e8re de la sant\u00e9 dans le cadre de la protection de l'environnement\\. Son domaine d'intervention est le d\u00e9pistage et \u00e0 l'identification des pollutions radioactives en France comme \u00e0 l'\u00e9tranger\\. Elle se finance par les cotisations de ses membres et la r\u00e9mun\u00e9ration de ses nombreux travaux \\(plus d'un millier depuis sa cr\u00e9ation\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips55',tt_store_content,'7025'); <\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \\<strong\\>C\\<\\\/strong\\>ommission de \\<strong\\>R\\<\\\/strong\\>echerche et d'\\<strong\\>I\\<\\\/strong\\>nformations \\<strong\\>I\\<\\\/strong\\>nd\u00e9pendantes sur la \\<strong\\>Rad\\<\\\/strong\\>ioactivit\u00e9 est une association fran\u00e7aise 'loi 1901'\\. Elle emploie une \u00e9quipe d'une douzaine de scientifiques\u00a0 et dispose d'un laboratoire d'analyse agr\u00e9e par le minist\u00e8re de la sant\u00e9 dans le cadre de la protection de l'environnement\\. Son domaine d'intervention est le d\u00e9pistage et \u00e0 l'identification des pollutions radioactives en France comme \u00e0 l'\u00e9tranger\\. Elle se finance par les cotisations de ses membres et la r\u00e9mun\u00e9ration de ses nombreux travaux \\(plus d'un millier depuis sa cr\u00e9ation\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips55',tt_store_content,'7025'); <\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br \/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;<br \/><br \/>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/a><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/p><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/a><\/sup><\/a><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/a><\/sup><\/a><\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br \/>ou<br \/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/span><\/p><\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-416dd66o1b\">#pt-cv-view-edf64eb5yg.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-edf64eb5yg.pt-cv-post-border .pt-cv-content-item   { border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-edf64eb5yg .pt-cv-title a, #pt-cv-view-edf64eb5yg  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-content , #pt-cv-view-edf64eb5yg  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 14px !important; line-height: 1.3 !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-readmore  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-edf64eb5yg .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-edf64eb5yg  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-edf64eb5yg  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-edf64eb5yg li a   { font-weight: 600 !important; }\n#pt-cv-gls-edf64eb5yg li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t <br><\/p>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pgc-30836-3-1\"  class=\"panel-grid-cell\" ><div id=\"panel-30836-3-1-0\" class=\"so-panel widget widget_ink-tabs panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"panel-widget-style panel-widget-style-for-30836-3-1-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-ink-tabs so-widget-ink-tabs-tabs-2b56913b4b9f-30836\"\n\t\t\t\n\t\t>\n<div class=\"iw-so-tabs iw-so-tabs-horizontal iw-so-tabs-fullwidth\">\n\n\t<ul class=\"iw-so-tabs-nav\">\n\n\t\t\t\t\t<li class=\"iw-so-tab-title iw-so-tab-active\" id=\"ink-tabs-828010003-1\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-1-content\">\n\t\t\t\t\t<span class=\"sow-icon-icomoon\" data-sow-icon=\"&#xe904;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Actualit\u00e9s<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-2\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-2-content\">\n\t\t\t\t\t<span class=\"sow-icon-icomoon\" data-sow-icon=\"&#xe92e;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Culture et Art de Vivre<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-3\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-3-content\">\n\t\t\t\t\t<span class=\"sow-icon-icomoon\" data-sow-icon=\"&#xe921;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Changer les Institutions<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"iw-so-tab-title\" id=\"ink-tabs-828010003-4\">\n\t\t\t\t<a href=\"#ink-tabs-828010003-4-content\">\n\t\t\t\t\t<span class=\"sow-icon-icomoon\" data-sow-icon=\"&#xea84;\"\n\t\tstyle=\"\" \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t<span class=\"iw-so-tab-text\">Expression Libre<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\n\t<\/ul>\n\n\t<div class=\"iw-so-tabs-content\">\n\n\t\t\t\t\t<div class=\"iw-so-tabs-panel iw-so-tab-active\" id=\"ink-tabs-828010003-1-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-54904956ml\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30932\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/la-france-un-systeme-politique-en-panne\/\" class=\"_self cvplbd\" target=\"_self\" >La France, un syst\u00e8me politique en panne ?<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/la-france-un-systeme-politique-en-panne\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"La France, un syst\u00e8me politique en panne ?\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2024\/12\/mouvement-pour-la-democratier-place-Tien-En-Men-Pekin-1989-2-Image-par-Lola-Anamon-de-Pixabay.jpg?resize=787%2C438&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Penser le fonctionnement d\u00e9mocratique de notre pays c\u2019est penser d\u2019abord \u00e0 sa d\u00e9centralisation et \u00e0 la d\u00e9concentration de ses pouvoirs de ses services et de son \u00e9conomie ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/la-france-un-systeme-politique-en-panne\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2024-12-21T12:30:26+01:00\">21 d\u00e9cembre 2024<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30918\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/a-propos-du-colloque-agaches-qui-sest-tenu-a-narbonne\/\" class=\"_self cvplbd\" target=\"_self\" >A propos du colloque \u00ab\u00a0Agaches\u00a0\u00bb qui s&rsquo;est tenu \u00e0 Narbonne<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/a-propos-du-colloque-agaches-qui-sest-tenu-a-narbonne\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"A propos du colloque &quot;Agaches&quot; qui s&#039;est tenu \u00e0 Narbonne\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2024\/12\/Agaches-photo-JR.jpg?resize=665%2C652&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">SURMONTER la FRONTIERE Coupure ? coutures ! Un colloque cr\u00e9atif et constructif  ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/a-propos-du-colloque-agaches-qui-sest-tenu-a-narbonne\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/joel\/\" rel=\"author\">Jo\u00ebl Raimondi<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2024-12-21T12:30:25+01:00\">21 d\u00e9cembre 2024<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30897\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/les-activites-de-lusine-orano-malvesi-a-narbonne-sont-elles-polluantes\/\" class=\"_self cvplbd\" target=\"_self\" >Les activit\u00e9s de l\u2019usine <span class='tooltipsall tooltip_post_id_5129 classtoolTips77'>Orano<\/span>-Malv\u00e9si \u00e0 Narbonne sont-elles polluantes ?<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/les-activites-de-lusine-orano-malvesi-a-narbonne-sont-elles-polluantes\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Les activit\u00e9s de l\u2019usine Orano-Malv\u00e9si \u00e0 Narbonne sont-elles polluantes ?\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2024\/12\/wagon-de-transport-duranium-en-gare-de-Narbonne-photo-Collectif-Vigilance-Malvesi.png?resize=591%2C406&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">29 novembre 2024 : le \u00ab Collectif Vigilance Malv\u00e9si \u00bb a tenu une conf\u00e9rence de presse pour rendre compte de son action ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/les-activites-de-lusine-orano-malvesi-a-narbonne-sont-elles-polluantes\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/hubert\/\" rel=\"author\">Hubert Reys<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2024-12-21T12:30:17+01:00\">21 d\u00e9cembre 2024<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30946\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/electeur-mais-citoyen\/\" class=\"_self cvplbd\" target=\"_self\" >\u00c9lecteur mais citoyen<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/electeur-mais-citoyen\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"\u00c9lecteur mais citoyen\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2024\/12\/Urne-Image-par-Tumisu-de-Pixabay.png?resize=642%2C454&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">il s\u2019agit de repenser la participation citoyenne \u00e0 la lumi\u00e8re des exigences d'une d\u00e9lib\u00e9ration v\u00e9ritable et faire de l'espace public un v\u00e9ritable creuset de la d\u00e9cision d\u00e9mocratique ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/electeur-mais-citoyen\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/laurent\/\" rel=\"author\">Laurent Fabas<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2024-12-21T12:30:04+01:00\">21 d\u00e9cembre 2024<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-26ea643e4m\">#pt-cv-view-54904956ml  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-54904956ml.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-54904956ml.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-54904956ml.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-54904956ml .pt-cv-title a, #pt-cv-view-54904956ml  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-54904956ml  .pt-cv-title a:hover, #pt-cv-view-54904956ml  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-54904956ml .pt-cv-content , #pt-cv-view-54904956ml  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-54904956ml  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-54904956ml .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-54904956ml .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-54904956ml .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-54904956ml  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-54904956ml  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-54904956ml li a   { font-weight: 600 !important; }\n#pt-cv-gls-54904956ml li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><br \/>\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#be8552;border-radius:10px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:#f1b885;color:#88360d;border-top-left-radius:8px;border-top-right-radius:8px\">Les Br\u00e8ves du mois<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:8px;border-bottom-right-radius:8px\"><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-scrollable pt-cv-colsys pt-cv-nolf pt-cv-reused\" id=\"pt-cv-view-176b9dand1\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"3\"><div id=\"ca05360i6n\" class=\"pt-cv-carousel pt-cv-slide\" data-ride=\"cvcarousel\" data-interval=5000>\n<div class=\"carousel-inner\"><div class=\"item active\"><div class=\"row\"><div class=\"col-md-4 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30980\"><div class=\"pt-cv-carousel-caption pt-cv-cap-wo-img\"><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/23\/le-nucleaire-une-energie-pilotablevraiment\/\" class=\"_self cvplbd\" target=\"_self\" >Le nucl\u00e9aire : une \u00e9nergie pilotable\u2026Vraiment ?<\/a><\/h2>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/curly\/\" rel=\"author\">Curly Mc Toole<\/a><\/span><span> \/ <\/span><span class=\"entry-date\"> <time datetime=\"2024-12-23T01:33:04+01:00\">23 d\u00e9cembre 2024<\/time><\/span><\/div>\n<div class=\"pt-cv-content\">En cette fin d'ann\u00e9e et de f\u00eates, on peut aussi parler d'un ton un peu badin de la situation du ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/23\/le-nucleaire-une-energie-pilotablevraiment\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-3790306wyo\">#pt-cv-view-176b9dand1 .pt-cv-content-item { padding-left: 5px !important; padding-right: 5px !important; }\n#pt-cv-view-176b9dand1  { margin-left: -5px !important; margin-right: -5px !important; }\n#pt-cv-view-176b9dand1 .pt-cv-carousel-caption { padding-top: 0px !important; padding-left: 0px !important; padding-bottom: 5px !important; padding-right: 0px !important; }\n#pt-cv-view-176b9dand1 .pt-cv-carousel-caption { left : 5px !important }\n#pt-cv-view-176b9dand1 .carousel-control.left { right : 40px }\n#pt-cv-view-176b9dand1 .pt-cv-carousel-caption { right : 5px !important }\n#pt-cv-view-176b9dand1 .carousel-control.right { right : 5px }\n#pt-cv-view-176b9dand1 .row {margin: 0 0 !important}\n#pt-cv-view-176b9dand1  .pt-cv-carousel-caption   { background-color: rgba(234,212,86,0.2) !important; }\n#pt-cv-view-176b9dand1.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-176b9dand1.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-176b9dand1.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-176b9dand1 .pt-cv-title a, #pt-cv-view-176b9dand1  .panel-title { font-family: 'Nunito', Arial, serif !important; font-size: 14px !important; color: #cc2e2e !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-176b9dand1  .pt-cv-title a:hover, #pt-cv-view-176b9dand1  .panel-title:hover   { color: rgba(204,46,46,0.41) !important; }\n#pt-cv-view-176b9dand1 .pt-cv-content , #pt-cv-view-176b9dand1  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 12px !important; line-height: 1.3 !important; }\n#pt-cv-view-176b9dand1  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(214,214,214,0.77) !important; }\n#pt-cv-view-176b9dand1 .pt-cv-meta-fields * { font-size: 12px !important; line-height: 1.3 !important; }\n#pt-cv-view-176b9dand1 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-176b9dand1 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-176b9dand1  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-176b9dand1  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-176b9dand1 li a   { font-weight: 600 !important; }\n#pt-cv-gls-176b9dand1 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Nunito' rel='stylesheet' type='text\/css'> <br><\/div><\/div><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-2-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-0a21f34gl7\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30902\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/remarques-a-la-suite-dune-visite-de-latelier-de-loic-trevelot\/\" class=\"_self cvplbd\" target=\"_self\" >Remarques suite \u00e0 une visite de l\u2019atelier du plasticien Lo\u00efc Tr\u00e9velot<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/remarques-a-la-suite-dune-visite-de-latelier-de-loic-trevelot\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Remarques suite \u00e0 une visite de l\u2019atelier du plasticien Lo\u00efc Tr\u00e9velot\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2024\/12\/C-hez-Loic-Trevelot.jpg?resize=814%2C377&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Le processus fascinant d'un chaos d'\u00e9nergies qui se concr\u00e9tise en formes, mati\u00e8res, vibrations ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/remarques-a-la-suite-dune-visite-de-latelier-de-loic-trevelot\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2024-12-21T12:30:04+01:00\">21 d\u00e9cembre 2024<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30928\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/une-recette-de-cuisine-simple-et-delicieuse-pour-les-fetes\/\" class=\"_self cvplbd\" target=\"_self\" >Une recette de cuisine simple et d\u00e9licieuse pour les f\u00eates<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/une-recette-de-cuisine-simple-et-delicieuse-pour-les-fetes\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"Une recette de cuisine simple et d\u00e9licieuse pour les f\u00eates\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2024\/12\/Quenelle-sauce-Nantua-2.jpg?resize=554%2C506&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Et pourquoi pas en cette p\u00e9riode de f\u00eates pr\u00e9parer un plat simple go\u00fbteux, rapide \u00e0 pr\u00e9parer et tout de m\u00eame un peu classe qui laisse le temps \u00e0 la cuisini\u00e8re ou au cuisinier d\u2019\u00eatre avec ses proches\u2026 Voici dans une version all\u00e9g\u00e9e (*) pr\u00e9sent\u00e9e par Sophie\u00a0: Les quenelles de brochet sauce Nantua \u00e0 la sortie du four (photo S.M) Ingr\u00e9dients\u00a0(pour 2 ou 3 personnes selon app\u00e9tit) : 6 quenelles achet\u00e9es ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/une-recette-de-cuisine-simple-et-delicieuse-pour-les-fetes\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/sophie\/\" rel=\"author\">Sophie Masini<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2024-12-21T12:30:59+01:00\">21 d\u00e9cembre 2024<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-255fa835ym\">#pt-cv-view-0a21f34gl7  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-0a21f34gl7.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-0a21f34gl7.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-0a21f34gl7.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-0a21f34gl7 .pt-cv-title a, #pt-cv-view-0a21f34gl7  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-0a21f34gl7  .pt-cv-title a:hover, #pt-cv-view-0a21f34gl7  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-content , #pt-cv-view-0a21f34gl7  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-0a21f34gl7  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-0a21f34gl7 .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-0a21f34gl7  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-0a21f34gl7  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-0a21f34gl7 li a   { font-weight: 600 !important; }\n#pt-cv-gls-0a21f34gl7 li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-3-content\">\n\t\t\t\t<p style=\"text-align: justify; color: #966400; font-size: 85%;\"><em>Cette rubrique, cr\u00e9\u00e9e en Novembre 2021 \u00e0 l'occasion de la campagne 2022 pour l'\u00e9lection du Pr\u00e9sident de la R\u00e9publique Fran\u00e7aise, vous propose des articles visant \u00e0 nourrir la r\u00e9flexion et l'engagement sur un n\u00e9cessaire changement de nos institutions politiques.&nbsp;<br \/>\n<\/em><\/p>\n<p style=\"text-align: justify; color: #966400; font-size: 85%;\"><em>Vous trouverez ici les articles de l'\u00e9dition en cours. Pour retrouver l'ensemble des articles parus au fil des diff\u00e9rentes \u00e9ditions, veuillez vous rendre <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/pages-visibles\/dossiers\/changer-institutions-politiques\/\">dans le dossier correspondant<\/a>.<\/em><\/p>\n<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-nolf pt-cv-shadow pt-cv-no-bb pt-cv-content-hover effect-ud pt-cv-overlay-top pt-cv-reused\" id=\"pt-cv-view-48ee47btyo\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"2\"><div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30946\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/electeur-mais-citoyen\/\" class=\"_self cvplbd\" target=\"_self\" >\u00c9lecteur mais citoyen<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/electeur-mais-citoyen\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"\u00c9lecteur mais citoyen\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2024\/12\/Urne-Image-par-Tumisu-de-Pixabay.png?resize=642%2C454&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">il s\u2019agit de repenser la participation citoyenne \u00e0 la lumi\u00e8re des exigences d'une d\u00e9lib\u00e9ration v\u00e9ritable et faire de l'espace public un v\u00e9ritable creuset de la d\u00e9cision d\u00e9mocratique ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/electeur-mais-citoyen\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/laurent\/\" rel=\"author\">Laurent Fabas<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2024-12-21T12:30:04+01:00\">21 d\u00e9cembre 2024<\/time><\/span><\/div><\/div><\/div>\n<div class=\"col-md-6 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"30932\"><div class='pt-cv-pinmas'><h2 class=\"pt-cv-title\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/la-france-un-systeme-politique-en-panne\/\" class=\"_self cvplbd\" target=\"_self\" >La France, un syst\u00e8me politique en panne ?<\/a><\/h2>\n<div class=\"pt-cv-hover-wrapper\"><a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/la-france-un-systeme-politique-en-panne\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img decoding=\"async\" src=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow cvp-substitute no-lazyload  cvplazy\" alt=\"La France, un syst\u00e8me politique en panne ?\" title=\"\" data-no-lazy=\"1\" data-cvpsrc=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2024\/12\/mouvement-pour-la-democratier-place-Tien-En-Men-Pekin-1989-2-Image-par-Lola-Anamon-de-Pixabay.jpg?resize=787%2C438&amp;ssl=1\" \/><\/a><div class=\"pt-cv-mask\"><div class=\"pt-cv-animation-left pt-cv-content\">Penser le fonctionnement d\u00e9mocratique de notre pays c\u2019est penser d\u2019abord \u00e0 sa d\u00e9centralisation et \u00e0 la d\u00e9concentration de ses pouvoirs de ses services et de son \u00e9conomie ... <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2024\/12\/21\/la-france-un-systeme-politique-en-panne\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Lire la suite<\/a><\/div><\/div><\/div>\n<div class=\"pt-cv-meta-fields\"><span class=\"author\"><span class=\"glyphicon glyphicon-user\"><\/span> <a href=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/author\/redact\/\" rel=\"author\">La R\u00e9daction du Clairon de l'Atax<\/a><\/span><span class=\"entry-date\"><span class=\"glyphicon glyphicon-calendar\"><\/span> <time datetime=\"2024-12-21T12:30:26+01:00\">21 d\u00e9cembre 2024<\/time><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-be78235z0b\">#pt-cv-view-48ee47btyo  .pt-cv-pinmas   { background-color: #fff8ed !important; }\n#pt-cv-view-48ee47btyo.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-48ee47btyo.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-48ee47btyo.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; }\n#pt-cv-view-48ee47btyo .pt-cv-title a, #pt-cv-view-48ee47btyo  .panel-title { font-family: 'Oswald', Arial, serif !important; font-size: 18px !important; color: #a52e26 !important; font-weight: 600 !important; display: block !important; text-align: center !important; clear: both !important; line-height: 0,5 !important; }\n#pt-cv-view-48ee47btyo  .pt-cv-title a:hover, #pt-cv-view-48ee47btyo  .panel-title:hover   { font-size: 18px !important; color: rgba(204,46,46,0.41) !important; line-height: 0,5 !important; }\n#pt-cv-view-48ee47btyo .pt-cv-content , #pt-cv-view-48ee47btyo  .pt-cv-content *:not(.pt-cv-readmore):not(style):not(script) { font-size: 13px !important; line-height: 1.3 !important; color: #a52e26 !important; }\n#pt-cv-view-48ee47btyo  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(255,248,237,0.85) !important; }\n#pt-cv-view-48ee47btyo .pt-cv-meta-fields * { font-size: 11px !important; line-height: 1.3 !important; color: #a52e26 !important; font-weight: 600 !important; }\n#pt-cv-view-48ee47btyo .pt-cv-readmore  { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-48ee47btyo .pt-cv-readmore:hover  { color: #ff7a7a !important; font-weight: 600 !important; }\n#pt-cv-view-48ee47btyo  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-48ee47btyo  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-gls-48ee47btyo li a   { font-weight: 600 !important; }\n#pt-cv-gls-48ee47btyo li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }<\/style>\r\n\t\t\t<link href='\/\/fonts.googleapis.com\/css?family=Oswald' rel='stylesheet' type='text\/css'> <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"iw-so-tabs-panel\" id=\"ink-tabs-828010003-4-content\">\n\t\t\t\t<p><div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys pt-cv-post-border pt-cv-reused\" id=\"pt-cv-view-8090fb6z9g\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page cv-npf\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"0\"><div class='pt-cv-ifield'><div class=\"pt-cv-no-post\">Aucune publication trouv\u00e9e.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-fbb1e6bcso\">#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-width: 1px; border-left-width: 1px }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-style: solid; border-left-style: solid }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border { margin: 0; border-top-color: #ede0ce; border-left-color: #ede0ce }\n#pt-cv-view-8090fb6z9g.pt-cv-post-border .pt-cv-content-item   { border-right-width: 1px; border-bottom-width: 1px; border-right-style: solid; border-bottom-style: solid; border-right-color: #ede0ce; border-bottom-color: #ede0ce; }\n#pt-cv-view-8090fb6z9g .pt-cv-title a, #pt-cv-view-8090fb6z9g  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-8090fb6z9g  .pt-cv-hover-wrapper::before   { background-color: rgba(0,0,0,.3) !important; }\n#pt-cv-view-8090fb6z9g  .pt-cv-content-item:hover .pt-cv-hover-wrapper::before   { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-8090fb6z9g:not(.pt-cv-nohover) .pt-cv-mask *   { color: #fff; }\n#pt-cv-view-8090fb6z9g .pt-cv-carousel-caption  { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-meta-fields * { color: #dd3333 !important; font-weight: 600 !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-specialp { background-color: #CC3333 !important }\n#pt-cv-view-8090fb6z9g .pt-cv-specialp * { color: #fff !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-pficon  { color: #bbb !important; }\n#pt-cv-view-8090fb6z9g  .add_to_cart_button, #pt-cv-view-8090fb6z9g  .add_to_cart_button *   { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-8090fb6z9g  .woocommerce-onsale   { color: #ffffff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-8090fb6z9g  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-8090fb6z9g  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-8090fb6z9g'] .active.pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .active .pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .selected.pt-cv-filter-option, [id^='pt-cv-filter-bar-8090fb6z9g'] .dropdown-toggle   { color: #fff !important; background-color: #00aeef !important; }\n[id^='pt-cv-filter-bar-8090fb6z9g'] .pt-cv-filter-title   { color: #fff !important; background-color: #00aeef !important; }\n#pt-cv-gls-8090fb6z9g li a.pt-active   { color: #fff !important; background-color: #ff5a5f !important; }\n#pt-cv-view-8090fb6z9g .pt-cv-gls-header  { color: #fff !important; background-color: #00aeef !important; }<\/style>\r\n\t\t\t <br><\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-30836-3-2\"  class=\"panel-grid-cell\" ><div id=\"panel-30836-3-2-0\" class=\"so-panel widget widget_search panel-first-child\" data-index=\"5\" >\r\n<form role=\"search\" method=\"get\" id=\"searchform\" class=\"search-form\" action=\"https:\/\/le-clairon-nouveau.fr\/wordpress\/\">\r\n    <div class=\"search-form-wrap\">\r\n\t\t<input type=\"text\" value=\"\" name=\"s\" id=\"s\" class=\"search-form-input\" placeholder=\"Recherche..\" \/>\r\n        <input type=\"submit\" id=\"searchsubmit\" class=\"button submit-button\" value=\"&#xf179;\" \/>\r\n    <\/div>\r\n<\/form><\/div><div id=\"panel-30836-3-2-1\" class=\"so-panel widget widget_ai1ec_agenda_widget panel-last-child\" data-index=\"6\" ><div class=\"une-agenda panel-widget-style panel-widget-style-for-30836-3-2-1\" >\n\n\t<h3 class=\"widget-title\">\u00c9v\u00e8nements en cours et \u00e0 venir<\/h3>\n\n<style>\n<!--\n\n-->\n<\/style>\n<div class=\"timely ai1ec-agenda-widget-view ai1ec-clearfix\">\n\n\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;17-5-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Mai<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">17<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1300\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1300\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1300\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1300\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tMai 17 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1300\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;24-5-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Mai<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">24<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1301\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1301\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1301\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1301\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tMai 24 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1301\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;31-5-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Mai<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">31<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1302\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1302\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1302\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1302\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tMai 31 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1302\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;7-6-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Juin<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">7<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1303\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1303\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1303\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1303\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tJuin 7 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1303\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;14-6-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Juin<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">14<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1304\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1304\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1304\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1304\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tJuin 14 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1304\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;21-6-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Juin<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">21<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1305\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1305\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1305\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1305\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tJuin 21 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1305\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;28-6-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Juin<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">28<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1306\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1306\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1306\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1306\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tJuin 28 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1306\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;5-7-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Juil<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">5<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1307\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1307\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1307\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1307\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tJuil 5 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1307\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;12-7-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Juil<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">12<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1308\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1308\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1308\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1308\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tJuil 12 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1308\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"ai1ec-date\n\t\t\t\t\t\">\n\t\t\t\t\t<a class=\"ai1ec-date-title ai1ec-load-view\"\n\t\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;action&#x7E;oneday&#x2F;exact_date&#x7E;19-7-2026&#x2F;\">\n\t\t\t\t\t\t<div class=\"ai1ec-month\">Juil<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-day\">19<\/div>\n\t\t\t\t\t\t<div class=\"ai1ec-weekday\">dim<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-year\">2026<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"ai1ec-date-events\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-event\n\t\t\t\t\t\t\t\t\tai1ec-event-id-21739\n\t\t\t\t\t\t\t\t\tai1ec-event-instance-id-1309\n\t\t\t\t\t\t\t\t\t\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1309\"\n\t\t\t\t\t\t\t\t\t\tclass=\"ai1ec-popup-trigger ai1ec-load-event\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-time\">\n\t\t\t\t\t\t\t\t\t\t\t\t9:30\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-title\">\n\t\t\t\t\t\t\t\t\t\t\tMarch&eacute; en plein air\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t<div class=\"ai1ec-popover ai1ec-popup \n\tai1ec-event-instance-id-1309\">\n\n\t\t\n\t<span class=\"ai1ec-popup-title\">\n\t\t<a href=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1309\"\n\t\t   class=\"ai1ec-load-event\"\n\t\t\t>March&eacute; en plein air<\/a>\n\t\t\t\t\t<span class=\"ai1ec-event-location\"\n\t\t\t\t>@ St Nazaire d&#039;Aude<\/span>\n\t\t\t\t\t<\/span>\n\n\t\n\t<div class=\"ai1ec-event-time\">\n\t\t\t\t\tJuil 19 @ 9:30 \u2013 12:30\n\t\t\t<\/div>\n\n\t\t\t<a class=\"ai1ec-load-event\"\n\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;blog&#x2F;&#x00E9;v&#x00E8;nement&#x2F;21739&#x2F;&#x3F;instance_id&#x3D;1309\">\n\t\t\t<div class=\"ai1ec-event-avatar timely  ai1ec-content_img ai1ec-portrait\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/05\/affiche-marche%CC%81-65-001.jpg?resize=509%2C701&#038;ssl=1\" alt=\"March\u00e9 en plein air @ St Nazaire d&#039;Aude | Saint-Nazaire-d&#039;Aude | Occitanie | France\" width=\"509\" height=\"701\" \/><\/div>\n\t\t<\/a>\n\t\n\t\n<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t \t\t<\/div>\n\t \n\t\t\t<div class=\"ai1ec-subscribe-buttons-widget\">\n\t\t\t\t\t\t\t<a class=\"ai1ec-btn ai1ec-btn-default ai1ec-btn-xs ai1ec-pull-right\n\t\t\t\t\tai1ec-calendar-link\"\n\t\t\t\t\thref=\"https&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;pages-visibles&#x2F;calendar&#x2F;\">\n\t\t\t\t\tVoir le calendrier\n\t\t\t\t\t<i class=\"ai1ec-fa ai1ec-fa-arrow-right\"><\/i>\n\t\t\t\t<\/a>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"ai1ec-subscribe-dropdown ai1ec-dropdown ai1ec-btn\n\tai1ec-btn-default ai1ec-btn-xs\">\n\t<span role=\"button\" class=\"ai1ec-dropdown-toggle ai1ec-subscribe\"\n\t\t\tdata-toggle=\"ai1ec-dropdown\">\n\t\t<i class=\"ai1ec-fa ai1ec-icon-rss ai1ec-fa-lg ai1ec-fa-fw\"><\/i>\n\t\t<span class=\"ai1ec-hidden-xs\">\n\t\t\t\t\t\t\tAjouter\n\t\t\t\t\t\t<span class=\"ai1ec-caret\"><\/span>\n\t\t<\/span>\n\t<\/span>\n\t\t\t<ul class=\"ai1ec-dropdown-menu ai1ec-pull-left\" role=\"menu\">\n\t\t<li>\n\t\t\t<a class=\"ai1ec-tooltip-trigger ai1ec-tooltip-auto\" target=\"_blank\"\n\t\t\t\tdata-placement=\"right\" title=\"Copiez cette URL pour votre propre calendrier Timely ou cliquez pour l\u2019ajouter \u00e0 votre calendrier de texte enrichi\"\n\t\t\t\thref=\"http&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;&#x3F;plugin&#x3D;all-in-one-event-calendar&amp;controller&#x3D;ai1ec_exporter_controller&amp;action&#x3D;export_events\">\n\t\t\t\t<i class=\"ai1ec-fa ai1ec-fa-lg ai1ec-fa-fw ai1ec-icon-timely\"><\/i>\n\t\t\t\tAjouter au calendrier Timely\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<a class=\"ai1ec-tooltip-trigger ai1ec-tooltip-auto\" target=\"_blank\"\n\t\t\t  data-placement=\"right\" title=\"Abonnez-vous \u00e0 ce calendrier dans votre agenda Google\"\n\t\t\t  href=\"https:\/\/www.google.com\/calendar\/render?cid=http&#x25;3A&#x25;2F&#x25;2Fle-clairon-nouveau.fr&#x25;2Fwordpress&#x25;2F&#x25;3Fplugin&#x25;3Dall-in-one-event-calendar&#x25;26controller&#x25;3Dai1ec_exporter_controller&#x25;26action&#x25;3Dexport_events&#x25;26no_html&#x25;3Dtrue&#x25;26&#x25;26\">\n\t\t\t\t<i class=\"ai1ec-fa ai1ec-icon-google ai1ec-fa-lg ai1ec-fa-fw\"><\/i>\n\t\t\t\tAjouter \u00e0 Google\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<a class=\"ai1ec-tooltip-trigger ai1ec-tooltip-auto\" target=\"_blank\"\n\t\t\t  data-placement=\"right\" title=\"Abonnez-vous \u00e0 ce calendrier dans MS Outlook\"\n\t\t\t  href=\"webcal&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;&#x3F;plugin&#x3D;all-in-one-event-calendar&amp;controller&#x3D;ai1ec_exporter_controller&amp;action&#x3D;export_events&amp;no_html&#x3D;true\">\n\t\t\t\t<i class=\"ai1ec-fa ai1ec-icon-windows ai1ec-fa-lg ai1ec-fa-fw\"><\/i>\n\t\t\t\tAjouter \u00e0 Outlook\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<a class=\"ai1ec-tooltip-trigger ai1ec-tooltip-auto\" target=\"_blank\"\n\t\t\t  data-placement=\"right\" title=\"Abonnez-vous \u00e0 ce calendrier dans votre agenda Apple\u00a0\/\u00a0iCal\"\n\t\t\t  href=\"webcal&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;&#x3F;plugin&#x3D;all-in-one-event-calendar&amp;controller&#x3D;ai1ec_exporter_controller&amp;action&#x3D;export_events&amp;no_html&#x3D;true\">\n\t\t\t\t<i class=\"ai1ec-fa ai1ec-icon-apple ai1ec-fa-lg ai1ec-fa-fw\"><\/i>\n\t\t\t\tAjouter au calendrier Apple\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t<li>\n\t\t\t\t\t\t<a class=\"ai1ec-tooltip-trigger ai1ec-tooltip-auto\"\n\t\t\t  data-placement=\"right\" title=\"Abonnez-vous \u00e0 ce calendrier dans un autre calendrier en texte brut\"\n\t\t\t  href=\"http&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;&#x3F;plugin&#x3D;all-in-one-event-calendar&amp;controller&#x3D;ai1ec_exporter_controller&amp;action&#x3D;export_events&amp;no_html&#x3D;true\">\n\t\t\t\t<i class=\"ai1ec-fa ai1ec-icon-calendar ai1ec-fa-fw\"><\/i>\n\t\t\t\tAjouter \u00e0 un autre calendrier\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<a class=\"ai1ec-tooltip-trigger ai1ec-tooltip-auto\"\n\t\t\t  data-placement=\"right\" title=\"\"\n\t\t\t  href=\"http&#x3A;&#x2F;&#x2F;le-clairon-nouveau.fr&#x2F;wordpress&#x2F;&#x3F;plugin&#x3D;all-in-one-event-calendar&amp;controller&#x3D;ai1ec_exporter_controller&amp;action&#x3D;export_events&xml=true\">\n\t\t\t\t<i class=\"ai1ec-fa ai1ec-fa-file-text ai1ec-fa-lg ai1ec-fa-fw\"><\/i>\n\t\t\t\tExporter vers XML\n\t\t\t<\/a>\n\t\t<\/li>\n\t<\/ul>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t \n<\/div>\n\n\n\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-30836-4\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-30836-4\" data-stretch-type=\"full-width-stretch\" ><div id=\"pgc-30836-4-0\"  class=\"panel-grid-cell\" ><div class=\"panel-cell-style panel-cell-style-for-30836-4-0\" ><div id=\"panel-30836-4-0-0\" class=\"so-panel widget widget_cl-popup widget-cl-popup panel-first-child\" data-index=\"7\" ><div class=\"panel-widget-style panel-widget-style-for-30836-4-0-0\" ><div class=\"cl-popup align_center\"><a href=\"javascript:void(0)\" class=\"cl-popup-trigger type_btn cl-btn\" style=\"color:#eae6dc;background-color:#997855;\"><span>M\u00e9dias recommand\u00e9s par le Clairon<\/span><\/a><div class=\"cl-popup-overlay\" style=\"background-color:rgba(2,0,0,0.67);\"><\/div><div class=\"cl-popup-wrap\"><div class=\"cl-popup-box size_l animation_flipVer\" style=\"border-radius:10px;\"><div class=\"cl-popup-box-h\"><div class=\"cl-popup-box-title\" style=\"color:#eae6dc;background-color:#997855;\">M\u00e9dias recommand\u00e9s par le Clairon<\/div><div class=\"cl-popup-box-content\" style=\"color:#333333;background-color:#ffffff;\"><p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 12pt;\">De nombreux lecteurs du Clairon regrettent de ne pas avoir acc\u00e8s \u00e0 des m\u00e9dias qu\u2019ils souhaitent objectifs. Il nous a paru utile de leur proposer une liste de m\u00e9dias qui, comme nous, ont pour projet \u00e9ditorial de faire r\u00e9fl\u00e9chir leurs lecteurs, leurs auditeurs ou leurs spectateurs. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 12pt;\">Ce qui nous importe, c\u2019est qu\u2019ils ne soient pas des outils de formatage au service d\u2019une cause ou d\u2019une autre, mais qu\u2019ils contribuent \u00e0 ce que chaque individu puisse faire \u00e9voluer ses id\u00e9es&nbsp; en toute conscience.<\/span><\/p>\n<p><span style=\"color: #000000; font-size: 12pt;\">Les m\u00e9dias s\u00e9lectionn\u00e9s r\u00e9sultent des choix de la r\u00e9daction du Clairon.<br>\nCette s\u00e9lection n\u2019est pas d\u00e9finitive, elle peut \u00e9voluer.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><em><strong>Bien \u00e9videmment, la publicit\u00e9 que nous faisons pour <span class='tooltipsall tooltip_post_id_29829 classtoolTips180'>ces<\/span> m\u00e9dias est exclusivement le fruit de notre conviction de leur int\u00e9r\u00eat pour nos lecteurs.<br>\n<span style=\"text-decoration: underline;\">Elle est donc gratuite<\/span> et ne b\u00e9n\u00e9ficie d'aucun retour de leur part, de quelque sorte que ce soit.<\/strong><\/em><\/span><\/p>\n<p><span style=\"color: #000000; font-size: 12pt;\"><em>En cliquant sur un logo, vous acc\u00e9dez au site du m\u00e9dia dans un nouvel onglet de votre navigateur.<\/em><\/span><\/p><\/div><div class=\"cl-popup-box-closer\" style=\"color:#eae6dc;\"><\/div><\/div><\/div><div class=\"cl-popup-closer\"><\/div><\/div><\/div><\/div><\/div><div id=\"panel-30836-4-0-1\" class=\"so-panel widget widget_sow-image-grid panel-last-child\" data-index=\"8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image-grid so-widget-sow-image-grid-default-8f674e2ace91-30836\"\n\t\t\t\n\t\t>\t<div\n\t\tclass=\"sow-image-grid-wrapper\"\n\t\tdata-max-width=\"120\"\t\t\t>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.bastamag.net\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"489\" height=\"269\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-basta-ombre.png?fit=489%2C269&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Excellent magazine gratuit en ligne, soutenu \u00e0 parts \u00e9gales par ses lecteurs et par des fondations - Existe depuis 2008 - Informations dans les domaines \u00e9conomique, social et environnemental - Son orientation ? L&#039;int\u00e9r\u00eat g\u00e9n\u00e9ral&quot;\" title=\"Basta !\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-basta-ombre.png?w=489&amp;ssl=1 489w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-basta-ombre.png?resize=300%2C165&amp;ssl=1 300w\" sizes=\"auto, (max-width: 489px) 100vw, 489px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.portail.bastamag.net\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"329\" height=\"107\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/Logo-Basta-Portail-ML-ombre.png?fit=329%2C107&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Initi\u00e9 par Basta !, ce portail vous donne acc\u00e8s \u00e0 de nombreux media alternatifs, peu connus du grand public mais dignes d&#039;int\u00e9r\u00eat&quot;\" title=\"Portail des media libres\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/Logo-Basta-Portail-ML-ombre.png?w=329&amp;ssl=1 329w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/Logo-Basta-Portail-ML-ombre.png?resize=300%2C98&amp;ssl=1 300w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.reporterre.net\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"538\" height=\"261\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-reporterre-ombre.png?fit=538%2C261&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"&quot;Le quotidien de l&#039;\u00e9cologie&quot; - Lanc\u00e9 en 2007 par le journaliste Herv\u00e9 Kempf, ce site gratuit d&#039;actualit\u00e9s traite principalement de probl\u00e9matiques environnementales &quot;\" title=\"Reporterre\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-reporterre-ombre.png?w=538&amp;ssl=1 538w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-reporterre-ombre.png?resize=300%2C146&amp;ssl=1 300w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.actu-environnement.com\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"331\" height=\"219\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Actu-Environnement-ombre.png?fit=331%2C219&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Depuis 2003, ce site de presse d\u00e9livre quotidiennement des informations sp\u00e9cialis\u00e9es sur les secteurs de l\u2019Environnement : d\u00e9chets, eau, \u00e9nergie, risques, am\u00e9nagement, biodiversit\u00e9, etc. Il est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 de presse ind\u00e9pendante CogiTerra&quot;\" title=\"Actu-Environnement\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Actu-Environnement-ombre.png?w=331&amp;ssl=1 331w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Actu-Environnement-ombre.png?resize=300%2C198&amp;ssl=1 300w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.agoravox.fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"95\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Agoravox-ombre.png?fit=350%2C95&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"M\u00e9dia citoyen, AgoraVox propose \u00e0 tout citoyen de devenir r\u00e9dacteur, en vue de mettre librement \u00e0 disposition de ses lecteurs des informations th\u00e9matiques in\u00e9dites, d\u00e9tect\u00e9es par les citoyens.&quot;\" title=\"AgoraVox\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Agoravox-ombre.png?w=350&amp;ssl=1 350w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Agoravox-ombre.png?resize=300%2C81&amp;ssl=1 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mediapart.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"199\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Mediapart-ombre.png?fit=499%2C199&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"&quot;Seuls nos lecteurs peuvent nous acheter&quot; - Ce quotidien payant d&#039;actualit\u00e9 en ligne, que l&#039;on ne pr\u00e9sente plus tant il est connu bien au-del\u00e0 de son lectorat, est, depuis 2008, une r\u00e9f\u00e9rence en mati\u00e8re d&#039;information et d&#039;investigation&quot;\" title=\"Mediapart\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Mediapart-ombre.png?w=499&amp;ssl=1 499w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Mediapart-ombre.png?resize=300%2C120&amp;ssl=1 300w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lemonde.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"351\" height=\"110\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Le-Monde-ombre.png?fit=351%2C110&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Quotidien g\u00e9n\u00e9raliste du soir, Le Monde a \u00e9t\u00e9 fond\u00e9 par Hubert Beuve-Mery en 1944. Edit\u00e9 initialement sur support papier, il est diffus\u00e9 depuis plusieurs ann\u00e9es sur l&#039;internet.&quot;\" title=\"Le Monde\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Le-Monde-ombre.png?w=351&amp;ssl=1 351w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Le-Monde-ombre.png?resize=300%2C94&amp;ssl=1 300w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.monde-diplomatique.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"433\" height=\"116\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Diplo-ombre.png?fit=433%2C116&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Fond\u00e9 en 1954 par Hubert Beuve-M\u00e9ry, le &quot;Diplo&quot;, initialement destin\u00e9  aux cercles diplomatiques, est un mensuel payant,combinant analyses, enqu\u00eates et reportages qui s&#039;affirme comme un &quot;journal de r\u00e9f\u00e9rence pour tous ceux qui veulent comprendre le monde, mais aussi le changer&quot; - R\u00e9guli\u00e8rement, des articles en libre acc\u00e8s permettent de se faire  une id\u00e9e juste de la qualit\u00e9 de ce mensuel de haute tenue.&quot;\" title=\"Le Monde Diplomatique\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Diplo-ombre.png?w=433&amp;ssl=1 433w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Diplo-ombre.png?resize=300%2C80&amp;ssl=1 300w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alternatives-economiques.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-AlterEco-ombre.png?fit=240%2C240&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Fond\u00e9 par Denis Clerc en 1980, le mensuel &quot;Alternavives Economiques&quot; s\u2019int\u00e9resse \u00e0 &quot;l\u2019\u00e9conomie comme enjeu collectif et social, \u00e0 travers des th\u00e9matiques vari\u00e9es : Europe, mondialisation, travail, emploi, sant\u00e9, retraites, famille, transports, solidarit\u00e9, \u00e9ducation, cadre de vie, environnement...&quot;. Il est compl\u00e9t\u00e9 par un quotidien payant d&#039;actualit\u00e9s en ligne sur les m\u00eames th\u00e8mes&quot;\" title=\"Alternatives \u00c9conomiques\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-AlterEco-ombre.png?w=240&amp;ssl=1 240w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-AlterEco-ombre.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lecanardenchaine.fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"525\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Canard-Enchaine-ombre.png?fit=630%2C525&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Peu de gens ignorent &quot;le journal satirique paraissant le mercredi&quot;. Et cela depuis plus d&#039;un si\u00e8cle. Chaque semaine, il nous rappelle que &quot;la libert\u00e9 de la presse ne s&#039;use que si l&#039;on ne s&#039;en sert pas&quot;. Derri\u00e8re un ton fantaisiste, ses articles r\u00e9v\u00e8lent des informations parfois explosives et toujours minutieusement v\u00e9rifi\u00e9es. &quot;\" title=\"Le Canard Encha\u00een\u00e9\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Canard-Enchaine-ombre.png?w=630&amp;ssl=1 630w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Canard-Enchaine-ombre.png?resize=300%2C250&amp;ssl=1 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/charliehebdo.fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"361\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Charlie-Hebdo-ombre.png?fit=660%2C361&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Hebdomadaire satirique fran\u00e7ais fond\u00e9 en 1970 par Fran\u00e7ois Cavanna et le professeur Choron, Charlie Hebdo est connu pour ses dessins satiriques, notamment au travers de ses c\u00e9l\u00e8bres couvertures et de celles &quot;auxquelles vous avez \u00e9chapp\u00e9&quot;. Il pratique aussi le journalisme d&#039;investigation, sur des domaines tels que les sectes, les religions, l&#039;extr\u00eame droite, l&#039;islamisme, la politique, la culture.&quot;\" title=\"Charlie Hebdo\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Charlie-Hebdo-ombre.png?w=660&amp;ssl=1 660w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Charlie-Hebdo-ombre.png?resize=300%2C164&amp;ssl=1 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.franceculture.fr\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"243\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Franc-Culture-ombre.png?fit=249%2C243&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"&quot;France Culture, l&#039;esprit d&#039;ouverture&quot; - Baptis\u00e9e sous ce nom en 1963, cette antenne de Radio France est l&#039;une des plus riches qui soit : Actualit\u00e9s, Savoirs, Art et Cr\u00e9ation, Fictions, Documentaires et Conf\u00e9rences, il y en a pour toutes les curiosit\u00e9s. Son site web permet non seulement d&#039;\u00e9couter les \u00e9missions en direct, mais aussi de les r\u00e9\u00e9couter sans limite dans le temps, de lire des articles originaux et d&#039;\u00e9couter des &quot;podcasts&quot; non diffus\u00e9s \u00e0 la radio. Edite aussi la revue trimestrielle &quot;Papiers&quot;&quot;\" title=\"France Culture\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.arte.tv\/fr\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"346\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Arte-ombre.png?fit=604%2C346&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Ouverte en 1992, l&#039;antenne franco-allemande ARTE (Association Relative \u00e0 la T\u00e9l\u00e9vision Europ\u00e9enne) a pour mission de &quot;rapprocher les europ\u00e9ens&quot;. Son projet est de &quot;faire de la culture un lien vivant entre les hommes&quot;. Elle est financ\u00e9e \u00e0 95% par la contribution \u00e0 l&#039;audiovisuel  public en Allemagne et en France. Ses programmes sont disponibles en 6 langues, permettant \u00e0 70% des europ\u00e9ens de la regarder dans leur langue maternelle. 85% de ses programmes sont produits dans l&#039;Union Europ\u00e9enne.&quot;\" title=\"ARTE\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Arte-ombre.png?w=604&amp;ssl=1 604w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Arte-ombre.png?resize=300%2C172&amp;ssl=1 300w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-image-grid-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.acrimed.org\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\" \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer\" \t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"285\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Acrimed-ombre.png?fit=285%2C285&amp;ssl=1\" class=\"sow-image-grid-image_html\" alt=\"Action CRItique MEDia (ACRIMED) est une association fond\u00e9e an 1996 par Pierre Bourdieu et Henri Maler. Son but est d&#039;\u00eatre un &quot;observatoire des media... au service d&#039;une critique ind\u00e9pendante, radicale et intransigeante&quot;&quot;\" title=\"ACRIMED\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Acrimed-ombre.png?w=285&amp;ssl=1 285w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/11\/logo-Acrimed-ombre.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>T\\<\\\/strong\\>raitement\\<strong\\> D\\<\\\/strong\\>es\\<strong\\> N\\<\\\/strong\\>itrates\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>TDN<\/span>\\)<br\/>TH\\<\\\/strong\\>ermal\\<strong\\> O\\<\\\/strong\\>rganic\\<strong\\> R\\<\\\/strong\\>eduction\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>THOR<\/span>\\)\\<\\\/strong\\>\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Proc\u00e9d\u00e9 envisag\u00e9 par la soci\u00e9t\u00e9 AREVA pour retraiter les d\u00e9chets nitrat\u00e9s et radio\\-actifs issus de son activit\u00e9 d'enrichissement de l'uranium, phase I de la pr\u00e9paration du combustible des centrales nucl\u00e9aires\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Cette activit\u00e9 est mise en \u0153uvre dans l'usine de Malv\u00e9si \u00e0 quelques kilom\u00e8tres de Narbonne\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Ce proc\u00e9d\u00e9, potentiellement tr\u00e8s toxique pour la sant\u00e9 et l'environnement, est au centre d'une vive opposition de la part des riverains et \u00e0 laquelle le Clairon s'associe \\(\\<a href\\='https\\:\\\/\\\/le\\-clairon\\-nouveau\\.fr\\\/wordpress\\\/dossiers\\\/dossier\\-malvesi\\-areva\\\/' target\\='_blank' rel\\='noopener'\\>voir notre dossier\\<\\\/a\\> sur le sujet\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips37',tt_store_content,'3610'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \\<strong\\>C\\<\\\/strong\\>ommission de \\<strong\\>R\\<\\\/strong\\>echerche et d'\\<strong\\>I\\<\\\/strong\\>nformations \\<strong\\>I\\<\\\/strong\\>nd\u00e9pendantes sur la \\<strong\\>Rad\\<\\\/strong\\>ioactivit\u00e9 est une association fran\u00e7aise 'loi 1901'\\. Elle emploie une \u00e9quipe d'une douzaine de scientifiques\u00a0 et dispose d'un laboratoire d'analyse agr\u00e9e par le minist\u00e8re de la sant\u00e9 dans le cadre de la protection de l'environnement\\. Son domaine d'intervention est le d\u00e9pistage et \u00e0 l'identification des pollutions radioactives en France comme \u00e0 l'\u00e9tranger\\. Elle se finance par les cotisations de ses membres et la r\u00e9mun\u00e9ration de ses nombreux travaux \\(plus d'un millier depuis sa cr\u00e9ation\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips55',tt_store_content,'7025'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \\<strong\\>C\\<\\\/strong\\>ommission de \\<strong\\>R\\<\\\/strong\\>echerche et d'\\<strong\\>I\\<\\\/strong\\>nformations \\<strong\\>I\\<\\\/strong\\>nd\u00e9pendantes sur la \\<strong\\>Rad\\<\\\/strong\\>ioactivit\u00e9 est une association fran\u00e7aise 'loi 1901'\\. Elle emploie une \u00e9quipe d'une douzaine de scientifiques\u00a0 et dispose d'un laboratoire d'analyse agr\u00e9e par le minist\u00e8re de la sant\u00e9 dans le cadre de la protection de l'environnement\\. Son domaine d'intervention est le d\u00e9pistage et \u00e0 l'identification des pollutions radioactives en France comme \u00e0 l'\u00e9tranger\\. Elle se finance par les cotisations de ses membres et la r\u00e9mun\u00e9ration de ses nombreux travaux \\(plus d'un millier depuis sa cr\u00e9ation\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips55',tt_store_content,'7025'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>Agence Nationale pour la gestion des D\u00e9chets RAdioactifs\\<\\\/strong\\>\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Agence_nationale_pour_la_gestion_des_d%C3%A9chets_radioactifs' target\\='_blank' rel\\='noopener'\\>Voir la fiche Wikipedia de l'ANDRA\\<\\\/a\\><br\/>\\<a href\\='http\\:\\\/\\\/www\\.andra\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>Voir le site de l'agence\\<\\\/a\\>\"; toolTips('.classtoolTips79',tt_store_content,'3612'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>C\\<\\\/strong\\>ommunal d'\\<strong\\>A\\<\\\/strong\\>ction \\<strong\\>S\\<\\\/strong\\>ociale\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Un centre communal d'action sociale \\(<span class='tooltipsall tooltip_post_id_18100 classtoolTips132'>CCAS<\/span>\\) est, en France, un \u00e9tablissement public administr\u00e9 par un conseil d'administration pr\u00e9sid\u00e9 par le maire de la commune\\. Il a pour mission d'animer une action g\u00e9n\u00e9rale de pr\u00e9vention et de d\u00e9veloppement social au sein de la commune en liaison \u00e9troite avec les institutions publiques et priv\u00e9es\\<\\\/p\\>\"; toolTips('.classtoolTips132',tt_store_content,'18100'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br\/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><br\/><br\/>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>tablissement \\<strong\\>F\\<\\\/strong\\>ran\u00e7ais du \\<strong\\>S\\<\\\/strong\\>ang\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p\\>\\<a href\\='https\\:\\\/\\\/www\\.efs\\.sante\\.fr\\\/' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Acc\u00e9der ici au site de l'<span class='tooltipsall tooltip_post_id_21261 classtoolTips150'>EFS<\/span>\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips150',tt_store_content,'21261'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9pertoire \\<strong\\>N\\<\\\/strong\\>ational des \\<strong\\>A\\<\\\/strong\\>ssociations\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips159',tt_store_content,'24374'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(COR\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br\/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;<br\/><br\/>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br\/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;<br\/><br\/>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>\\<span class\\='ILfuVd'\\>La politique agricole commune \\(\\<b\\><span class='tooltipsall tooltip_post_id_11364 classtoolTips174'>PAC<\/span>\\<\\\/b\\>\\) est une politique mise en place \u00e0 l'\u00e9chelle de l'Union europ\u00e9enne\\. \u00c0 l'origine, elle est fond\u00e9e principalement sur des mesures de contr\u00f4le des prix et de subventionnement, visant \u00e0 moderniser et d\u00e9velopper l'agriculture\\.\\<\\\/span\\> \\(source Wikipedia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips174',tt_store_content,'11364'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>H\\<\\\/strong\\>ydrocarbure \\<strong\\>A\\<\\\/strong\\>romatique \\<strong\\>P\\<\\\/strong\\>olycyclique\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Depuis de nombreuses ann\u00e9es, les <span class='tooltipsall tooltip_post_id_20397 classtoolTips184'>HAP<\/span> sont tr\u00e8s \u00e9tudi\u00e9s car ce sont des compos\u00e9s pr\u00e9sents dans tous les milieux environnementaux et qui montrent une forte toxicit\u00e9\\. On a pu \u00e9tablir la canc\u00e9rog\u00e9n\u00e8se de certains HPA, tels que le Benzo\\[a\\]anthrac\u00e8ne, le Chrys\u00e8ne et d'autres\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les HAP proviennent principalement de la combustion \u00e0 haute temp\u00e9rature \\(500\u00b0 C et plus\\) de mati\u00e8res fossiles telles que le bois, le charbon et le p\u00e9trole\\. Dans l'environnement, la production de HAP provient donc&nbsp; du chauffage domestique, de la circulation automobile, des centrales \u00e9lectriques fonctionnant au charbon ou au p\u00e9trole \\('fioul'\\), ainsi que des incin\u00e9rateurs\\.\\<\\\/p\\><br\/>\\<p\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Hydrocarbure_aromatique_polycyclique' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Voir ici l'article Wikipedia consacr\u00e9 aux HAP\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips184',tt_store_content,'20397'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br\/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<br\/><br\/>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<br\/><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br\/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_21204 classtoolTips199'>COV<\/span> \\= Compos\u00e9 Organique Volatile\\<\\\/p\\>\"; toolTips('.classtoolTips199',tt_store_content,'21204'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_24572 classtoolTips211'>MIT<\/span> \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>d\u00e9chets \u00e0 Vie Courte \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips212',tt_store_content,'19201'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br\/>ou<br\/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"<div class='tooltips_youtube_class' ><iframe width='100%' height='100%' src='http:\/\/www.youtube.com\/embed\/terawatt?rel=0&autoplay=1' frameborder='0' allowfullscreen><\/iframe><\/div>\\<p\\>\\<strong\\>TERAWATT \\(<span class='tooltipsall tooltip_post_id_30105 classtoolTips219'>TW<\/span>\\) \\= 1000 000 000 000 <span class='tooltipsall tooltip_post_id_30101 classtoolTips216'>KW<\/span>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips219',tt_store_content,'30105'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\><span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nm<\/span> \\= n\\<\\\/strong\\>ano\\<strong\\>m\\<\\\/strong\\>\u00e8tre \\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<em\\>le <span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nanom\u00e8tre<\/span>, de symbole nm, est une unit\u00e9 de longueur du Syst\u00e8me international\\. C'est un sous\\-multiple du m\u00e8tre, il vaut un milliardi\u00e8me de m\u00e8tre, soit un millioni\u00e8me de millim\u00e8tre\\.\\<\\\/em\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<em\\> 1 nm \\= 10\u207b\u00b3 \u00b5m \\= 10\\<sup\\>\u20136\\<\\\/sup\\> mm \\= 10\\<sup\\>\u20139\\<\\\/sup\\> m\\.\\<\\\/em\\>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips222',tt_store_content,'21736'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script>","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0C&rsquo;\u00e9tait un temps d\u00e9raisonnable&#8230;\u00a0\u00bb (Macron dissout l&rsquo;Assembl\u00e9e Nationale, puis rejette le choix des urnes) \u00ab\u00a0On avait mis les morts \u00e0 table&#8230;\u00a0\u00bb (Macron nomme Barnier puis Bayrou comme premiers ministres) \u00ab\u00a0On faisait des <span class='tooltipsall tooltip_post_id_18357 classtoolTips220'>ch<\/span>\u00e2teaux de sable&#8230;\u00a0\u00bb (Quand la finance dicte les choix politiques) \u00ab\u00a0On prenait les loups pour des chiens&#8230;\u00a0\u00bb (Quand le pouvoir joue avec leLire la suite &rarr;<script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>T\\<\\\/strong\\>raitement\\<strong\\> D\\<\\\/strong\\>es\\<strong\\> N\\<\\\/strong\\>itrates\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>TDN<\/span>\\)<br \/>TH\\<\\\/strong\\>ermal\\<strong\\> O\\<\\\/strong\\>rganic\\<strong\\> R\\<\\\/strong\\>eduction\\<strong\\> \\(<span class='tooltipsall tooltip_post_id_3610 classtoolTips37'>THOR<\/span>\\)\\<\\\/strong\\>\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Proc\u00e9d\u00e9 envisag\u00e9 par la soci\u00e9t\u00e9 AREVA pour retraiter les d\u00e9chets nitrat\u00e9s et radio\\-actifs issus de son activit\u00e9 d'enrichissement de l'uranium, phase I de la pr\u00e9paration du combustible des centrales nucl\u00e9aires\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Cette activit\u00e9 est mise en \u0153uvre dans l'usine de Malv\u00e9si \u00e0 quelques kilom\u00e8tres de Narbonne\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Ce proc\u00e9d\u00e9, potentiellement tr\u00e8s toxique pour la sant\u00e9 et l'environnement, est au centre d'une vive opposition de la part des riverains et \u00e0 laquelle le Clairon s'associe \\(\\<a href\\='https\\:\\\/\\\/le\\-clairon\\-nouveau\\.fr\\\/wordpress\\\/dossiers\\\/dossier\\-malvesi\\-areva\\\/' target\\='_blank' rel\\='noopener'\\>voir notre dossier\\<\\\/a\\> sur le sujet\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips37',tt_store_content,'3610'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \\<strong\\>C\\<\\\/strong\\>ommission de \\<strong\\>R\\<\\\/strong\\>echerche et d'\\<strong\\>I\\<\\\/strong\\>nformations \\<strong\\>I\\<\\\/strong\\>nd\u00e9pendantes sur la \\<strong\\>Rad\\<\\\/strong\\>ioactivit\u00e9 est une association fran\u00e7aise 'loi 1901'\\. Elle emploie une \u00e9quipe d'une douzaine de scientifiques\u00a0 et dispose d'un laboratoire d'analyse agr\u00e9e par le minist\u00e8re de la sant\u00e9 dans le cadre de la protection de l'environnement\\. Son domaine d'intervention est le d\u00e9pistage et \u00e0 l'identification des pollutions radioactives en France comme \u00e0 l'\u00e9tranger\\. Elle se finance par les cotisations de ses membres et la r\u00e9mun\u00e9ration de ses nombreux travaux \\(plus d'un millier depuis sa cr\u00e9ation\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips55',tt_store_content,'7025'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \\<strong\\>C\\<\\\/strong\\>ommission de \\<strong\\>R\\<\\\/strong\\>echerche et d'\\<strong\\>I\\<\\\/strong\\>nformations \\<strong\\>I\\<\\\/strong\\>nd\u00e9pendantes sur la \\<strong\\>Rad\\<\\\/strong\\>ioactivit\u00e9 est une association fran\u00e7aise 'loi 1901'\\. Elle emploie une \u00e9quipe d'une douzaine de scientifiques\u00a0 et dispose d'un laboratoire d'analyse agr\u00e9e par le minist\u00e8re de la sant\u00e9 dans le cadre de la protection de l'environnement\\. Son domaine d'intervention est le d\u00e9pistage et \u00e0 l'identification des pollutions radioactives en France comme \u00e0 l'\u00e9tranger\\. Elle se finance par les cotisations de ses membres et la r\u00e9mun\u00e9ration de ses nombreux travaux \\(plus d'un millier depuis sa cr\u00e9ation\\)\\.\\<\\\/p\\>\"; toolTips('.classtoolTips55',tt_store_content,'7025'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>Agence Nationale pour la gestion des D\u00e9chets RAdioactifs\\<\\\/strong\\>\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Agence_nationale_pour_la_gestion_des_d%C3%A9chets_radioactifs' target\\='_blank' rel\\='noopener'\\>Voir la fiche Wikipedia de l'<span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\<\\\/a\\><br \/>\\<a href\\='http\\:\\\/\\\/www\\.andra\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>Voir le site de l'agence\\<\\\/a\\>\"; toolTips('.classtoolTips79',tt_store_content,'3612'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>C\\<\\\/strong\\>ommunal d'\\<strong\\>A\\<\\\/strong\\>ction \\<strong\\>S\\<\\\/strong\\>ociale\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Un centre communal d'action sociale \\(<span class='tooltipsall tooltip_post_id_18100 classtoolTips132'>CCAS<\/span>\\) est, en France, un \u00e9tablissement public administr\u00e9 par un conseil d'administration pr\u00e9sid\u00e9 par le maire de la commune\\. Il a pour mission d'animer une action g\u00e9n\u00e9rale de pr\u00e9vention et de d\u00e9veloppement social au sein de la commune en liaison \u00e9troite avec les institutions publiques et priv\u00e9es\\<\\\/p\\>\"; toolTips('.classtoolTips132',tt_store_content,'18100'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br \/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><\/p>\n<p>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>tablissement \\<strong\\>F\\<\\\/strong\\>ran\u00e7ais du \\<strong\\>S\\<\\\/strong\\>ang\\<\\\/span\\>\\<\\\/p\\><br \/>\\<p\\>\\<a href\\='https\\:\\\/\\\/www\\.efs\\.sante\\.fr\\\/' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Acc\u00e9der ici au site de l'<span class='tooltipsall tooltip_post_id_21261 classtoolTips150'>EFS<\/span>\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips150',tt_store_content,'21261'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9pertoire \\<strong\\>N\\<\\\/strong\\>ational des \\<strong\\>A\\<\\\/strong\\>ssociations\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips159',tt_store_content,'24374'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"Energies Renouvelables\"; toolTips('.classtoolTips167',tt_store_content,'7758'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br \/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br \/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>\\<span class\\='ILfuVd'\\>La politique agricole commune \\(\\<b\\><span class='tooltipsall tooltip_post_id_11364 classtoolTips174'>PAC<\/span>\\<\\\/b\\>\\) est une politique mise en place \u00e0 l'\u00e9chelle de l'Union europ\u00e9enne\\. \u00c0 l'origine, elle est fond\u00e9e principalement sur des mesures de contr\u00f4le des prix et de subventionnement, visant \u00e0 moderniser et d\u00e9velopper l'agriculture\\.\\<\\\/span\\> \\(source Wikipedia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips174',tt_store_content,'11364'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>E\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>lectricit\u00e9 \\<strong\\>d\\<\\\/strong\\>e \\<strong\\>F\\<\\\/strong\\>rance\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips178',tt_store_content,'7035'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>H\\<\\\/strong\\>ydrocarbure \\<strong\\>A\\<\\\/strong\\>romatique \\<strong\\>P\\<\\\/strong\\>olycyclique\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Depuis de nombreuses ann\u00e9es, les <span class='tooltipsall tooltip_post_id_20397 classtoolTips184'>HAP<\/span> sont tr\u00e8s \u00e9tudi\u00e9s car ce sont des compos\u00e9s pr\u00e9sents dans tous les milieux environnementaux et qui montrent une forte toxicit\u00e9\\. On a pu \u00e9tablir la canc\u00e9rog\u00e9n\u00e8se de certains HPA, tels que le Benzo\\[a\\]anthrac\u00e8ne, le Chrys\u00e8ne et d'autres\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les HAP proviennent principalement de la combustion \u00e0 haute temp\u00e9rature \\(500\u00b0 C et plus\\) de mati\u00e8res fossiles telles que le bois, le charbon et le p\u00e9trole\\. Dans l'environnement, la production de HAP provient donc&nbsp; du chauffage domestique, de la circulation automobile, des centrales \u00e9lectriques fonctionnant au charbon ou au p\u00e9trole \\('fioul'\\), ainsi que des incin\u00e9rateurs\\.\\<\\\/p\\><br \/>\\<p\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Hydrocarbure_aromatique_polycyclique' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Voir ici l'article Wikipedia consacr\u00e9 aux HAP\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips184',tt_store_content,'20397'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br \/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<\/p>\n<p>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br \/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_21204 classtoolTips199'>COV<\/span> \\= Compos\u00e9 Organique Volatile\\<\\\/p\\>\"; toolTips('.classtoolTips199',tt_store_content,'21204'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_24572 classtoolTips211'>MIT<\/span> \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>d\u00e9chets \u00e0 Vie Courte \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips212',tt_store_content,'19201'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br \/>ou<br \/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"<\/p>\n<div class='tooltips_youtube_class' ><iframe width='100%' height='100%' src='http:\/\/www.youtube.com\/embed\/terawatt?rel=0&autoplay=1' frameborder='0' allowfullscreen><\/iframe><\/div>\n<p>\\<p\\>\\<strong\\>TERAWATT \\(<span class='tooltipsall tooltip_post_id_30105 classtoolTips219'>TW<\/span>\\) \\= 1000 000 000 000 <span class='tooltipsall tooltip_post_id_30101 classtoolTips216'>KW<\/span>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips219',tt_store_content,'30105'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\><span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nm<\/span> \\= n\\<\\\/strong\\>ano\\<strong\\>m\\<\\\/strong\\>\u00e8tre \\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<em\\>le <span class='tooltipsall tooltip_post_id_21736 classtoolTips222'>nanom\u00e8tre<\/span>, de symbole nm, est une unit\u00e9 de longueur du Syst\u00e8me international\\. C'est un sous\\-multiple du m\u00e8tre, il vaut un milliardi\u00e8me de m\u00e8tre, soit un millioni\u00e8me de millim\u00e8tre\\.\\<\\\/em\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<em\\> 1 nm \\= 10\u207b\u00b3 \u00b5m \\= 10\\<sup\\>\u20136\\<\\\/sup\\> mm \\= 10\\<sup\\>\u20139\\<\\\/sup\\> m\\.\\<\\\/em\\>\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips222',tt_store_content,'21736'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement ANDRA\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script><\/p>\n","protected":false},"author":1,"featured_media":18234,"parent":1235,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"coauthors":[8],"class_list":["post-30836","page","type-page","status-publish","has-post-thumbnail","hentry","has-thumb"],"acf":[],"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/P9B5TM-81m","_links":{"self":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/30836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=30836"}],"version-history":[{"count":2,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/30836\/revisions"}],"predecessor-version":[{"id":30966,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/30836\/revisions\/30966"}],"up":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/pages\/1235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media\/18234"}],"wp:attachment":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=30836"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/coauthors?post=30836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}