{"id":21546,"date":"2020-04-23T14:44:56","date_gmt":"2020-04-23T12:44:56","guid":{"rendered":"https:\/\/le-clairon-nouveau.fr\/wordpress\/?p=21546"},"modified":"2020-04-23T16:23:46","modified_gmt":"2020-04-23T14:23:46","slug":"ours-64","status":"publish","type":"post","link":"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2020\/04\/23\/ours-64\/","title":{"rendered":"Ours 64"},"content":{"rendered":"<p><span style=\"font-size: 14pt; color: #0000ff;\"><strong>Articles<\/strong><\/span><\/p>\n<p>Arr\u00eat du nucl\u00e9aire 34 (H\u00e9rault)<br \/>\nCatherine Burger (Aude)<br \/>\nCDRSS (Aude)<br \/>\nPhilippe Comte (Aude)<br \/>\nConf\u00e9d\u00e9ration Paysanne (Aude)<br \/>\nJean Cordier (H\u00e9rault)<br \/>\nJean Fran\u00e7ois Lambert (Aude)<br \/>\nSophie Masini (Bas Rhin)<br \/>\nCurly Mac Toole (Paris)<br \/>\nColin Reys (Bas Rhin)<br \/>\nHubert Reys (Aude)<br \/>\nCatherine Schmitt (Paris)<br \/>\nLouise B. Velpeau (Aude)<br \/>\nColette&nbsp; &amp; Daniel Vexenat (Aude)<br \/>\nJean Pierre Vialle (Aude)<br \/>\nLena Waag (Bas Rhin)<br \/>\nDavid Wiker (H\u00e9rault)<\/p>\n<p><strong><span style=\"font-size: 14pt; color: #0000ff;\">R\u00e9daction, \u00c9dition, Publication<br \/>\n<\/span><\/strong><\/p>\n<p>Jean Cordier<br \/>\nHubert Reys<\/p>\n<p><span style=\"color: #0000ff;\"><strong><span style=\"font-size: 14pt;\">Coach<\/span><\/strong><\/span><\/p>\n<div id=\"attachment_19010\" style=\"width: 135px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19010\" class=\"wp-image-19010\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?resize=125%2C187&#038;ssl=1\" alt=\"\" width=\"125\" height=\"187\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?resize=201%2C300&amp;ssl=1 201w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2019\/05\/dundee-daniel-17.jpg?w=685&amp;ssl=1 685w\" sizes=\"auto, (max-width: 125px) 100vw, 125px\" \/><\/a><p id=\"caption-attachment-19010\" class=\"wp-caption-text\">Dundee<\/p><\/div>\n<script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 de \\<strong\\>D\\<\\\/strong\\>\u00e9fense et de \\<strong\\>R\\<\\\/strong\\>econqu\u00eate de la \\<strong\\>S\\<\\\/strong\\>\u00e9curit\u00e9 \\<strong\\>S\\<\\\/strong\\>ociale\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p\\>\\<a href\\='https\\:\\\/\\\/comitesdrss\\.wordpress\\.com\\\/author\\\/comitesdrss\\\/' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Acc\u00e9der ici au site des CDRSS\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips94',tt_store_content,'18645'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(COR\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br\/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<br\/><br\/>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<br\/><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br\/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>MIT \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script>","protected":false},"excerpt":{"rendered":"<p>Articles Arr\u00eat du nucl\u00e9aire 34 (H\u00e9rault) Catherine Burger (Aude) CDRSS (Aude) Philippe Comte (Aude) Conf\u00e9d\u00e9ration Paysanne (Aude) Jean Cordier (H\u00e9rault) Jean Fran\u00e7ois Lambert (Aude) Sophie Masini (Bas Rhin) Curly Mac Toole (Paris) Colin Reys (Bas Rhin) Hubert Reys (Aude) Catherine Schmitt (Paris) Louise B. Velpeau (Aude) Colette&nbsp; &amp; Daniel Vexenat (Aude) Jean Pierre Vialle (Aude)Lire la suite &rarr;<script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 de \\<strong\\>D\\<\\\/strong\\>\u00e9fense et de \\<strong\\>R\\<\\\/strong\\>econqu\u00eate de la \\<strong\\>S\\<\\\/strong\\>\u00e9curit\u00e9 \\<strong\\>S\\<\\\/strong\\>ociale\\<\\\/span\\>\\<\\\/p\\><br \/>\\<p\\>\\<a href\\='https\\:\\\/\\\/comitesdrss\\.wordpress\\.com\\\/author\\\/comitesdrss\\\/' target\\='_blank' rel\\='noopener noreferrer'\\>\\<em\\>Acc\u00e9der ici au site des CDRSS\\<\\\/em\\>\\<\\\/a\\>\\<\\\/p\\>\"; toolTips('.classtoolTips94',tt_store_content,'18645'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(COR\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br \/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<\/p>\n<p>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br \/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>MIT \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"coauthors":[8],"class_list":["post-21546","post","type-post","status-publish","format-standard","hentry","category-uncategorized","edition-edi_00064","type_art-type_art_ours","no-thumb"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9B5TM-5Bw","_links":{"self":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/21546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=21546"}],"version-history":[{"count":0,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/21546\/revisions"}],"wp:attachment":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=21546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=21546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=21546"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/coauthors?post=21546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}