{"id":24340,"date":"2021-04-23T12:30:42","date_gmt":"2021-04-23T10:30:42","guid":{"rendered":"https:\/\/le-clairon-nouveau.fr\/wordpress\/?p=24340"},"modified":"2021-04-20T19:57:06","modified_gmt":"2021-04-20T17:57:06","slug":"wonder-boys","status":"publish","type":"post","link":"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2021\/04\/23\/wonder-boys\/","title":{"rendered":"Wonder Boys"},"content":{"rendered":"<p style=\"text-align: center\">Etats-Unis \/ Allemagne \/ Royaume-Uni \u2013 2000 \u2013 1h50<\/p>\n<p style=\"text-align: center\">Un film de Curtis Hanson avec Michael Douglas, Tobey Maguire, Frances McDormand, Robert Downey Jr.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_24341\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-24341\" class=\"size-medium wp-image-24341\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/04\/Quel-livre-mage-par-Gerd-Altmann-de-Pixabay.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/04\/Quel-livre-mage-par-Gerd-Altmann-de-Pixabay.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/04\/Quel-livre-mage-par-Gerd-Altmann-de-Pixabay.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/04\/Quel-livre-mage-par-Gerd-Altmann-de-Pixabay.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/04\/Quel-livre-mage-par-Gerd-Altmann-de-Pixabay.jpg?resize=600%2C400&amp;ssl=1 600w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/04\/Quel-livre-mage-par-Gerd-Altmann-de-Pixabay.jpg?resize=272%2C182&amp;ssl=1 272w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2021\/04\/Quel-livre-mage-par-Gerd-Altmann-de-Pixabay.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-24341\" class=\"wp-caption-text\"><strong><span style=\"font-size: 8pt\"><em>\u00a0\u00a0\u00a0\u00a0 Quel livre ? image par Gerd Altmann de Pixabay<\/em><\/span><\/strong><\/p><\/div>\n<p style=\"text-align: justify\"><span style=\"font-family: comic sans ms, sans-serif\">C\u2019est l\u2019histoire d\u2019un professeur de lettres \u00e0 la facult\u00e9 de Pittsburgh en panne d\u2019inspiration apr\u00e8s un premier roman prometteur qui tisse une relation amicale avec un de ses \u00e9tudiants talentueux.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: comic sans ms, sans-serif\">Grady Tripp a publi\u00e9 il y a 7ans un premier roman, celui-ci a eu beaucoup de succ\u00e8s et a amen\u00e9 son \u00e9diteur Terry Grabtree \u00e0 attendre avec impatience, un second roman qui tarde malheureusement \u00e0 venir. Tripp est dans une mauvaise passe, sa femme l\u2019a quitt\u00e9, il anime p\u00e9niblement un atelier d\u2019\u00e9criture dans lequel James Leer, un \u00e9tudiant, se distingue par son style mais est peu appr\u00e9ci\u00e9 de ses camarades.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: comic sans ms, sans-serif\">Les \u00e9v\u00e9nements se pr\u00e9cipitent quand Sara, la doyenne de l\u2019universit\u00e9 et accessoirement la ma\u00eetresse de Grady (dont elle est enceinte), l\u2019invite \u00e0 une soir\u00e9e. Grady ira avec son nouvel ami le jeune James.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: comic sans ms, sans-serif\">Le film, lors de sa sortie,\u00a0 en 2000, n\u2019a eu aucun succ\u00e8s \u00e0 deux reprises. Le r\u00e9alisateur et les acteurs sont tous dans une p\u00e9riode \u00e0 succ\u00e8s, le casting est prestigieux et le th\u00e8me du film est tir\u00e9 du roman <span class='tooltipsall tooltip_post_id_6639 classtoolTips46'>\u00e9ponyme<\/span> de Michael Chabon qui est un best-seller. Nouvelle campagne commerciale avec la deuxi\u00e8me sortie en novembre, nouvel \u00e9chec.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: comic sans ms, sans-serif\">Le film obtient toutefois un Oscar avec la chanson \u201cThings Have Changed\u201d, compos\u00e9e par Bob Dylan, un ami de Curtis Hanson.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: comic sans ms, sans-serif\">\u00a0\u00bb\u00a0Wonder Boy \u00a0\u00bb signifie non seulement \u00ab\u00a0un gar\u00e7on merveilleux\u00a0\u00bb mais aussi une personne qui s&rsquo;est fait remarquer avec une \u0153uvre talentueuse et dont le public est en attente d&rsquo;une seconde \u0153uvre qui confirmera alors son talent.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: comic sans ms, sans-serif\">Grady Tripp est dans cette situation, il utilise un objet f\u00e9tiche pour se convaincre qu&rsquo;il r\u00e9ussira \u00e0 terminer une \u0153uvre qu&rsquo;il n&rsquo;en finit pas de finir, il se retrouve flanqu\u00e9 de ce jeune \u00e9tudiant, qui ne cesse de s&rsquo;inventer\u00a0 des histoires et de son \u00e9diteur, gay. Il d\u00e9ambule dans la vie, visite des salons litt\u00e9raires et \u00e9volue dans une ambiance chaotique, parfois incongrue, souvent ubuesque. Immature, \u00e9ternel adolescent, il se cherche, cherche un sens \u00e0 sa vie.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: comic sans ms, sans-serif\">On retrouve un peu l&rsquo;univers des meilleurs films de Woody Allen, ce milieu d&rsquo;intellectuels d\u00e9complex\u00e9s, cette soci\u00e9t\u00e9 am\u00e9ricaine polaris\u00e9e sur le succ\u00e8s et la c\u00e9l\u00e9brit\u00e9. Le tout ponctu\u00e9 par une musique des sixties envo\u00fbtante.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: comic sans ms, sans-serif\">Michael Douglas qui restait persuad\u00e9 que c&rsquo;\u00e9tait l&rsquo;un de ses meilleurs films, y excelle, c&rsquo;est un vrai festival d&rsquo;acteurs et du grand cin\u00e9ma.<\/span><\/p>\n<p style=\"text-align: right\"><em>Patricia Renaud pour le Clairon de l\u2019Atax le 18\/04\/2021<\/em><\/p>\n<script type=\"text\/javascript\"> var tt_store_content = \"\\<span class\\='tlf_cdefinition'\\>Qui porte le m\u00eame nom\\<\\\/span\\><br\/><br\/>\\<em\\>\\<span class\\='tlf_cdefinition'\\>\\(Celui, celle, ce\\) qui donne son nom \u00e0 quelque chose ou \u00e0 quelqu'un, \u00e0 qui l'on se r\u00e9f\u00e8re, que l'on v\u00e9n\u00e8re\\<\\\/span\\>\\<\\\/em\\> \\(source www\\.cnrtl\\.fr\\)\"; toolTips('.classtoolTips46',tt_store_content,'6639'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br\/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><br\/><br\/>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br\/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;<br\/><br\/>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\u00c9cole des<br\/>\\<strong\\>H\\<\\\/strong\\>autes \\<strong\\>\u00c9\\<\\\/strong\\>tudes \\<strong\\>C\\<\\\/strong\\>ommerciales\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips171',tt_store_content,'5214'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script>","protected":false},"excerpt":{"rendered":"<p>Etats-Unis \/ Allemagne \/ Royaume-Uni \u2013 2000 \u2013 1h50 Un film de Curtis Hanson avec Michael Douglas, Tobey Maguire, Frances McDormand, Robert Downey Jr. &nbsp; C\u2019est l\u2019histoire d\u2019un professeur de lettres \u00e0 la facult\u00e9 de Pittsburgh en panne d\u2019inspiration apr\u00e8s un premier roman prometteur qui tisse une relation amicale avec un de ses \u00e9tudiants talentueux.Lire la suite &rarr;<script type=\"text\/javascript\"> var tt_store_content = \"\\<span class\\='tlf_cdefinition'\\>Qui porte le m\u00eame nom\\<\\\/span\\><\/p>\n<p>\\<em\\>\\<span class\\='tlf_cdefinition'\\>\\(Celui, celle, ce\\) qui donne son nom \u00e0 quelque chose ou \u00e0 quelqu'un, \u00e0 qui l'on se r\u00e9f\u00e8re, que l'on v\u00e9n\u00e8re\\<\\\/span\\>\\<\\\/em\\> \\(source www\\.cnrtl\\.fr\\)\"; toolTips('.classtoolTips46',tt_store_content,'6639'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br \/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><\/p>\n<p>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br \/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\u00c9cole des<br \/>\\<strong\\>H\\<\\\/strong\\>autes \\<strong\\>\u00c9\\<\\\/strong\\>tudes \\<strong\\>C\\<\\\/strong\\>ommerciales\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips171',tt_store_content,'5214'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[62,65,27],"tags":[],"coauthors":[137],"class_list":["post-24340","post","type-post","status-publish","format-standard","hentry","category-rub_cult","category-rub_cult_litter","category-rub","edition-edi_00075","type_art-type_art_article","no-thumb"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9B5TM-6kA","_links":{"self":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/24340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=24340"}],"version-history":[{"count":0,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/24340\/revisions"}],"wp:attachment":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=24340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=24340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=24340"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/coauthors?post=24340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}