{"id":26359,"date":"2022-05-23T11:30:32","date_gmt":"2022-05-23T09:30:32","guid":{"rendered":"https:\/\/le-clairon-nouveau.fr\/wordpress\/?p=26359"},"modified":"2022-05-23T16:36:06","modified_gmt":"2022-05-23T14:36:06","slug":"fermeture-du-theatre-de-segure-lorsque-letat-sattaque-aux-citoyens","status":"publish","type":"post","link":"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2022\/05\/23\/fermeture-du-theatre-de-segure-lorsque-letat-sattaque-aux-citoyens\/","title":{"rendered":"Fermeture du Th\u00e9\u00e2tre de S\u00e9gure :  lorsque l\u2019\u00c9tat s\u2019attaque aux citoyens"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-26432 aligncenter\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/05\/galerie-2.jpg?resize=768%2C187&#038;ssl=1\" alt=\"\" width=\"768\" height=\"187\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/05\/galerie-2.jpg?resize=300%2C73&amp;ssl=1 300w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/05\/galerie-2.jpg?resize=768%2C188&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2022\/05\/galerie-2.jpg?w=835&amp;ssl=1 835w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 8pt\"><em><strong>Photos association les Compagnons de S\u00e9gure<\/strong><\/em><\/span><\/p>\n<ol>\n<li><span style=\"color: #09850f;font-size: 14pt\"><strong>Un coup de c\u0153ur puis un projet r\u00e9alis\u00e9<\/strong><\/span><\/li>\n<\/ol>\n<p style=\"text-align: justify\"><strong>Lorsque Murielle et Patrick Chevalier, tous deux professionnels du th\u00e9\u00e2tre, prennent leur retraite en 2012, le temps est venu pour eux de r\u00e9aliser un projet m\u00fbri depuis longtemps : cr\u00e9er un th\u00e9\u00e2tre dans un lieu \u00e9loign\u00e9 des \u00e9quipements culturels et contribuer ainsi \u00e0 la diffusion du spectacle vivant dans un territoire peu desservi (par la culture). Ils d\u00e9cident d\u2019investir leurs \u00e9conomies dans ce projet et partent \u00e0 la recherche d\u2019un lieu propice. Ce lieu ils le trouvent dans les Corbi\u00e8res Maritimes sur le territoire de la commune de Tuchan, entre Tuchan et Palairac.<\/strong><\/p>\n<p style=\"text-align: justify\">Il s\u2019agit d\u2019un vaste hangar qui aurait autrefois servi de forge puis de chai. Il est situ\u00e9 dans un lieu-dit \u00ab Segure \u00bb qu\u2019il partage avec deux habitations situ\u00e9es \u00e0 moins d\u2019une centaine de m\u00e8tres de part et d\u2019autre. La transaction se fait chez le notaire en 2013. Pour la somme de 50000 euros hors frais. D\u00e8s l\u2019acquisition du hangar, de nombreux amis du couple, issus des quatre coins de la France, aux m\u00e9tiers et comp\u00e9tences diverses, se mobilisent pour donner un coup de main au chantier consid\u00e9rable qui s\u2019ouvre. Il s\u2019agit de cr\u00e9er un th\u00e9\u00e2tre recevant du public et donc de se mettre en conformit\u00e9 avec les normes de s\u00e9curit\u00e9 qui r\u00e9gissent <span class='tooltipsall tooltip_post_id_29829 classtoolTips180'>ces<\/span> \u00e9quipements. Le permis de construire instruit par la DDTM, service de l\u2019\u00c9tat est accord\u00e9 le 8 d\u00e9cembre 2016.<\/p>\n<p style=\"text-align: justify\">Alors commence le temps de l\u2019huile de coude qui permet d\u2019\u00e9conomiser car tout est pay\u00e9 par les porteurs du projet, il n\u2019y a pas un sou d\u2019argent public dans cette construction. C\u2019est aussi le temps des dons provenant de compagnies de th\u00e9\u00e2tre amies qui font cadeau de mat\u00e9riels amortis, mais en bon \u00e9tat. L\u2019association des Compagnons de S\u00e9gure se cr\u00e9e. Ce travail ne passe pas inaper\u00e7u des autorit\u00e9s, le conseiller vice-pr\u00e9sident du d\u00e9partement et les maires des Tuchan et Palairac soutiennent le projet.<\/p>\n<p style=\"text-align: justify\"><strong><em>Le th\u00e9\u00e2tre est enfin op\u00e9rationnel au printemps 2017, avec, situ\u00e9 dans ses combles, un appartement destin\u00e9 \u00e0 accueillir les compagnies. Selon les estimations de ses promoteurs il aura co\u00fbt\u00e9 environ deux cent mille euros en mat\u00e9riel investi et presque autant en b\u00e9n\u00e9volat valoris\u00e9 \u00e0 l\u2019heure de travail.<\/em><\/strong><\/p>\n<p style=\"text-align: justify\">L\u2019activit\u00e9 du th\u00e9\u00e2tre peut d\u00e9buter en mars 2017. Il s\u2019agit de proposer au public du canton et au-del\u00e0, des repr\u00e9sentations faites par des professionnels du spectacle vivant, mais aussi de proposer aux artistes d\u2019utiliser le th\u00e9\u00e2tre comme lieu de cr\u00e9ation d\u2019autant plus que des locaux sont am\u00e9nag\u00e9s pour abriter d\u2019\u00e9ventuelles r\u00e9sidences. Ceux-ci viennent de tous les coins de France, c\u00e9l\u00e8bres ou non, souvent par amiti\u00e9 avec les porteurs de ce projet. Il est d\u00e9cid\u00e9 de faire des repr\u00e9sentations de mars \u00e0 octobre, avec en point d\u2019orgue un festival de 4 jours \u00e0 la fin du mois d\u2019ao\u00fbt.<br \/>\nC\u2019est ainsi que pendant cinq saisons des spectacles se succ\u00e8dent pour le plus grand plaisir du public. Certains sont cr\u00e9\u00e9s sur place, notamment \u00ab\u00a0<strong>S\u00e9gure au hasard du vent<\/strong>\u00a0\u00bb, cr\u00e9ation th\u00e9\u00e2trale qui porte sur l\u2019histoire locale et qui par la suite donnera lieu \u00e0 un film d\u00e9j\u00e0 diffus\u00e9 et encore \u00e0 faire conna\u00eetre dans diverses salles du d\u00e9partement.<\/p>\n<p style=\"text-align: justify\">A la fin 2021 le Th\u00e9\u00e2tre de S\u00e9gure pouvait se pr\u00e9valoir de plusieurs dizaines de repr\u00e9sentations de th\u00e9\u00e2tre, de concerts, de marionnettes, de contes pour adultes et enfants. Une bonne demi-douzaine de cr\u00e9ations th\u00e9\u00e2trales ont \u00e9t\u00e9 r\u00e9p\u00e9t\u00e9es puis inaugur\u00e9es dans ce m\u00eame lieu. Les r\u00e9sidences d\u2019artistes se sont succ\u00e9d\u00e9 au rythme de deux \u00e0 trois chaque ann\u00e9e et le festival en \u00e9tait en 2021 \u00e0 sa cinqui\u00e8me \u00e9dition, toutes inaugur\u00e9es par les \u00e9lus locaux et en fr\u00e9quentation en hausse chaque ann\u00e9e.<\/p>\n<ol start=\"2\">\n<li><span style=\"color: #09850f;font-size: 14pt\"><strong>Les ennuis commencent<\/strong><\/span><\/li>\n<\/ol>\n<p style=\"text-align: justify\"><strong><em>Le contexte<br \/>\n<\/em><\/strong>Si l\u2019installation du th\u00e9\u00e2tre de S\u00e9gure est accueillie avec plaisir par une grande partie des habitants du canton, il n\u2019en est pas de m\u00eame pour une voisine du th\u00e9\u00e2tre qui habite \u00e0 une centaine de m\u00e8tres en aval. Celle-ci a introduit aupr\u00e8s du TA de Montpellier d\u00e8s janvier 2017, soit sit\u00f4t connue la d\u00e9livrance du permis, une action en r\u00e9f\u00e9r\u00e9 pour bloquer les travaux en cours, ainsi qu\u2019une action sur le fond pour faire annuler ce permis de construire. Pour ce qui est du r\u00e9f\u00e9r\u00e9, le tribunal administratif de Montpellier la d\u00e9boute, estimant le dossier r\u00e9gulier, mais r\u00e9servant cependant pour l\u2019avenir sa d\u00e9cision de fond. Il est \u00e0 noter que le permis de construire \u00e9tait indispensable, compte tenu de la transformation du hangar de S\u00e9gure \u00e0 usage agricole en \u00e9tablissement recevant du public (ERP de cat\u00e9gorie 5).<\/p>\n<p style=\"text-align: justify\"><strong><em>Pourquoi cet acharnement proc\u00e9durier\u00a0?<br \/>\n<\/em><\/strong>Il semble que la vengeance soit \u00e0 l\u2019origine de la col\u00e8re de la voisine\u00a0: elle souhaitait acqu\u00e9rir le terrain d\u2019assise du th\u00e9\u00e2tre de S\u00e9gure et n\u2019aurait pas support\u00e9 qu\u2019il soit vendu \u00e0 quelqu\u2019un d\u2019autre. Elle dispose en tout cas des moyens n\u00e9cessaires \u00e0 l\u2019entreprise d\u2019une aventure proc\u00e9duri\u00e8re et engage un g\u00e9om\u00e8tre pour v\u00e9rifier les cotes du th\u00e9\u00e2tre afin de voir s\u2019il est situ\u00e9 en zone \u00e0 risque d\u2019inondation. Ce sera son angle d\u2019attaque car invoquer des nuisances semble plus hypoth\u00e9tique<\/p>\n<p style=\"text-align: justify\"><strong><em>R\u00e9sultat du recours en tribunal administratif<br \/>\n<\/em><\/strong>Le 7 juin 2019 le tribunal administratif de Montpellier donne raison \u00e0 la voisine et annule le permis de construire du th\u00e9\u00e2tre de S\u00e9gure au motif que la dalle qui constitue le rez de chauss\u00e9e du Th\u00e9\u00e2tre se trouve \u00e0 <u>19 centim\u00e8tres\u00a0!!<\/u> en dessous du seuil r\u00e8glementaire d\u00e9fini par un document d\u2019urbanisme appel\u00e9 PPRI (Plan de protection du risque inondation). Rappelons qu\u2019en l\u2019esp\u00e8ce ce seuil r\u00e8glementaire est calcul\u00e9 \u00e0 partir du niveau de la plus forte inondation connue, augment\u00e9 d\u2019une hauteur de 20 cm. Faut-il pr\u00e9ciser que lorsqu\u2019on mesure la hauteur d\u2019une crue on n\u2019arrive jamais \u00e0 une pr\u00e9cision de l\u2019ordre de quelques centim\u00e8tres. Mais le r\u00e8glement c\u2019est le r\u00e8glement, m\u00eame lorsqu\u2019il ne correspond pas toujours \u00e0 la r\u00e9alit\u00e9 et dans le cas pr\u00e9cis le Tribunal administratif l\u2019a interpr\u00e9t\u00e9 dans le sens le plus d\u00e9favorable !<\/p>\n<p style=\"text-align: justify\"><strong><em>Que faire\u00a0?<br \/>\n<\/em><\/strong>La d\u00e9cision du tribunal administratif de Montpellier remet en cause le Th\u00e9\u00e2tre de S\u00e9gure qui, <u>dot\u00e9 d\u2019un permis de construire en bonne et due forme<\/u>, apr\u00e8s avoir satisfait \u00e0 toutes les demandes et r\u00e8glementations administratives, fonctionne depuis deux ans et demi et a diffus\u00e9 plus de vingt spectacles sans aucun incident et \u00e0 la satisfaction de tous\u00a0!<br \/>\nApr\u00e8s avoir pris conseil aupr\u00e8s d\u2019urbanistes et d\u2019un cabinet d\u2019avocats sp\u00e9cialis\u00e9s, le propri\u00e9taire du th\u00e9\u00e2tre, appuy\u00e9 par l\u2019association des Compagnons de S\u00e9gure qui en assure le fonctionnement, d\u00e9cide de se pourvoir en appel aupr\u00e8s de la cour administrative d\u2019appel de Marseille. Cette d\u00e9cision entraine 6000 \u20ac de frais d\u2019avocats. Ceux\u2013ci plaideront une interpr\u00e9tation abusive par le TA de la r\u00e8glementation PPRI, notamment que le Th\u00e9\u00e2tre ne se trouve pas en zone inondable et que le TA de Montpellier, au lieu d\u2019annuler le permis de construire, aurait d\u00fb surseoir et demander au propri\u00e9taire des travaux afin de se mettre en conformit\u00e9 r\u00e8glementaire.<\/p>\n<p style=\"text-align: justify\"><strong><em>Mais la cour administrative d\u2019appel de Marseille confirme le jugement du TA de Montpellier<br \/>\n<\/em><\/strong>Par jugement du 9 mars 2021, la cour d\u2019appel administrative de Marseille rejette le pourvoi en appel. Elle ne retient pas l\u2019in-constructibilit\u00e9 du th\u00e9\u00e2tre \u00e9galement d\u00e9velopp\u00e9e par la voisine du fait de la carte communale et retenue par le TA de Montpellier lors du premier jugement, mais retient cependant le non-respect du PPRI par le propri\u00e9taire (les fameux 19 centim\u00e8tres), ce qui lui permet de confirmer ce jugement du TA et donc l\u2019annulation du permis de construire<br \/>\nPeu apr\u00e8s cette d\u00e9cision de justice, un entretien avec le directeur des services de l\u2019\u00e9quipement du d\u00e9partement de l\u2019Aude informe le propri\u00e9taire du th\u00e9\u00e2tre qu\u2019aucune demande nouvelle de permis de construire, visant \u00e0 mettre l\u2019\u00e9quipement en conformit\u00e9 avec la r\u00e8glementation, ne sera instruite favorablement par ses services. Cela lui est \u00e9nonc\u00e9 de fa\u00e7on orale mais ne sera jamais \u00e9crit, malgr\u00e9 une lettre de ce m\u00eame propri\u00e9taire souhaitant sortir de l\u2019impasse, lettre rest\u00e9e sans r\u00e9ponse.<br \/>\n<u>Cette fois le rejet se fonde sur un nouvel argument qui jusque-l\u00e0 n\u2019avait pas \u00e9t\u00e9 mentionn\u00e9, ni dans le cadre de l\u2019instruction du permis de construire par les service de l\u2019Etat, ni par le tribunal administratif de Montpellier, mais qui est \u00e9voqu\u00e9 par la Cour administrative d\u2019appel de Marseille dans son jugement<\/u>\u00a0: il s\u2019agit de la s\u00e9curit\u00e9 des acc\u00e8s au th\u00e9\u00e2tre, car la route de Tuchan \u00e0 Palairac et une partie du parking qui permet d\u2019acc\u00e9der au th\u00e9\u00e2tre, sont \u00e9galement situ\u00e9s en zone inondable \u00ab\u00a0<em>ce qui est de nature \u00e0 mettre en danger les personnes soucieuses de quitter les lieux lors d\u2019un \u00e9v\u00e8nement pluviom\u00e9trique important\u00a0\u00bb.<\/em><\/p>\n<p><strong>La justice a tranch\u00e9\u00a0: la r\u00e8glementation interpr\u00e9t\u00e9e dans sa plus grande rigueur ne tient pas compte de la r\u00e9alit\u00e9 \u00e0 savoir\u00a0:<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify\">Les responsables du th\u00e9\u00e2tre sont des professionnels du spectacle vivant, responsables de structures th\u00e9\u00e2trales, lui metteur en sc\u00e8ne chevronn\u00e9, elle chevalier des arts et lettres. A l\u2019issue d\u2019une longue carri\u00e8re, salu\u00e9e par les institutions culturelles, leur responsabilit\u00e9 n\u2019a jamais \u00e9t\u00e9 mise en cause. Ce ne sont pas des d\u00e9linquants potentiels et ils ne vont pas convoquer le public en cas de pr\u00e9vision de crue d\u2019autant plus qu\u2019ils travaillent en relation constante avec les services des collectivit\u00e9s locales concern\u00e9es.<\/li>\n<li style=\"text-align: justify\">Les spectacles pr\u00e9sent\u00e9s par le th\u00e9\u00e2tre durent au maximum 3 heures, y compris les temps d\u2019acc\u00e8s et de d\u00e9part vers des endroits hors-eaux en cas d\u2019\u00e9v\u00e8nement pluvieux\u00a0: donc bien en de\u00e7\u00e0 des d\u00e9lais fiables de pr\u00e9visions m\u00e9t\u00e9o.<\/li>\n<li style=\"text-align: justify\">La fr\u00e9quence et la saisonnalit\u00e9 des spectacles se situent essentiellement en \u00e9t\u00e9, en dehors des p\u00e9riodes o\u00f9 se manifestent habituellement les crues importantes.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Dans ces conditions, retenir le risque d\u2019inondation de la route rel\u00e8ve d\u2019une interpr\u00e9tation excessive, d\u2019autant que la solution de relever le sol du b\u00e2timent de 20 centim\u00e8tres ainsi que la totalit\u00e9 du parking et l\u2019acc\u00e8s entre ce dernier et le th\u00e9\u00e2tre, ferait bel et bien sortir l\u2019ensemble de la propri\u00e9t\u00e9 du p\u00e9rim\u00e8tre de la zone inondable. Or cette solution est tout \u00e0 fait envisageable. Le propri\u00e9taire l\u2019a toujours dit.<\/p>\n<p style=\"text-align: justify\"><strong><em>Compte tenu de l\u2019int\u00e9r\u00eat public que pr\u00e9sentent les activit\u00e9s du Th\u00e9\u00e2tre de Tuchan, les autorit\u00e9s locales continuent cependant \u00e0 lui apporter leur soutien. <br \/>\n<\/em><\/strong>C\u2019est ainsi que Madame la maire de Tuchan, soutenue par le d\u00e9partement de l\u2019Aude et le maire de Palairac, avec l\u2019accord tacite de la sous-pr\u00e9fecture de Narbonne, prend un arr\u00eat\u00e9 d\u00e9rogatoire pour autoriser la tenue du festival annuel de th\u00e9\u00e2tre la 3<sup>\u00e8me<\/sup> semaine d\u2019ao\u00fbt 2020 et 2021. Cette d\u00e9cision est d\u2019autant plus juste et <span class='tooltipsall tooltip_post_id_19394 classtoolTips134'>sage<\/span> que lors de la publication de la d\u00e9cision de la cour administrative d\u2019appel la programmation du festival \u00e9tait d\u00e9j\u00e0 boucl\u00e9e, les com\u00e9diens engag\u00e9s, les \u00e9quipements accessoires lou\u00e9s, etc. Un haut fonctionnaire de la sous-pr\u00e9fecture honore d\u2019ailleurs le festival de sa pr\u00e9sence.<\/p>\n<p style=\"text-align: justify\"><strong><em>Avril 2022, un courrier du nouveau sous-pr\u00e9fet de Narbonne, Monsieur R\u00e9mi Recio, enjoint par lettre Madame la maire de Tuchan de ne plus prendre d\u2019arr\u00eat\u00e9 d\u00e9rogatoire en 2022 autorisant les activit\u00e9s du Th\u00e9\u00e2tre de S\u00e9gure.<br \/>\n<\/em><\/strong>Le couperet tombe, le th\u00e9\u00e2tre doit fermer. Il faut jouer ailleurs, un point c\u2019est tout. Une fois de plus cette d\u00e9cision officielle tombe au moment o\u00f9 la programmation du th\u00e9\u00e2tre est faite, les com\u00e9diens, les personnels et une bonne partie des frais engag\u00e9s.<\/p>\n<p style=\"text-align: justify\"><strong><em>Est-ce la fin de l\u2019aventure pour l\u2019\u00e9quipe b\u00e9n\u00e9vole qui anime le th\u00e9\u00e2tre de S\u00e9gure\u00a0? Une d\u00e9cision de justice, provoqu\u00e9e par une voisine vindicative et proc\u00e9duri\u00e8re peut-elle emp\u00eacher tout un canton peu desservi de disposer d\u2019un outil de diffusion culturelle\u00a0qu\u2019il appr\u00e9cie ? Quid de l\u2019argent personnel investi par les propri\u00e9taires du Th\u00e9\u00e2tre, suite au permis de construire accord\u00e9 sur instruction des services de l\u2019Etat\u00a0? Quid des 11.000 \u20ac pay\u00e9s par ces propri\u00e9taires au titre de la taxe d\u2019am\u00e9nagement\u00a0? Et quid du d\u00e9vouement sans limite de l\u2019association culturelle\u00a0?<\/em><\/strong><\/p>\n<p style=\"text-align: justify\"><strong><em>De tout cela les services de l\u2019\u00c9tat ne s\u2019en pr\u00e9occupent pas. Chacun, le nez dans le guidon, a suivi sa logique r\u00e8glementaire particuli\u00e8re, sa propre conception de l\u2019int\u00e9r\u00eat public au d\u00e9triment de l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral\u2026<br \/>\n<\/em><\/strong><strong>Et comment ne pas penser que tous ces braves gens, abrit\u00e9s derri\u00e8re leurs interpr\u00e9tations de la loi et des r\u00e8glements, ne s\u2019en lavent pas les mains lorsqu\u2019on lit ce conseil d\u00e9sinvolte du directeur de la DDTM dans un courrier adress\u00e9 \u00e0 l\u2019ancien Maire de Tuchan et au vice-pr\u00e9sident du Conseil d\u00e9partemental de l\u2019Aude\u00a0: <em>\u00ab\u00a0<\/em><\/strong><em>Peut-\u00eatre que dans la d\u00e9marche que vous entreprenez au titre du P.L.U., vous pourriez identifier d&rsquo;autres sites potentiellement plus adapt\u00e9s et qui pourraient convenir \u00e0 la poursuite de l&rsquo;activit\u00e9.<\/em><strong><em>\u00a0\u00bb<\/em><\/strong> <strong>C\u2019est ne faire aucun cas de l\u2019\u00e9norme travail r\u00e9alis\u00e9 par des b\u00e9n\u00e9voles qui, sur la base du permis de construire instruit par cette m\u00eame DDTM, ont investi leur force de travail et leurs \u00e9conomies sans en attendre un quelconque b\u00e9n\u00e9fice mat\u00e9riel et qui, de plus, ne pourront m\u00eame pas r\u00e9cup\u00e9rer un sou de leur propre argent, sauf \u00e0 prendre le risque de nouveaux frais en engageant une proc\u00e9dure en justice contre l\u2019\u00c9tat pour r\u00e9paration du pr\u00e9judice moral et financier.<\/strong><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 14pt\"><strong>Faut-il faire un proc\u00e8s \u00e0 l\u2019\u00c9tat ?<\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><strong><em>\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: right\"><em>Hubert Reys pour le Clairon de l&rsquo;Atax le 14\/05\/2022<\/em><\/p>\n<p>&nbsp;<\/p>\n<script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>SAGE \\= \\<span class\\='st'\\> sch\u00e9ma d'am\u00e9nagement et de gestion de l'eau\\<\\\/span\\> , c'est un outil de planification qui concerne l'ensemble des eaux situ\u00e9es dans un bassin versant\\<\\\/p\\>\"; toolTips('.classtoolTips134',tt_store_content,'19394'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br\/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><br\/><br\/>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>Imp\u00f4t de Solidarit\u00e9 sur la Fortune\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips149',tt_store_content,'3596'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br\/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;<br\/><br\/>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>A\\<\\\/strong\\>gence \\<strong\\>R\\<\\\/strong\\>\u00e9gionale de \\<strong\\>S\\<\\\/strong\\>ant\u00e9\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips188',tt_store_content,'18356'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br\/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<br\/><br\/>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<br\/><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br\/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9seau \\<strong\\>A\\<\\\/strong\\>ction \\<strong\\>C\\<\\\/strong\\>limat\\<\\\/p\\><br\/>Le r\u00e9seau Action Climat '\\<em\\>f\u00e9d\u00e8re les associations impliqu\u00e9es dans la lutte contre les changements climatiques et pour une transition \u00e9cologique, solidaire et \u00e9quitable\\<\\\/em\\>'\\.<br\/><br\/>\\<a href\\='https\\:\\\/\\\/reseauactionclimat\\.org\\\/' target\\='_blank' rel\\='noopener'\\>Voir le site du <span class='tooltipsall tooltip_post_id_4309 classtoolTips200'>RAC<\/span>\\<\\\/a\\>\"; toolTips('.classtoolTips200',tt_store_content,'4309'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_24572 classtoolTips211'>MIT<\/span> \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br\/>ou<br\/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script>","protected":false},"excerpt":{"rendered":"<p>Photos association les Compagnons de S\u00e9gure Un coup de c\u0153ur puis un projet r\u00e9alis\u00e9 Lorsque Murielle et Patrick Chevalier, tous deux professionnels du th\u00e9\u00e2tre, prennent leur retraite en 2012, le temps est venu pour eux de r\u00e9aliser un projet m\u00fbri depuis longtemps : cr\u00e9er un th\u00e9\u00e2tre dans un lieu \u00e9loign\u00e9 des \u00e9quipements culturels et contribuerLire la suite &rarr;<script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_19394 classtoolTips134'>SAGE<\/span> \\= \\<span class\\='st'\\> sch\u00e9ma d'am\u00e9nagement et de gestion de l'eau\\<\\\/span\\> , c'est un outil de planification qui concerne l'ensemble des eaux situ\u00e9es dans un bassin versant\\<\\\/p\\>\"; toolTips('.classtoolTips134',tt_store_content,'19394'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br \/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><\/p>\n<p>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>I\\<\\\/strong\\>mp\u00f4t sur la \\<strong\\>F\\<\\\/strong\\>ortune \\<strong\\>I\\<\\\/strong\\>mmobili\u00e8re\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips148',tt_store_content,'5643'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>Imp\u00f4t de Solidarit\u00e9 sur la Fortune\\<\\\/strong\\>\\<\\\/p\\>\"; toolTips('.classtoolTips149',tt_store_content,'3596'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(<span class='tooltipsall tooltip_post_id_7750 classtoolTips164'>PPE<\/span>\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify'\\>La \u00ab\u00a0\\<b\\>programmation pluriannuelle de l'\u00e9nergie\\<\\\/b\\>\u00a0\u00bb \\(PPE\\) est, en France, un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la \\<a title\\='Loi relative \u00e0 la transition \u00e9nerg\u00e9tique pour la croissance verte' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Loi_relative_%C3%A0_la_transition_%C3%A9nerg%C3%A9tique_pour_la_croissance_verte'\\>loi de transition \u00e9nerg\u00e9tique\\<\\\/a\\> \\(TECV\\), elle fixe une trajectoire pour le \\<a title\\='Mix \u00e9nerg\u00e9tique' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Mix_%C3%A9nerg%C3%A9tique'\\>mix \u00e9nerg\u00e9tique\\<\\\/a\\>, ainsi que \\<span class\\='citation'\\>\u00ab\u00a0les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\u00a0\u00bb\\<\\\/span\\>\\. \\(Wikip\u00e9dia\\)\\<\\\/p\\>\"; toolTips('.classtoolTips164',tt_store_content,'7750'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br \/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>\u00c9\\<\\\/strong\\>cole \\<strong\\>N\\<\\\/strong\\>ationale d'\\<strong\\>A\\<\\\/strong\\>dministration\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips170',tt_store_content,'5213'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>Conseil \u00c9conomique et Social\\<\\\/p\\>\"; toolTips('.classtoolTips180',tt_store_content,'29829'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>A\\<\\\/strong\\>gence \\<strong\\>R\\<\\\/strong\\>\u00e9gionale de \\<strong\\>S\\<\\\/strong\\>ant\u00e9\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips188',tt_store_content,'18356'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>P\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>rogrammation \\<strong\\>P\\<\\\/strong\\>luri\\-annuelle de l'\\<strong\\>\u00c9\\<\\\/strong\\>nergie\\<\\\/span\\>\\<\\\/p\\><br \/>La PPE est est en France un document strat\u00e9gique de pilotage de la transition \u00e9nerg\u00e9tique\\. Institu\u00e9e par l'article 176 de la loi transition \u00e9nerg\u00e9tique \\(TECV\\)\\. Elle fixe \\(par \u00e9nergie\\) une trajectoire pour le mix \u00e9nerg\u00e9tique, ainsi que \u00ab&nbsp;\\<em\\>les priorit\u00e9s d'action pour la gestion de l\u2019ensemble des formes d'\u00e9nergie sur le territoire m\u00e9tropolitain continental, afin d\u2019atteindre les objectifs nationaux fix\u00e9s par la loi\\<\\\/em\\>&nbsp;\u00bb\\.<\/p>\n<p>Initi\u00e9e en 2016, elle est r\u00e9vis\u00e9e en 2018 puis ensuite tous les 5 ans\\.<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Programmation_pluriannuelle_de_l'\u00e9nergi' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page Wikipedia consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\><br \/>\\<a href\\='https\\:\\\/\\\/ppe\\.debatpublic\\.fr\\\/' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la page du site 'Commission du D\u00e9bat Public' consacr\u00e9e \u00e0 la PPE\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips193',tt_store_content,'7102'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>E\\<\\\/strong\\>volutionary \\<strong\\>P\\<\\\/strong\\>ower \\<strong\\>R\\<\\\/strong\\>eactor\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>R\u00e9acteur nucl\u00e9aire de troisi\u00e8me g\u00e9n\u00e9ration \\(classification internationale\\), con\u00e7u et d\u00e9velopp\u00e9 par <span class='tooltipsall tooltip_post_id_5121 classtoolTips35'>Areva NP<\/span>&nbsp; au cours des ann\u00e9es 1990 et 2000\\. Il fait partie de la fili\u00e8re des r\u00e9acteurs \u00e0 eau pressuris\u00e9e\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/R%C3%A9acteur_pressuris%C3%A9_europ%C3%A9en' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia <span class='tooltipsall tooltip_post_id_5579 classtoolTips196'>EPR<\/span>\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips196',tt_store_content,'5579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>R\\<\\\/strong\\>\u00e9seau \\<strong\\>A\\<\\\/strong\\>ction \\<strong\\>C\\<\\\/strong\\>limat\\<\\\/p\\><br \/>Le r\u00e9seau Action Climat '\\<em\\>f\u00e9d\u00e8re les associations impliqu\u00e9es dans la lutte contre les changements climatiques et pour une transition \u00e9cologique, solidaire et \u00e9quitable\\<\\\/em\\>'\\.<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/reseauactionclimat\\.org\\\/' target\\='_blank' rel\\='noopener'\\>Voir le site du <span class='tooltipsall tooltip_post_id_4309 classtoolTips200'>RAC<\/span>\\<\\\/a\\>\"; toolTips('.classtoolTips200',tt_store_content,'4309'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_24572 classtoolTips211'>MIT<\/span> \\= Massachussets Institute of Technology, prestigieuse universit\u00e9 am\u00e9ricaine de la c\u00f4te est\\<\\\/p\\>\"; toolTips('.classtoolTips211',tt_store_content,'24572'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br \/>ou<br \/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,9,62,5,27,66],"tags":[],"coauthors":[4],"class_list":["post-26359","post","type-post","status-publish","format-standard","hentry","category-actu","category-actu_gen","category-rub_cult","category-rub_pol","category-rub","category-rub_cult_theatre","edition-edi_00087","type_art-type_art_article","no-thumb"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9B5TM-6R9","_links":{"self":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/26359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=26359"}],"version-history":[{"count":0,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/26359\/revisions"}],"wp:attachment":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=26359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=26359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=26359"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/coauthors?post=26359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}