{"id":27777,"date":"2023-03-12T21:34:50","date_gmt":"2023-03-12T20:34:50","guid":{"rendered":"https:\/\/le-clairon-nouveau.fr\/wordpress\/?p=27777"},"modified":"2023-03-12T22:48:21","modified_gmt":"2023-03-12T21:48:21","slug":"narbonne-7eme-manifestation-contre-la-reforme-des-retraites-ce-ne-fut-pas-waterloo-non-non-mais-ce-ne-fut-pas-arcole","status":"publish","type":"post","link":"https:\/\/le-clairon-nouveau.fr\/wordpress\/blog\/2023\/03\/12\/narbonne-7eme-manifestation-contre-la-reforme-des-retraites-ce-ne-fut-pas-waterloo-non-non-mais-ce-ne-fut-pas-arcole\/","title":{"rendered":"Narbonne 7\u00e8me manifestation contre la r\u00e9forme des retraites : \u00ab ce ne fut pas Waterloo non non mais ce ne fut pas Arcole (*)"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-23558 aligncenter\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/12\/Breves-du-Clairon-nvelle.jpg?resize=151%2C64&#038;ssl=1\" alt=\"\" width=\"151\" height=\"64\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/12\/Breves-du-Clairon-nvelle.jpg?resize=300%2C127&amp;ssl=1 300w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2020\/12\/Breves-du-Clairon-nvelle.jpg?w=329&amp;ssl=1 329w\" sizes=\"auto, (max-width: 151px) 100vw, 151px\" \/><\/p>\n<p style=\"text-align: center\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-27781 aligncenter\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11-mars-23-1-1.jpg?resize=584%2C329&#038;ssl=1\" alt=\"\" width=\"584\" height=\"329\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11-mars-23-1-1.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11-mars-23-1-1.jpg?resize=768%2C434&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11-mars-23-1-1.jpg?w=1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><span style=\"font-size: 8pt\"><em><strong>(Photo HR)<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify\">Le vent soufflait fort : des rafales \u00e0 80 km\/h ce samedi 11 mars \u00e0 10 h 30 du matin. Ils \u00e9taient pourtant entre 2200 et 2500 manifestants, selon le comptage du Clairon ou de la CGT, \u00e0 prendre le d\u00e9part du Cort\u00e8ge devant le th\u00e9\u00e2tre\/cin\u00e9ma de Narbonne.<br \/>\nMoins de monde que le 7 mars, car pour beaucoup il \u00e9tait difficile de participer \u00e0 2 manifs la m\u00eame semaine, mais des manifestants dont la d\u00e9termination \u00e9tait intacte sinon renforc\u00e9e.<\/p>\n<p style=\"text-align: center\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-27779 aligncenter\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11mars23-4.jpg?resize=580%2C327&#038;ssl=1\" alt=\"\" width=\"580\" height=\"327\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11mars23-4.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11mars23-4.jpg?resize=768%2C434&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11mars23-4.jpg?w=1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><span style=\"font-size: 8pt\"><strong><em>(Photo HR)<\/em><\/strong><\/span><\/p>\n<p style=\"text-align: justify\">Les m\u00e9dias nationaux de formatage de l&rsquo;opinion auraient tort de se r\u00e9jouir et d\u2019insister sur la baisse du nombre de manifestants, qui serait, selon eux, le pr\u00e9lude \u00e0 une acceptation des Fran\u00e7aises et Fran\u00e7ais de cette r\u00e9forme impos\u00e9e par Macron et son gouvernement.<br \/>\nCompter sur la r\u00e9signation du peuple pour continuer la politique actuelle serait une grave erreur. La violence faite aux gens comme aux <span class='tooltipsall tooltip_post_id_7841 classtoolTips4'>corps interm\u00e9diaires<\/span> s\u2019est renforc\u00e9e au cours du second quinquennat d&rsquo;E. Macron. Elle s\u2019exprime de mani\u00e8re particuli\u00e8rement spectaculaire dans la mani\u00e8re dont ce projet de r\u00e9forme des retraites est actuellement impos\u00e9 et cette fois-ci cette violence a \u00e9t\u00e9 ressentie par tout un peuple. La blessure est profonde et ne se refermera pas facilement dans l\u2019oubli, rien ne sera plus comme avant.<\/p>\n<p style=\"text-align: justify\">Certes la lutte contre la r\u00e9forme des retraites continue dans l\u2019incertitude de savoir qui va gagner. Mais celui qui a d\u00e9j\u00e0 perdu c\u2019est E Macron : d\u2019une part aux yeux de tout un peuple qui malgr\u00e9 les man\u0153uvres et les mensonges a compris que ce pr\u00e9sident l\u00e0 ne d\u00e9fendait pas ses int\u00e9r\u00eats, d\u2019autre part aux yeux de ses commanditaires de la finance qui constatent qu\u2019il fait beaucoup de bruit pour des r\u00e9sultats discutables.<\/p>\n<p style=\"text-align: justify\">Le premier aura beau laisser sa cord\u00e9e en difficult\u00e9 pour papillonner en Afrique sur la fin de la Fran\u00e7afrique, ou d\u00eener avec l\u2019ultra lib\u00e9ral Rishi Sunac puis avec \u00ab\u00a0the king Charles the third\u00a0\u00bb, le peuple fran\u00e7ais a compris \u00e0 pr\u00e9sent ce qu&rsquo;il en est, ce qu\u2019il est et ce qu\u2019il veut\u2026<\/p>\n<p style=\"text-align: center\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-27780 aligncenter\" src=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11mars-23-2.jpg?resize=581%2C327&#038;ssl=1\" alt=\"\" width=\"581\" height=\"327\" srcset=\"https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11mars-23-2.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11mars-23-2.jpg?resize=768%2C434&amp;ssl=1 768w, https:\/\/i0.wp.com\/le-clairon-nouveau.fr\/wordpress\/wp-content\/uploads\/2023\/03\/11mars-23-2.jpg?w=1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 581px) 100vw, 581px\" \/><span style=\"font-size: 8pt\"><em><strong>(Photo HR)<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: right\"><em>Hubert Reys pour le Clairon de l\u2019Atax le 12\/03\/2023<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>(*) extrait de la chanson de J Brel \u00ab\u00a0Au suivant\u00a0\u00bb<\/p>\n<p>Pour \u00e9largir la r\u00e9flexion<br \/>\n\u00ab\u00a0Le traitre et le n\u00e9ant\u00a0\u00bb par G\u00e9rard Davet et Fabrice Lhomme : \u00e9ditions fayard 2021<br \/>\n\u00ab\u00a0L&rsquo;esprit du macronisme\u00a0\u00bb ou l&rsquo;art de d\u00e9voyer les concepts par Myriam Revaut d&rsquo;Allonnes \u00e9ditions du Seuil\u00a0 2021<\/p>\n<p>&nbsp;<\/p>\n<script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Les corps interm\u00e9diaires, h\u00e9ritiers des corps de l'Ancien R\u00e9gime, sont des \\<strong\\>groupes sociaux et humains, situ\u00e9s entre l\u2019individu et l\u2019\u00c9tat, ind\u00e9pendants et autonomes, constitu\u00e9s naturellement ou par accord d\u00e9lib\u00e9r\u00e9\\<\\\/strong\\> en vue d\u2019atteindre un \\<strong\\>objectif commun aux personnes qui les composent\\<\\\/strong\\> \\(partis politiques, entreprises et syndicats, divisions administratives du territoire, chambres de commerce et d'industrie, associations, voire groupes de pression etc\\.\\)\\. Pour qualifier les corps interm\u00e9diaires, on peut reprendre une formule de Pierre Rosanvallon et parler d'\u00ab&nbsp;institutions de l'interaction&nbsp;\u00bb\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Le professeur de science politique Yves M\u00e9ny regroupe les corps interm\u00e9diaires en \\<strong\\>trois cat\u00e9gories&nbsp;\\<\\\/strong\\>\\: les \\<strong\\>organisations politico\\-sociales\\<\\\/strong\\> \\(partis politiques, syndicats, patronat\\), les \\<strong\\>organisations professionnelles sectorielles\\<\\\/strong\\> \\(chambres de commerce, chambres d'agriculture, ordre des avocats, Conseil sup\u00e9rieur du notariat\\.\\.\\.\\), les \\<strong\\>associations\\<\\\/strong\\>\\.\\<\\\/p\\><br\/>Les \\<strong\\>journalistes\\<\\\/strong\\>, qui servent d'interm\u00e9diaire entre la soci\u00e9t\u00e9 civile et le pouvoir politique, peuvent \u00e9galement \u00eatre consid\u00e9r\u00e9s comme un groupe interm\u00e9diaire<br\/><br\/>\\<em\\>Extrait de la \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Corps_interm%C3%A9diaires' target\\='_blank' rel\\='noopener'\\>fiche Wikipedia\\<\\\/a\\> consacr\u00e9e aux corps interm\u00e9diaires\\<\\\/em\\>\"; toolTips('.classtoolTips4',tt_store_content,'7841'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br\/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><br\/><br\/>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br\/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br\/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;<br\/><br\/>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br\/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>A\\<\\\/strong\\>gence \\<strong\\>R\\<\\\/strong\\>\u00e9gionale de \\<strong\\>S\\<\\\/strong\\>ant\u00e9\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips188',tt_store_content,'18356'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br\/>\\<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br\/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br\/>ou<br\/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script>","protected":false},"excerpt":{"rendered":"<p>(Photo HR) Le vent soufflait fort : des rafales \u00e0 80 km\/h ce samedi 11 mars \u00e0 10 h 30 du matin. Ils \u00e9taient pourtant entre 2200 et 2500 manifestants, selon le comptage du Clairon ou de la CGT, \u00e0 prendre le d\u00e9part du Cort\u00e8ge devant le th\u00e9\u00e2tre\/cin\u00e9ma de Narbonne. Moins de monde que leLire la suite &rarr;<script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les <span class='tooltipsall tooltip_post_id_7841 classtoolTips4'>corps interm\u00e9diaires<\/span>, h\u00e9ritiers des corps de l'Ancien R\u00e9gime, sont des \\<strong\\>groupes sociaux et humains, situ\u00e9s entre l\u2019individu et l\u2019\u00c9tat, ind\u00e9pendants et autonomes, constitu\u00e9s naturellement ou par accord d\u00e9lib\u00e9r\u00e9\\<\\\/strong\\> en vue d\u2019atteindre un \\<strong\\>objectif commun aux personnes qui les composent\\<\\\/strong\\> \\(partis politiques, entreprises et syndicats, divisions administratives du territoire, chambres de commerce et d'industrie, associations, voire groupes de pression etc\\.\\)\\. Pour qualifier les corps interm\u00e9diaires, on peut reprendre une formule de Pierre Rosanvallon et parler d'\u00ab&nbsp;institutions de l'interaction&nbsp;\u00bb\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le professeur de science politique Yves M\u00e9ny regroupe les corps interm\u00e9diaires en \\<strong\\>trois cat\u00e9gories&nbsp;\\<\\\/strong\\>\\: les \\<strong\\>organisations politico\\-sociales\\<\\\/strong\\> \\(partis politiques, syndicats, patronat\\), les \\<strong\\>organisations professionnelles sectorielles\\<\\\/strong\\> \\(chambres de commerce, chambres d'agriculture, ordre des avocats, Conseil sup\u00e9rieur du notariat\\.\\.\\.\\), les \\<strong\\>associations\\<\\\/strong\\>\\.\\<\\\/p\\><br \/>Les \\<strong\\>journalistes\\<\\\/strong\\>, qui servent d'interm\u00e9diaire entre la soci\u00e9t\u00e9 civile et le pouvoir politique, peuvent \u00e9galement \u00eatre consid\u00e9r\u00e9s comme un groupe interm\u00e9diaire<\/p>\n<p>\\<em\\>Extrait de la \\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Corps_interm%C3%A9diaires' target\\='_blank' rel\\='noopener'\\>fiche Wikipedia\\<\\\/a\\> consacr\u00e9e aux corps interm\u00e9diaires\\<\\\/em\\>\"; toolTips('.classtoolTips4',tt_store_content,'7841'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>S\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>oci\u00e9t\u00e9 d'\\<strong\\>\u00c9\\<\\\/strong\\>conomie \\<strong\\>M\\<\\\/strong\\>ixte\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>En France, une soci\u00e9t\u00e9 d'\u00e9conomie mixte est une soci\u00e9t\u00e9 anonyme dont le capital est majoritairement d\u00e9tenu par une ou plusieurs personnes publiques \\(\u00e0 savoir l'\u00c9tat, une Collectivit\u00e9 territoriale, ou tout autre \u00c9tablissement public\\)\\. Cette participation majoritaire publique est plafonn\u00e9e \u00e0 85&nbsp;% du capital depuis la Loi du 2 janvier 2002\\. Au moins une personne priv\u00e9e doit participer au capital de la <span class='tooltipsall tooltip_post_id_7168 classtoolTips142'>SEM<\/span>, sachant qu'il peut s'agir d'une autre SEM\\.\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>\\<strong\\>Le recours \u00e0 la SEM garantit\\<\\\/strong\\> \u00e0 la collectivit\u00e9 publique actionnaire et cocontractante \\<strong\\>la prise en compte effective de l'int\u00e9r\u00eat g\u00e9n\u00e9ral\\<\\\/strong\\> dans les objectifs de l'entreprise \\<strong\\>et la souplesse de la soci\u00e9t\u00e9 de droit priv\u00e9\\<\\\/strong\\>\\.\\<\\\/p\\><br \/>\\<em\\>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Soci%C3%A9t%C3%A9_d%27%C3%A9conomie_mixte' target\\='_blank' rel\\='noopener'\\>Voir ici la page Wikipedia consacr\u00e9e aux SEM\\<\\\/a\\> \\<\\\/em\\><\/p>\n<p>&nbsp;\"; toolTips('.classtoolTips142',tt_store_content,'7168'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>G\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>az \u00e0 \\<strong\\>E\\<\\\/strong\\>ffet de \\<strong\\>S\\<\\\/strong\\>erre\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les gaz \u00e0 effet de serre \\(<span class='tooltipsall tooltip_post_id_7232 classtoolTips161'>GES<\/span>\\) sont des composants gazeux qui absorbent le rayonnement infrarouge \u00e9mis par la surface terrestre et contribuent \u00e0 l'effet de serre\\. L'augmentation de leur concentration dans l'atmosph\u00e8re terrestre est l'un des facteurs \u00e0 l'origine du r\u00e9chauffement climatique\\.\\<\\\/p\\><br \/>\\<a href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Gaz_%C3%A0_effet_de_serre' target\\='_blank' rel\\='noopener'\\>\\<em\\>Voir ici la fiche Wikipedia sur les gaz \u00e0 effet de serre\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips161',tt_store_content,'7232'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Le Conseil d'Orientation des Retraites est une instance qui r\u00e9unit &nbsp;\\<span class\\='st'\\>les principaux acteurs du champ des retraites\\<\\\/span\\> et effectue un travail d'\u00e9tudes et de concertation\\. Compos\u00e9 de parlementaires, de repr\u00e9sentants des organisations professionnelles et syndicales, des retrait\u00e9s et des familles, de membres de l'administration et d'experts, le Conseil d'orientation des retraites \\(<span class='tooltipsall tooltip_post_id_7751 classtoolTips165'>COR<\/span>\\) est plac\u00e9 aupr\u00e8s du Premier ministre\\.\\<\\\/p\\>\"; toolTips('.classtoolTips165',tt_store_content,'7751'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation \\<strong\\>M\\<\\\/strong\\>\u00e9t\u00e9orologique \\<strong\\>M\\<\\\/strong\\>ondiale<br \/>\\<strong\\>W\\<\\\/strong\\>orld \\<strong\\>M\\<\\\/strong\\>eteorological \\<strong\\>O\\<\\\/strong\\>rganization\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;<\/p>\n<p>\\<a href\\='https\\:\\\/\\\/public\\.wmo\\.int\\\/fr' target\\='_blank' rel\\='noopener'\\>\\<em\\>Acc\u00e9der ici au site de l'organisation\\<\\\/em\\>\\<\\\/a\\>\"; toolTips('.classtoolTips168',tt_store_content,'7763'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>P\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>lan \\<strong\\>L\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>ocal d'\\<strong\\>U\\<\\\/strong\\>\\<\\\/span\\>\\<span style\\='font\\-size\\: 14pt;'\\>rbanisme\\<\\\/span\\>\\<\\\/p\\><br \/>&nbsp;\"; toolTips('.classtoolTips176',tt_store_content,'4979'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>A\\<\\\/strong\\>gence \\<strong\\>R\\<\\\/strong\\>\u00e9gionale de \\<strong\\>S\\<\\\/strong\\>ant\u00e9\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips188',tt_store_content,'18356'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>G\\<\\\/strong\\>roupement \\<strong\\>H\\<\\\/strong\\>ospitalier de \\<strong\\>T\\<\\\/strong\\>erritoire\\<\\\/span\\>\\<\\\/p\\><br \/>\\<\/p>\n<p style\\='text\\-align\\: justify;'\\>Les groupements hospitaliers de territoires, dispositif pr\u00e9vu par la loi de sant\u00e9 2016, sont un nouveau mode de coop\u00e9ration entre les \u00e9tablissements publics de sant\u00e9 \u00e0 l\u2019\u00e9chelle d\u2019un territoire\\<\\\/p\\>\"; toolTips('.classtoolTips189',tt_store_content,'18358'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>omit\u00e9 \\<strong\\>T\\<\\\/strong\\>echnique d'\\<strong\\>\u00c9\\<\\\/strong\\>tablissement\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips191',tt_store_content,'18359'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>R\\<\\\/span\\>\\<\\\/strong\\>\\<span style\\='font\\-size\\: 14pt;'\\>eferendum d'\\<strong\\>I\\<\\\/strong\\>nitiative \\<strong\\>C\\<\\\/strong\\>itoyenne\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips205',tt_store_content,'12268'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_25844 classtoolTips208'>RTE<\/span> \\= R\u00e9seau de Transport d'Electricit\u00e9 est une filiale d'<span class='tooltipsall tooltip_post_id_7035 classtoolTips178'>EDF<\/span> qui est l'actionnaire majoritaire avec 50,1% des parts le reste \u00e9tant partag\u00e9 par la CDC et la CNP\\<\\\/p\\>\"; toolTips('.classtoolTips208',tt_store_content,'25844'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(<span class='tooltipsall tooltip_post_id_3579 classtoolTips210'>ONG<\/span>\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>O\\<\\\/strong\\>rganisation\\<strong\\> N\\<\\\/strong\\>on\\<strong\\> G\\<\\\/strong\\>ouvernementale\\<\\\/span\\>\\<\\\/p\\><br \/>Une organisation non gouvernementale \\(ONG\\) est une \\<a title\\='Association \u00e0 but non lucratif' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Association_%C3%A0_but_non_lucratif' target\\='_blank' rel\\='noopener'\\>association \u00e0 but non lucratif\\<\\\/a\\>, d'int\u00e9r\u00eat public, qui ne rel\u00e8ve ni de l'\u00c9tat, ni d'institutions internationales\\<sup id\\='cite_ref\\-novethic_1\\-0' class\\='reference'\\>\\<\\\/sup\\>\\. Les ONG n'ont pas le statut de sujet de \\<a title\\='Droit international public' href\\='https\\:\\\/\\\/fr\\.wikipedia\\.org\\\/wiki\\\/Droit_international_public' target\\='_blank' rel\\='noopener'\\>droit international\\<\\\/a\\>\\.\"; toolTips('.classtoolTips210',tt_store_content,'3579'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<strong\\>J\\<\\\/strong\\>eux \\<strong\\>O\\<\\\/strong\\>lympiques<br \/>ou<br \/>\\<strong\\>J\\<\\\/strong\\>ournal \\<strong\\>O\\<\\\/strong\\>fficiel de la R\u00e9publique Fran\u00e7aise\\<\\\/p\\>\"; toolTips('.classtoolTips213',tt_store_content,'4451'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\><span class='tooltipsall tooltip_post_id_30593 classtoolTips214'>RN<\/span> \\= Rassemble National, c'est le parti d'extr\u00eame droite de Marine Le Pen qui succ\u00e8de au FN \\= Front National fond\u00e9 par son p\u00e8re Jean Marie Le Pen\\<\\\/p\\>\"; toolTips('.classtoolTips214',tt_store_content,'30593'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<\/p>\n<p style\\='text\\-align\\: center;'\\>\\<span style\\='font\\-size\\: 14pt;'\\>\\<strong\\>C\\<\\\/strong\\>entre \\<strong\\>H\\<\\\/strong\\>ospitalier\\<\\\/span\\>\\<\\\/p\\>\"; toolTips('.classtoolTips220',tt_store_content,'18357'); <\/script><script type=\"text\/javascript\"> var tt_store_content = \"\\<p\\>D\u00e9chets radioactifs \u00e0 Haute Activit\u00e9 \\(classement <span class='tooltipsall tooltip_post_id_3612 classtoolTips79'>ANDRA<\/span>\\)\\<\\\/p\\>\"; toolTips('.classtoolTips223',tt_store_content,'19196'); <\/script><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,37,170,5,27],"tags":[],"coauthors":[4],"class_list":["post-27777","post","type-post","status-publish","format-standard","hentry","category-actu","category-actu_loc","category-rub_pol_citoyennete","category-rub_pol","category-rub","edition-edi_00095","type_art-type_art_breve","no-thumb"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9B5TM-7e1","_links":{"self":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/27777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=27777"}],"version-history":[{"count":0,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/27777\/revisions"}],"wp:attachment":[{"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=27777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=27777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=27777"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/le-clairon-nouveau.fr\/wordpress\/wp-json\/wp\/v2\/coauthors?post=27777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}